{"id":990,"date":"2015-11-24T18:39:39","date_gmt":"2015-11-24T17:39:39","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/aspettando-natale-dolce\/"},"modified":"2018-03-14T14:25:13","modified_gmt":"2018-03-14T13:25:13","slug":"aspettando-natale-dolce","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/11\/24\/aspettando-natale-dolce\/","title":{"rendered":".. Aspettando Natale&#8230; dolce"},"content":{"rendered":"<p style=\"text-align: justify;\">&#8220;<strong>Aspettando Natale<\/strong>&#8221; e&#8217; il nome che e&#8217; stato dato all&#8217;impasto dolce, fatto con Pasta Madre.<!--more--><\/p>\n<p style=\"text-align: justify;\">Per l&#8217;occasione non ho neppure contato i ProPoint WW, giusto per non farmi del male.<br \/>\n{ ne ho assaggiato solo una fettina, solo per sapere di cosa si trattava, ma ho evitato di mangiare troppo nel restante giorno! }.<\/p>\n<p style=\"text-align: justify;\">La ricetta originale l&#8217;ho trovata sul <a href=\"http:\/\/app.gruppolapastamadre.it\/#ricetta\/858\" target=\"_blank\" rel=\"noopener\">Lievitario <\/a><\/p>\n<figure id=\"attachment_9628\" aria-describedby=\"caption-attachment-9628\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9628\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161517-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161517-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161517-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161517-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161517-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161517.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-9628\" class=\"wp-caption-text\">Pandolce &#8220;Aspettando Natale&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Si tratta di un dolce tipo che potrebbe essere l&#8217;incrocio tra panettone\/pandoro.<br \/>\nNel mio caso ho inserito pinoli, uvetta, cranberry e mandorle a pezzetti.<br \/>\nL&#8217;ho cotto nella forma del Kugelhopf ma mi sono scordata di imburrarlo, cosi&#8217; ho fatto una faticaccia nell&#8217;estrarlo (rompendone anche un pezzetto).<\/p>\n<figure id=\"attachment_9629\" aria-describedby=\"caption-attachment-9629\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9629\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161504-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161504-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161504-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161504-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161504-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151109_161504.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-9629\" class=\"wp-caption-text\">Pandolce &#8220;Aspettando Natale&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Penso, pero&#8217;, che nel mio caso sia lievitato un po&#8217; troppo&#8230;<br \/>\nAd essere sincera mi ero completamente scordata di lui!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Aspettando Natale&#8221; e&#8217; il nome che e&#8217; stato dato all&#8217;impasto dolce, fatto con Pasta Madre.<\/p>\n","protected":false},"author":2,"featured_media":9628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145,22,90],"tags":[112,41],"class_list":["post-990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dolci","category-food","category-lievitati","tag-licoli","tag-natale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=990"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/990\/revisions"}],"predecessor-version":[{"id":9630,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/990\/revisions\/9630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/9628"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}