{"id":979,"date":"2015-12-07T18:39:39","date_gmt":"2015-12-07T17:39:39","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/biscotti-avvento-prima-settimana\/"},"modified":"2018-09-01T15:04:57","modified_gmt":"2018-09-01T14:04:57","slug":"1-avvento-2015","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/12\/07\/1-avvento-2015\/","title":{"rendered":"Prima settimana &#8211; Avvento  2015"},"content":{"rendered":"<p style=\"text-align: justify;\">I biscotti dell&#8217;Avvento sono una caratteristica di Patatolandia, e vengono preparati tutti insieme.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per questo motivo avevo chiesto a Oma se potevamo andare da lei a farli.<br \/>\nLei ha declinato l&#8217;invito, ma Oma &amp; Opa hanno deciso di venire loro da noi.<\/p>\n<p style=\"text-align: justify;\">Ecco quindi alcuni momenti durante la preparazione<\/p>\n<figure id=\"attachment_6194\" aria-describedby=\"caption-attachment-6194\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6194 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due-1.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due-1.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6194\" class=\"wp-caption-text\">Tobias &amp; Opa che preparano le loro forme<\/figcaption><\/figure>\n<figure id=\"attachment_6193\" aria-describedby=\"caption-attachment-6193\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6193 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tre.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tre.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tre-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tre-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6193\" class=\"wp-caption-text\">Oma &amp; Stephan che &#8216;sparano&#8217; biscotti<\/figcaption><\/figure>\n<figure id=\"attachment_6192\" aria-describedby=\"caption-attachment-6192\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6192 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/quattro.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/quattro.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/quattro-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/quattro-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6192\" class=\"wp-caption-text\">Il risultato<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il risultato<br \/>\nE voi?<br \/>\nCosa aspettate?<\/p>\n<p style=\"text-align: justify;\">Noi ne abbiamo preparato solo 2 tipi, ma solitamente la &#8216;tradizione&#8217; ne richiede molti di piu&#8217;.<br \/>\nMagari la prossima settimana si raddoppia&#8230;<\/p>\n<figure id=\"attachment_6191\" aria-describedby=\"caption-attachment-6191\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6191 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/cinque.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/cinque.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/cinque-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/cinque-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6191\" class=\"wp-caption-text\">Alcune decorazioni sono state fatte da me<\/figcaption><\/figure>\n<figure id=\"attachment_6190\" aria-describedby=\"caption-attachment-6190\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6190 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sei.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sei.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sei-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sei-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6190\" class=\"wp-caption-text\">Ancora caldi.. ma buoni!<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Considerate, comunque, che la cucina (e non solo) risultera&#8217; in uno stato pietoso!<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I biscotti dell&#8217;Avvento sono una caratteristica di Patatolandia, e vengono preparati tutti insieme.<\/p>\n","protected":false},"author":2,"featured_media":6195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[99],"class_list":["post-979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-avvento"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=979"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/979\/revisions"}],"predecessor-version":[{"id":6197,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/979\/revisions\/6197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6195"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}