{"id":972,"date":"2015-12-18T18:39:39","date_gmt":"2015-12-18T17:39:39","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/risotto-allarancia\/"},"modified":"2018-03-02T17:04:42","modified_gmt":"2018-03-02T16:04:42","slug":"risotto-allarancia","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/12\/18\/risotto-allarancia\/","title":{"rendered":"Risotto all&#8217;arancia"},"content":{"rendered":"<p style=\"text-align: justify;\">Proprio non ce la faccio piu&#8217; di\u00c2\u00a0 mangiare le stesse cose.<!--more--><br \/>\nSenza avere la facolta&#8217; di cambiare un pochino, esplorare nuovi gusti.<br \/>\nNon che sia una cuoca provetta, ma almeno fare dei tentativi.<\/p>\n<p style=\"text-align: justify;\">E cosi&#8217; e&#8217; successo.<br \/>\nNel numero di dicembre di &#8216;Cucina di Stagione&#8217; ho trovato un risottino all&#8217;arancia.<\/p>\n<p style=\"text-align: justify;\">Veramente semplice, cosi&#8217; da ripeterlo a casa.<\/p>\n<figure id=\"attachment_7793\" aria-describedby=\"caption-attachment-7793\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7793\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_121012.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_121012.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_121012-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_121012-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_121012-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_121012-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7793\" class=\"wp-caption-text\">Risotto all&#8217;arancia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Questo e&#8217; il risultato da me ottenuto (devo ancora capire come si pulisce lo spiccio d&#8217;arancia al vivo!!):<\/p>\n<figure id=\"attachment_7792\" aria-describedby=\"caption-attachment-7792\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7792\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_124441.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_124441.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_124441-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_124441-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_124441-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151205_124441-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7792\" class=\"wp-caption-text\">Risotto all&#8217;arancia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Risotto all&#8217;arancia<\/strong><\/p>\n<p style=\"text-align: justify;\">Questa la ricettina, per pesi e misure ho fatto ad occhio<\/p>\n<p style=\"text-align: justify;\">Per il risotto, tritate la cipolla.<br \/>\nScaldate il burro in una padella ampia e soffriggetevi la cipolla.<br \/>\nUnite il riso e tostatelo finch\u00c3\u00a9 diventa traslucido.<br \/>\nUnite la scorza grattugiata della met\u00c3\u00a0 delle arance e mettete un\u00e2\u20ac\u2122arancia da parte.<br \/>\nSfumate il riso con la met\u00c3\u00a0 del succo di arancia.<br \/>\nFate cuocere il riso per ca. 20 minuti, mescolando di tanto in tanto e incorporando poco per volta il succo d\u00e2\u20ac\u2122arancia rimasto e il brodo.<br \/>\nPelate al vivo l\u00e2\u20ac\u2122arancia messa da parte. Liberate gli spicchi dalle pellicine.<br \/>\nRegolate il risotto di sale e pepe.<br \/>\nMantecatelo con il formaggio fresco e affinatelo con gli spicchi d\u00e2\u20ac\u2122arancia.<\/p>\n<p style=\"text-align: justify;\">Niente male.<br \/>\nVedremo se tra una decina di anni potro&#8217; fare nuovi esperimenti<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proprio non ce la faccio piu&#8217; di\u00c2\u00a0 mangiare le stesse cose.<\/p>\n","protected":false},"author":2,"featured_media":7792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,67],"tags":[107],"class_list":["post-972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-riso_risotti","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=972"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/972\/revisions"}],"predecessor-version":[{"id":7794,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/972\/revisions\/7794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7792"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}