{"id":951,"date":"2015-12-20T18:39:37","date_gmt":"2015-12-20T17:39:37","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/albero-di-natale-2015\/"},"modified":"2018-11-06T20:16:19","modified_gmt":"2018-11-06T19:16:19","slug":"albero-di-natale-2015","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/12\/20\/albero-di-natale-2015\/","title":{"rendered":"Albero di Natale &#8211; 2015"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;abitudine a decorare l&#8217;albero di Natale al ponte dell&#8217;Immacolata e&#8217; sempre piu&#8217; forte, soprattutto quando lo si va (o lo si deve??) ad acquistare alla quasi-vigilia natalizia.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Per Pino (cosi&#8217; lo abbiamo chiamato) e&#8217; stata quasi una fortuna essere adottato dalla nostra famiglia, anche se per poche settimane.<\/p>\n<figure id=\"attachment_13399\" aria-describedby=\"caption-attachment-13399\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13399 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151224_150316.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151224_150316.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151224_150316-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20151224_150316-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-13399\" class=\"wp-caption-text\">Pino appena arrivato a casa nostra<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Per Stephan sembra che sia un affare di stato.<\/p>\n<p>Si va in questi ampi spazi dove gli alberi sono in bella mostra, e si sceglie il proprio a seconda della tipologia di albero, della dimensione, del portamento, della presenza (o meno) di rami importanti, della punta piu&#8217; o meno alta.<br \/>\nInsomma, per pigliare un albero ci si impiega delle ore.<\/p>\n<figure id=\"attachment_13390\" aria-describedby=\"caption-attachment-13390\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13390 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0047.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0047.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0047-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0047-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-13390\" class=\"wp-caption-text\">Il luoco<\/figcaption><\/figure>\n<figure id=\"attachment_13391\" aria-describedby=\"caption-attachment-13391\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13391 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0050.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0050.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0050-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0050-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-13391\" class=\"wp-caption-text\">La selezione<\/figcaption><\/figure>\n<figure id=\"attachment_13392\" aria-describedby=\"caption-attachment-13392\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13392 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0051.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0051.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0051-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0051-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-13392\" class=\"wp-caption-text\">La sistemazione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ora non capisco bene se Stephan decida di andare ad acquistarlo all&#8217;ultimo momento per diversi fattori, ma soprattutto perche&#8217; la scelta e&#8217; stata notevolemente ridimensionata, la stragrande maggioranza di alberi sono stati venduti e quindi lo si seleziona tra i rimanenti.<\/p>\n<p style=\"text-align: justify;\">Quest&#8217;anno, poi, ci siamo battuti per averne uno &#8220;piccolo&#8221;.<br \/>\nA cosa serve averne di maestosi, con punte che toccano il soffitto quando anche piccolino fa la sua sporca figura?<\/p>\n<figure id=\"attachment_13393\" aria-describedby=\"caption-attachment-13393\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13393 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0058.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0058.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0058-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0058-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-13393\" class=\"wp-caption-text\">Il puntale<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Poi, Pino, si e&#8217; anche comportato benissimo.<br \/>\nNonostante sia stato dismesso alla Befana, non ha perso neppure una grossa quantita di pelo, pardon, di aghi.<\/p>\n<p style=\"text-align: justify;\">Ora una parte di lui e&#8217; ancora con noi.<br \/>\nStephan ha provveduto a tagliuzzarlo e coprire la sua edera con i rami avvolgenti, per tenere al caldo la pianta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-13397\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0076.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0076.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0076-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0076-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;abitudine a decorare l&#8217;albero di Natale al ponte dell&#8217;Immacolata e&#8217; sempre piu&#8217; forte, soprattutto quando lo si va (o lo si deve??) ad acquistare alla quasi-vigilia natalizia.<\/p>\n","protected":false},"author":2,"featured_media":13390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[154,41],"class_list":["post-951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-giardino","tag-natale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=951"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/951\/revisions"}],"predecessor-version":[{"id":13400,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/951\/revisions\/13400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13390"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}