{"id":904,"date":"2016-03-15T18:39:36","date_gmt":"2016-03-15T17:39:36","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/erding-erdino\/"},"modified":"2026-05-13T19:04:50","modified_gmt":"2026-05-13T17:04:50","slug":"erding-erdino","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/03\/15\/erding-erdino\/","title":{"rendered":"Erding &#8211; Erdino"},"content":{"rendered":"<p style=\"text-align: justify;\">Per festeggiare il compleanno dei cugini acquisiti, siamo stati invitati alla festa di compleanno che si e&#8217; tenuta ad Eding, esattamente da &#8221; <strong>Erdino<\/strong>&#8220;.<!--more--><\/p>\n<p style=\"text-align: justify;\">Si tratta di uno spazio coperto, utilizzato come &#8220;campo giochi&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il soffitto non e&#8217; esattamente alto, quindi alcuni giochi (come il vulcano o lo scivolo) sono molto penalizzati ma, anche qui, si possono ritrovare gli stessi giochi di <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/11\/06\/jux-tollerei-parsdorf\/\" target=\"_blank\" rel=\"noopener\">Jux<\/a>.<\/p>\n<p style=\"text-align: justify;\">Il &#8220;settore&#8221; per festeggiare &#8211; quindi con tavoli e panche &#8211; mi e&#8217; sembrato un po&#8217; piu&#8217; grosso rispetto a Parsdorf, sebbene tutto l&#8217;insieme sia piu&#8217; spartano come al solito, senza pretese ed alla portata di tutti.<\/p>\n<figure id=\"attachment_10162\" aria-describedby=\"caption-attachment-10162\" style=\"width: 256px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10162\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/erd.jpg\" alt=\"\" width=\"256\" height=\"192\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/erd.jpg 256w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/erd-150x113.jpg 150w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><figcaption id=\"caption-attachment-10162\" class=\"wp-caption-text\">Erding &#8211; Erdino<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Una grossa vetrata (con tende per evitare le assolate giornate estive) fa filtrare la luce dal soffitto, proprio quasi al centro dello spiazzo, sopra l&#8217;area contenuta e recitanta per i piu&#8217; piccoli<\/p>\n<p style=\"text-align: justify;\">L&#8217;unico lato negativo, a mio avviso, e&#8217; il pavimento.<br \/>\nSi tratta di una gettata di cemento sulla terra cosi&#8217; che e&#8217; di un gelo glaciale (e non si possono tenere le scarpe!)&#8230; proprio mi domando come abbiano resistito i ragazzini.<\/p>\n<p>Personalmente sono stata solo pochi minuti senza scarpe, giusto il tempo di accompagnare Tobias all&#8217;interno, di salutare e di scappare, che mi sono ritrovata ghiacciata per tutte le restanti ore!<\/p>\n<p style=\"text-align: justify;\">L&#8217;importante, pero&#8217;, e&#8217; che si siano divertiti (non tanto mio figlio, non conoscendo nessuno e.. non parlando spagnolo!).<\/p>\n<p><a href=\"http:\/\/www.erdino.de\/\" target=\"_blank\" rel=\"noopener\"><strong>Erdino GmbH\u00c2\u00a0<\/strong><\/a><br \/>\nRennweg 57<br \/>\n85435 Erding<br \/>\nTel.: +49 (8122) 180 89 79<br \/>\ninfo@erdino.de<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per festeggiare il compleanno dei cugini acquisiti, siamo stati invitati alla festa di compleanno che si e&#8217; tenuta ad Eding, esattamente da &#8221; Erdino&#8220;.<\/p>\n","protected":false},"author":2,"featured_media":10162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162,110],"tags":[26],"class_list":["post-904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dintorni","category-monaco","tag-da_fare"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=904"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/904\/revisions"}],"predecessor-version":[{"id":51971,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/904\/revisions\/51971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10162"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}