{"id":880,"date":"2016-04-16T18:39:35","date_gmt":"2016-04-16T17:39:35","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/fiocco-nero-per-lecuador\/"},"modified":"2018-03-04T16:04:45","modified_gmt":"2018-03-04T15:04:45","slug":"fiocco-nero-per-lecuador","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/04\/16\/fiocco-nero-per-lecuador\/","title":{"rendered":"Fiocco nero per l&#8217;Ecuador"},"content":{"rendered":"<p style=\"text-align: justify;\">Nonostante l&#8217;Ecuador sia solamente una piccola Nazione, e&#8217; considerato il piu&#8217; grande paese in relazione alle sue specie botaniche di orchidee.<!--more--><\/p>\n<p style=\"text-align: justify;\">Quindi, un piccolo fiore per ricordare tutte le persone coinvolte nel tragico terremoto di qualche giorno fa (al momento sono 440 i deceduti)<\/p>\n<figure id=\"attachment_8027\" aria-describedby=\"caption-attachment-8027\" style=\"width: 259px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8027\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/orch.jpg\" alt=\"\" width=\"259\" height=\"194\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/orch.jpg 259w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/orch-150x112.jpg 150w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><figcaption id=\"caption-attachment-8027\" class=\"wp-caption-text\">Orchidea<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Perche&#8217; ho deciso per l&#8217;Ecuador e non il Giappone, penserete voi?<\/p>\n<p style=\"text-align: justify;\">Considerando che Carmen e&#8217; ecuadoregna, il problema e&#8217; un po&#8217; piu&#8217; vicino alla sottoscritta.<br \/>\nInoltre la zona colpita e&#8217; veramente molto povera.<\/p>\n<figure id=\"attachment_8026\" aria-describedby=\"caption-attachment-8026\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8026\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0418-for-ECUDORmap-600.png\" alt=\"\" width=\"1200\" height=\"1022\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0418-for-ECUDORmap-600.png 1200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0418-for-ECUDORmap-600-150x128.png 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0418-for-ECUDORmap-600-300x256.png 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0418-for-ECUDORmap-600-768x654.png 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/0418-for-ECUDORmap-600-1024x872.png 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-8026\" class=\"wp-caption-text\">Mappa del sisma che ha colpito l&#8217;Ecuador<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Se leggete gli articoli dei giornali (come ho fatto io con il Financial Time, di ritorno da Roma) scoprirete che tutti gli obiettivi sono puntati sul paese del Sol Levante, solamente per le sue citta&#8217; altamente industrializzate (produzione di Toyota e componentistiche per Apple).<\/p>\n<p>E pochissimi riferimenti all&#8217;Ecuador.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante l&#8217;Ecuador sia solamente una piccola Nazione, e&#8217; considerato il piu&#8217; grande paese in relazione alle sue specie botaniche di orchidee.<\/p>\n","protected":false},"author":2,"featured_media":8027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=880"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/880\/revisions"}],"predecessor-version":[{"id":8028,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/880\/revisions\/8028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8027"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}