{"id":868,"date":"2016-04-30T18:39:35","date_gmt":"2016-04-30T17:39:35","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/lego-education\/"},"modified":"2018-03-13T10:36:51","modified_gmt":"2018-03-13T09:36:51","slug":"lego-education","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/04\/30\/lego-education\/","title":{"rendered":"Lego Education"},"content":{"rendered":"<p style=\"text-align: justify;\">Questo e&#8217; l&#8217;ultimo acquisto che si e&#8217; fatto il mio ragazzo:<!--more--><\/p>\n<p style=\"text-align: justify;\">un pezzo &#8220;idraulico&#8221; di <strong>Lego Educational.<\/strong><\/p>\n<p style=\"text-align: justify;\">Onestamente non sapevo neppure dell&#8217;esistenza di questo genere di lego, ma lui l&#8217;ha scoperta navigando in Internet.<\/p>\n<figure id=\"attachment_7424\" aria-describedby=\"caption-attachment-7424\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7424\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mancia.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mancia.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mancia-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mancia-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mancia-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mancia-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7424\" class=\"wp-caption-text\">Lego Educational<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ebbene si, se i suoi amici vengono solo per giocare a Candy Crash o applicazioni simili, lui utilizza Internet come\u00c2\u00a0 mezzo per la sua navigazione\/ricerca e la visione di filmati su youtube (come costruzioni varie di lego Technical, modelli o simili).<\/p>\n<p style=\"text-align: justify;\">Logicamente la connessione non e&#8217; sprovvista di firewall!<\/p>\n<p style=\"text-align: justify;\">Ma cosa si puo&#8217; pretendere?<br \/>\nDovrei forse togliergli la connessione?<\/p>\n<p style=\"text-align: justify;\">Presto magari inseriro&#8217; alcune sue nuove costruzioni.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo e&#8217; l&#8217;ultimo acquisto che si e&#8217; fatto il mio ragazzo:<\/p>\n","protected":false},"author":2,"featured_media":7424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[115],"class_list":["post-868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-passatempo","tag-lego"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=868"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/868\/revisions"}],"predecessor-version":[{"id":7425,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/868\/revisions\/7425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7424"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}