{"id":837,"date":"2016-06-09T18:39:34","date_gmt":"2016-06-09T17:39:34","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/maccheroncini-handmade\/"},"modified":"2019-04-25T18:56:26","modified_gmt":"2019-04-25T17:56:26","slug":"maccheroncini-handmade","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/06\/09\/maccheroncini-handmade\/","title":{"rendered":"Maccheroncini HandMade"},"content":{"rendered":"<p style=\"text-align: justify;\">A Natale Babbo Geppetto mi ha regalato l&#8217;attrezzo ulteriore per fare la pasta in casa con il Kenwood e diverse trafile in bronzo (tagliabiscotti compreso)<!--more--><\/p>\n<p>Fino ad ora non le avevo mai provate, ma eccoci tutti in cucina, ognuno con il suo compito assegnato da eseguire:<\/p>\n<p>&#8211; chi alla lettura delle istruzioni<br \/>\n&#8211; chi ad inserire l&#8217;impasto ed azionare il motore<br \/>\n&#8211; chi a tagliare<br \/>\n&#8211; chi a fare foto e ad arrabbiarsi un poco<br \/>\n&#8211; chi a stendere la pasta appiccicaticcia su un canovaccio infarinato<br \/>\n(da considerare che eravamo solo in 3!).<\/p>\n<figure id=\"attachment_8310\" aria-describedby=\"caption-attachment-8310\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8310\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111239-1024x575.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111239-1024x575.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111239-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111239-300x168.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111239-768x431.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111239.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8310\" class=\"wp-caption-text\">Attrezzi da attaccare al Kenwood per la Pasta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La farina usata e&#8217; stata quella per &#8220;pasta&#8221; del <a href=\"http:\/\/www.hb-kunstmuehle.de\/\" target=\"_blank\" rel=\"noopener\">Mulino di Monaco<\/a>, e la ricetta seguita alla lettera (e, soprattutto al grammo!) quella allegata alla confezione stessa del tool (Stephan era alla direzione dei lavori, con la lettura delle istruzioni per &#8220;pasta fatta in casa senza uova&#8221;, quindi non ci si poteva sbagliare).<\/p>\n<figure id=\"attachment_8309\" aria-describedby=\"caption-attachment-8309\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8309\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111235-1024x575.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111235-1024x575.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111235-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111235-300x168.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111235-768x431.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_111235.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8309\" class=\"wp-caption-text\">Il mio impasto con le istruzioni fornite da Kenwood<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ebbene, la massa e&#8217; venuta troppo molle (almeno per i miei gusti), e&#8217; stato inserito dell&#8217;olio &#8211; e non ho ancora capito a cosa possa servire &#8211; cosi&#8217; abbiamo aggiunto ulteriore farina (semola avanzata dagli acquisti fatti in Francia) ad occhio, e vai di reimpasto manuale.<\/p>\n<p style=\"text-align: justify;\">In pratica.. &#8216;na ciofeca\u00c2\u00a0 \ud83d\ude41<\/p>\n<figure id=\"attachment_8308\" aria-describedby=\"caption-attachment-8308\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8308\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131515-1024x575.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131515-1024x575.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131515-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131515-300x168.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131515-768x431.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131515.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8308\" class=\"wp-caption-text\">I nostri pseudo-maccheroncini<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In qualche modo siamo riusciti a far risultare qualche forma, come potete veder e dalle immagini &#8230; dovrebbero essere dei maccheroncini rigati.<\/p>\n<figure id=\"attachment_8307\" aria-describedby=\"caption-attachment-8307\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8307\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131531-1024x575.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131531-1024x575.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131531-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131531-300x168.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131531-768x431.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160525_131531.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8307\" class=\"wp-caption-text\">I nostri pseudo-maccheroncini<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Li abbiamo lasciati volutamente piu&#8217; lunghi, con la speranza di non che non si appiccihino immediatamente tra di loro nello spostamento dall&#8217;uscita della macchina al piano di lavoro.<\/p>\n<p style=\"text-align: justify;\">Il gusto?<br \/>\nPersonalmente non mi ha soddisfatto per niente, ma mica potevo dirlo apertamente, no?<\/p>\n<figure id=\"attachment_8306\" aria-describedby=\"caption-attachment-8306\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8306\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160526_131048-1024x575.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160526_131048-1024x575.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160526_131048-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160526_131048-300x168.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160526_131048-768x431.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160526_131048.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8306\" class=\"wp-caption-text\">I nostri pseudo-maccheroncini<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cosi&#8217; mi sono messa a cercare in Internet ed ho trovato il blog di<a href=\"http:\/\/meleemore.blogspot.de\/2013\/05\/impasto-per-pasta-trafilata-al-torchio.html\" target=\"_blank\" rel=\"noopener\"> Mele&amp;More<\/a> che, dopo avermi rincuorato, ha\/hanno fornito brillanti idee a consigli su come fare.<\/p>\n<p style=\"text-align: justify;\">La prossima volta li seguiro&#8217;, sperando in un risultato diverso, magari migliore di questo.<\/p>\n<p style=\"text-align: justify;\"><strong>In definitiva&#8230; e&#8217; sconsigliato seguire la ricetta indicata nel ricettario Kenwood per fare la pasta.!!<\/strong><\/p>\n<p style=\"text-align: justify;\">Stay tuned!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Natale Babbo Geppetto mi ha regalato l&#8217;attrezzo ulteriore per fare la pasta in casa con il Kenwood e diverse trafile in bronzo (tagliabiscotti compreso)<\/p>\n","protected":false},"author":2,"featured_media":8309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[153],"class_list":["post-837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti","tag-homemade"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=837"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/837\/revisions"}],"predecessor-version":[{"id":16646,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/837\/revisions\/16646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8309"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}