{"id":835,"date":"2016-06-11T18:39:34","date_gmt":"2016-06-11T17:39:34","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/panca\/"},"modified":"2018-09-02T17:11:16","modified_gmt":"2018-09-02T16:11:16","slug":"panca","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/06\/11\/panca\/","title":{"rendered":"Panca"},"content":{"rendered":"<p style=\"text-align: justify;\">Sopra la panca la capra canta.<\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_12685\" aria-describedby=\"caption-attachment-12685\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12685 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150351-1.jpg\" alt=\"\" width=\"320\" height=\"180\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150351-1.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150351-1-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150351-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-12685\" class=\"wp-caption-text\">sopra la panca<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Sotto la panca .. le lumache crepano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12684\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150508.jpg\" alt=\"\" width=\"180\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150508.jpg 180w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150508-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150508-169x300.jpg 169w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/p>\n<p style=\"text-align: justify;\">Ultimo acquisto fatto, gia&#8217; pitturata di olio e pronta per il suo utilizzo.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12683\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150611-1.jpg\" alt=\"\" width=\"180\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150611-1.jpg 180w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150611-1-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20160606_150611-1-169x300.jpg 169w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/p>\n<p style=\"text-align: justify;\">Peccato il tempo non ci permetta di stare all&#8217;aperto, seduti comodamente all&#8217;ombra, sorseggiando un cocktail (ops.. un bicchiere d&#8217;acqua&#8230; punti limitati per me :)\u00c2\u00a0 )<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sopra la panca la capra canta.<\/p>\n","protected":false},"author":2,"featured_media":12682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[157,154],"class_list":["post-835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-acquisto","tag-giardino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=835"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/835\/revisions"}],"predecessor-version":[{"id":12686,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/835\/revisions\/12686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12682"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}