{"id":808,"date":"2012-07-07T18:39:33","date_gmt":"2012-07-07T17:39:33","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/torta-di-compleanno-luglio-2012\/"},"modified":"2018-09-01T13:03:29","modified_gmt":"2018-09-01T12:03:29","slug":"compleanno-s-2012","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/07\/07\/compleanno-s-2012\/","title":{"rendered":"Torta di compleanno !"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco la torta di compleanno che ho fatto per Stephan!<!--more--><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10714\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5130-1.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5130-1.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5130-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5130-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Si, lo vedo anche io che i savoiardi intorno non hanno tutti la stessa misura..<br \/>\nE non ricordo neppure quale ricetta ho usato per raggiungere questo obiettivo<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo, a giorni, dovrei replicare con qualche cosa d&#8217;altro.<br \/>\nNon ho idee.<br \/>\nSicuramente qualche cosa mi verra&#8217; pure in mente!<\/p>\n<figure id=\"attachment_10715\" aria-describedby=\"caption-attachment-10715\" style=\"width: 480px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10715\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5120.jpg\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5120.jpg 480w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5120-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5120-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><figcaption id=\"caption-attachment-10715\" class=\"wp-caption-text\">Il festeggiato. Ai tempi aveva meno pancia<\/figcaption><\/figure>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco la torta di compleanno che ho fatto per Stephan!<\/p>\n","protected":false},"author":2,"featured_media":10714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[36],"class_list":["post-808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-compleanno"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=808"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/808\/revisions"}],"predecessor-version":[{"id":10717,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/808\/revisions\/10717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10714"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}