{"id":798,"date":"2016-07-15T18:39:33","date_gmt":"2016-07-15T17:39:33","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/torta-allacqua-frizzante\/"},"modified":"2020-11-21T15:10:53","modified_gmt":"2020-11-21T14:10:53","slug":"torta-allacqua-frizzante","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/07\/15\/torta-allacqua-frizzante\/","title":{"rendered":"Torta all&#8217;acqua frizzante"},"content":{"rendered":"<p style=\"text-align: justify;\">Per fare questo tipo di torta &#8220;<strong>all&#8217;acqua frizzante<\/strong>&#8221; ci sono in rete tantissime ricette.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<figure id=\"attachment_10712\" aria-describedby=\"caption-attachment-10712\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10712\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0779-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0779-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0779-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0779-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0779-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0779.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-10712\" class=\"wp-caption-text\">Torta all&#8217;acqua frizzante<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ho provato mischiando i seguenti ingredienti, con l&#8217;aggiunta di una generosa manciata di cranberry (che mi guardavano da tempo dalla dispensa&#8230;)<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<pre style=\"text-align: justify;\">100gr acqua gasata\r\n230gr farina\r\n3 uova\r\n200 zucchero\r\n200 burro\r\n200 zucchero a velo\r\nlatte q.b. per avere una consistenza non troppo solida<\/pre>\n<p style=\"text-align: justify;\">tortiera diametro 22<\/p>\n<p style=\"text-align: justify;\">Avete gia&#8217; provato a farla?<br \/>\nNiente male!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per fare questo tipo di torta &#8220;all&#8217;acqua frizzante&#8221; ci sono in rete tantissime ricette.<\/p>\n","protected":false},"author":2,"featured_media":10712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[88],"class_list":["post-798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=798"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/798\/revisions"}],"predecessor-version":[{"id":27004,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/798\/revisions\/27004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10712"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}