{"id":752,"date":"2016-10-28T18:39:31","date_gmt":"2016-10-28T17:39:31","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/vino-roma-cioccolato-e-ciliegia\/"},"modified":"2018-11-16T16:40:42","modified_gmt":"2018-11-16T15:40:42","slug":"vino-roma","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/10\/28\/vino-roma\/","title":{"rendered":"Vino &#8220;Roma&#8221; cioccolato e ciliegia"},"content":{"rendered":"<p style=\"text-align: justify;\">Stephan stava prendendo il vino, cosi&#8217; mi ha chiesto quale\u00c2\u00a0 volessi bere.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">&#8220;Al cioccolato, chiaro&#8221; ho risposto, senza pensare che nella nostra cantina esisteva una bottiglia di <strong>Vino &#8220;Roma&#8221; cioccolato e ciliegia<\/strong> acquistata tempo fa dalla sottoscritta, e mai aperta.<\/p>\n<figure id=\"attachment_14248\" aria-describedby=\"caption-attachment-14248\" style=\"width: 224px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14248\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/roma.jpg\" alt=\"\" width=\"224\" height=\"400\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/roma.jpg 224w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/roma-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/roma-168x300.jpg 168w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><figcaption id=\"caption-attachment-14248\" class=\"wp-caption-text\">Vino &#8220;Roma&#8221; cioccolato e ciliegia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Piu&#8217; che vino, direi che si tratta di un liquido molto piu&#8217; corposo, dolciastro, con un tocco di ciliegia.<br \/>\nIn pratica, per ogni sorsata, lo considererei un piccolo boero senza nocciolo \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stephan stava prendendo il vino, cosi&#8217; mi ha chiesto quale\u00c2\u00a0 volessi bere.<\/p>\n","protected":false},"author":2,"featured_media":14248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149],"tags":[],"class_list":["post-752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevande"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=752"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/752\/revisions"}],"predecessor-version":[{"id":14249,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/752\/revisions\/14249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/14248"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}