{"id":732,"date":"2016-11-29T18:39:30","date_gmt":"2016-11-29T17:39:30","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/uova-in-brick\/"},"modified":"2018-11-24T17:05:17","modified_gmt":"2018-11-24T16:05:17","slug":"uova-in-brick","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/11\/29\/uova-in-brick\/","title":{"rendered":"Uova in brick."},"content":{"rendered":"<p style=\"text-align: justify;\">Anche quest&#8217;anno voglio tentare di preparare il panettone in casa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Vista la grande quantita&#8217; di rossi d&#8217;uovo che vengono utilizzati nella preparazione (panettone, pandoro e colomba), ho deciso di acquistare\u00c2\u00a0 il brick di soli albumi tramite Amazon.<\/p>\n<p style=\"text-align: justify;\">Altrimenti proprio non riuscirei a smaltire una grossa quantita&#8217; di tuorli in una volta sola.<\/p>\n<p style=\"text-align: justify;\">Dico da &#8220;Amazon&#8221; in quanto qui, nella acculturata\/avanzata\/all&#8217;avanguardia Patatolandia, non si trova minimamente in commecio tale prodotto.<\/p>\n<p style=\"text-align: justify;\">Ho girato molte catene di supermercati diversi, di negozi alimentari, ho chiesto alle gelaterie italiane (pensando fossero forniti e usassero questi brick) , ho intavolato discorsi sulla grande utilita&#8217; di questo prodotto confezionato in\u00c2\u00a0 diversi forum tedeschi: niente.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4338 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1kg_eigelb_eng.jpg\" alt=\"\" width=\"138\" height=\"133\" \/><br \/>\nNessuno ne vuole sapere perche&#8217; il prodotto, a loro detta, non e&#8217; controllato e d e&#8217; possibile possa essere la causa di salmonella (peccato, la salmonella non si prende dall&#8217;uovo, ma dalla sporcizia del guscio&#8230;).<\/p>\n<p style=\"text-align: justify;\">Pare che loro (i Patatolesi) usino questo ingrediente solamente nella gastronomia.<br \/>\nNeppure le gelaterie lo consumano ma quelle poche che ancora ne fanno uso per alcuni gusti di gelato (in effetti non viene usato per i gusti a base di frutta), acquistano il prodotto disidratato &#8211; o cosi&#8217; mi hanno detto.<br \/>\nPeccato pero&#8217;, che se si leggono gli ingredienti dei gelati da loro venduti, molte volte troviamo la scritta &#8220;preparato con uova fresche&#8221;.<\/p>\n<p>Non credo neppure che molte altre gelaterie usino le uova provenienti direttamente dal pollaio vicino.<br \/>\nPer la preparazione dei gelati non servono gli albumi, e quindi sprecherebberomolto prodotto acquistato.<\/p>\n<p style=\"text-align: justify;\">In Italia e&#8217; piu&#8217; semplice trovare le uova in confezione brick.<br \/>\nBasta andare al supermercato (Esselunga, ad esempio) ed il gioco e&#8217; fatto!<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo ho acquistato il prodotto via Internet.<br \/>\nQuando il mio brick e&#8217; arrivato, era contenuto in una scatola di polistirolo, con tanto di borsetta di gel refrigerante (era ancora ghiacciato).<br \/>\nAlla fin fine, si e&#8217; trattato di tuorlo preparato con uova biologiche tedesche e pastorizzate.<\/p>\n<p style=\"text-align: justify;\">A breve utilizzero&#8217; il contenuto per i miei panettoni.<br \/>\nIl restante &#8220;tuorlo&#8221; verra&#8217; usato per qualche altra preparazione.<br \/>\nA ben guardare,\u00c2\u00a0 siamo vicino al periodo dell&#8217;Avvento: bisogna scaldare la casa accendendo il forno (per la cottura dei biscotti) e riempiendo la stanza di aroma di zucchero, vaniglia e cannella!<\/p>\n<p style=\"text-align: justify;\">L&#8217;unica marca da me recuperata in rete, ad un prezzo &#8220;abbordabile&#8221;\u00c2\u00a0 e&#8217; la <a href=\"http:\/\/www.eipro.de\/451\/egg_products\/egg_yolk.html\" target=\"_blank\" rel=\"noopener\">seguente<\/a> (vedi foto inserita e tratta da internet), che produce brics anche per soli tuorli, crepes, waffle, uova bollite, uova arrotolate (ne avevo scritto <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2016\/06\/22\/uovo-lungo\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a>) ed altro ancora.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno voglio tentare di preparare il panettone in casa.<\/p>\n","protected":false},"author":2,"featured_media":4338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,60,61],"tags":[],"class_list":["post-732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-secondi_piatti","category-uova-formaggio"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=732"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/732\/revisions"}],"predecessor-version":[{"id":14866,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/732\/revisions\/14866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/4338"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}