{"id":691,"date":"2017-01-07T18:39:28","date_gmt":"2017-01-07T17:39:28","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/kids-day-darc\/"},"modified":"2019-04-26T10:17:28","modified_gmt":"2019-04-26T09:17:28","slug":"kids-day-darc","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/01\/07\/kids-day-darc\/","title":{"rendered":"Kid&#8217;s day &#8211; DARC"},"content":{"rendered":"<p style=\"text-align: justify;\">Il gruppo HamRadio del mio paese, in collaborazione con il DARC\/HARAC nazionale. ha organizzato sabato\u00c2\u00a0 un pomeriggio per i bambini { <a href=\"http:\/\/www.arrl.org\/kids-day\" target=\"_blank\" rel=\"noopener\"> Kid&#8217;s day <\/a>} , per dar loro l&#8217;opportunita&#8217; di conoscere e promuovere le radio e le trasmissioni via etere.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nNell&#8217;evento organizzato si dava anche la possibilita&#8217; di poter utilizzare le radio dal vivo, chiamando e contattando persone.<\/p>\n<p style=\"text-align: justify;\">Proprio non capisco come questa occasione sia stata snobbata dall&#8217;intero paese (e dintorni) sta di fatto che noi eravamo gli UNICI partecipanti a questa giornata.<\/p>\n<figure id=\"attachment_9416\" aria-describedby=\"caption-attachment-9416\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9416\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/01\/PhotoGrid_1483817099191.png\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/01\/PhotoGrid_1483817099191.png 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/01\/PhotoGrid_1483817099191-150x150.png 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/01\/PhotoGrid_1483817099191-300x300.png 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/01\/PhotoGrid_1483817099191-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-9416\" class=\"wp-caption-text\">Diploma di Radiooperatore &#8211; Kid&#8217;s Day 2017<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Essendo un evento bi-annuale, al momento non so se verra&#8217; replicata in seguito e se parteciperanno piu&#8217; ragazzini.<br \/>\nCerto che e&#8217; triste organizzare qualche cosa e non vedere adesioni del pubblico&#8230;<\/p>\n<p style=\"text-align: justify;\">Beh, almeno noi c&#8217;eravamo.<br \/>\nChe dire&#8230; tale madre tale figlio!<\/p>\n<p style=\"text-align: justify;\">73,<\/p>\n<p style=\"text-align: justify;\">de DB2rxw<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il gruppo HamRadio del mio paese, in collaborazione con il DARC\/HARAC nazionale. ha organizzato sabato\u00c2\u00a0 un pomeriggio per i bambini { Kid&#8217;s day } , per dar loro l&#8217;opportunita&#8217; di conoscere e promuovere le radio e le trasmissioni via etere.<\/p>\n","protected":false},"author":2,"featured_media":9416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[141,102],"class_list":["post-691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-passatempo","tag-darc","tag-hobby"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=691"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/691\/revisions"}],"predecessor-version":[{"id":9690,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/691\/revisions\/9690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/9416"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}