{"id":6898,"date":"2018-03-07T12:07:32","date_gmt":"2018-03-07T11:07:32","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=6898"},"modified":"2020-11-08T12:18:01","modified_gmt":"2020-11-08T11:18:01","slug":"caronno-p-donnangelin","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/03\/07\/caronno-p-donnangelin\/","title":{"rendered":"Caronno Pertusella &#8211; Donn&#8217;Angelin"},"content":{"rendered":"<p style=\"text-align: justify;\">Ancora in vacanza dal Nonno,<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">siamo usciti a cena con Mara e rispettive famiglie.<\/p>\n<p style=\"text-align: justify;\">Il suggerimento accolto e&#8217; stato di andare alla nuova pizzeria aperta in Caronno Pertusella, da <strong>Donn&#8217;Angelin,<\/strong> catena d pizzerie.<\/p>\n<p style=\"text-align: justify;\">Il locale e&#8217; molto grande e spazioso, luminoso e di sera anche un po&#8217; caotico.<br \/>\nC&#8217;e&#8217; possibilita&#8217; di parcheggio di fronte all&#8217;ingresso, ma anche usufruendo del pacheggio del negozio vicino.<\/p>\n<p style=\"text-align: justify;\">Il menu \u00c3\u00a8 scritto sulla tovaglietta di carta riciclata e consiste in qualche antipasto, un po\u00e2\u20ac\u2122 di pizze, bibite e pochi dolci.<br \/>\nLe pizze sono quelle tradizionali, poche le farcite. Non manca il calzone e la pizza fritta.<\/p>\n<p style=\"text-align: justify;\">Come potete vedere dalla foto allegata del menu&#8217;, i prezzi sono piu&#8217; che ragionevoli.<\/p>\n<figure id=\"attachment_6899\" aria-describedby=\"caption-attachment-6899\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6899 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/menu-768x507.jpg\" alt=\"\" width=\"768\" height=\"507\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/menu-768x507.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/menu-768x507-150x99.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/menu-768x507-300x198.jpg 300w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6899\" class=\"wp-caption-text\">Caronno Pertusella &#8211; Donn&#8217;Angelin<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Noi ci siamo trovati molto bene.<br \/>\nAbbiamo &#8220;testato&#8221;\u00c2\u00a0 Misto Angela (con pizzette fritte ed assaggi vari), pizze varie, torta caprese e pastiera.<\/p>\n<p style=\"text-align: justify;\">Preparano anche portate per pranzo &#8211; nelle giornate lavorative &#8211; a prezzi sicuramente interessanti.<\/p>\n<p style=\"text-align: justify;\">Vale la pena di provare e, mi raccomando, prenotate prima!<\/p>\n<p style=\"text-align: justify;\">Queste successive foto sono state scattate il 17 giugno 2019, giornata in cui siamo ritornati con il Nonno.<br \/>\nEd ancora una volta, nonostante la tarda ora di pranzo, ci siamo trovati veramente bene.<\/p>\n<figure id=\"attachment_17346\" aria-describedby=\"caption-attachment-17346\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17346 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_142656-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_142656-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_142656-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_142656-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_142656-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17346\" class=\"wp-caption-text\">Caronno Pertusella &#8211; Donn&#8217;Angelin<\/figcaption><\/figure>\n<figure id=\"attachment_17348\" aria-describedby=\"caption-attachment-17348\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17348 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_145219-e1560787599669-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_145219-e1560787599669-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_145219-e1560787599669-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_145219-e1560787599669-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_145219-e1560787599669-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17348\" class=\"wp-caption-text\">Caronno Pertusella &#8211; Donn&#8217;Angelin<\/figcaption><\/figure>\n<figure id=\"attachment_17349\" aria-describedby=\"caption-attachment-17349\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17349 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151446-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151446-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151446-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151446-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151446-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17349\" class=\"wp-caption-text\">Caronno Pertusella &#8211; Donn&#8217;Angelin<\/figcaption><\/figure>\n<figure id=\"attachment_17350\" aria-describedby=\"caption-attachment-17350\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17350 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151443-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151443-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151443-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151443-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/03\/IMG_20190617_151443-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17350\" class=\"wp-caption-text\">Caronno Pertusella &#8211; Donn&#8217;Angelin<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\n<span style=\"color: #ff0000;\">Aggiornamento all&#8217;8 Novembre 2020<\/span><br \/>\nPare che il 30 ottobre 2019 sia stato dichiarato il fallimento di questa attivita ed il 6 Novembre 2019 il locale e&#8217;\u00c2\u00a0 stato chiuso.<br \/>\nPeccato per i 140 lavoratori, ma anche per la qualita&#8217; del cibo e, soprattutto, del fatto che con i prezzi era veramente abbordabile a tutti.<\/p>\n<p><strong>PER INFORMAZIONI<\/strong><\/p>\n<p>Donn&#8217;Angelin<br \/>\nviale della Vittoria<br \/>\nCaronno Pertusella (VA)<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora in vacanza dal Nonno,<\/p>\n","protected":false},"author":2,"featured_media":17352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,25,21],"tags":[28,47,130],"class_list":["post-6898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-italia","category-travel","tag-dove_mangiare","tag-lombardia","tag-pizzeria"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=6898"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6898\/revisions"}],"predecessor-version":[{"id":26636,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6898\/revisions\/26636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/17352"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=6898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=6898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=6898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}