{"id":6689,"date":"2018-03-11T10:56:44","date_gmt":"2018-03-11T09:56:44","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=6689"},"modified":"2020-07-14T16:13:31","modified_gmt":"2020-07-14T15:13:31","slug":"bollate-pizzeria-pomodoro-mozzarella","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/03\/11\/bollate-pizzeria-pomodoro-mozzarella\/","title":{"rendered":"Bollate: Pizzeria Pomodoro &#038; Mozzarella"},"content":{"rendered":"<p style=\"text-align: justify;\">Immancabile &#8211; nei tempi passati &#8211; era l&#8217;appuntamento fisso del Mercoledi&#8217; in questa pizzeria.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per diversi motivi:<\/p>\n<ul style=\"text-align: justify;\">\n<li>vicinanza a casa, cosi&#8217; da fare un take-away<\/li>\n<li>ottima comparazione qualita&#8217;-prezzo<\/li>\n<li>gentilezza, competenza<\/li>\n<li>sconto al mercoledi&#8217;<\/li>\n<li>ottime materie prime ed ingredienti scelti.\n<figure id=\"attachment_6692\" aria-describedby=\"caption-attachment-6692\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6692 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7950.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7950.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7950-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7950-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7950-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7950-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6692\" class=\"wp-caption-text\">Pizza Margherita<\/figcaption><\/figure>\n<figure id=\"attachment_6691\" aria-describedby=\"caption-attachment-6691\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6691 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7948.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7948.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7948-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7948-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7948-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7948-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6691\" class=\"wp-caption-text\">Pizza Smookey<\/figcaption><\/figure>\n<p>Ed anche questa volta non mi ha delusa \ud83d\ude42<\/p>\n<p>L&#8217;ambiente e&#8217; piccolo ma accogliente.<br \/>\nC&#8217;e&#8217; un lungo tavolo contro il muro,\u00c2\u00a0 e poche sedie a disposizione, dove e&#8217; possibile cosi&#8217; mangiare &#8220;al volo&#8221; la propria pizza.<\/p>\n<p>In effetti, questa e&#8217; una pizzeria da asporto o con consegna a domicilio.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6693\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7951.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7951.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7951-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7951-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7951-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7951-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>PER INFORMAZIONE<\/strong><\/p>\n<p style=\"text-align: justify;\">Pomodoro &amp; Mozzarella<br \/>\nVia Repubblica 45<br \/>\n20021 Bollate,<br \/>\nItalia<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immancabile &#8211; nei tempi passati &#8211; era l&#8217;appuntamento fisso del Mercoledi&#8217; in questa pizzeria.<\/p>\n","protected":false},"author":2,"featured_media":6693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,25,21],"tags":[28,47,130],"class_list":["post-6689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-italia","category-travel","tag-dove_mangiare","tag-lombardia","tag-pizzeria"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=6689"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6689\/revisions"}],"predecessor-version":[{"id":24267,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6689\/revisions\/24267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6693"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=6689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=6689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=6689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}