{"id":6680,"date":"2018-03-15T10:07:49","date_gmt":"2018-03-15T09:07:49","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=6680"},"modified":"2021-03-20T17:13:51","modified_gmt":"2021-03-20T16:13:51","slug":"yoghurt-mila-gusto-castagna","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/03\/15\/yoghurt-mila-gusto-castagna\/","title":{"rendered":"Yoghurt Mila: gusto &#8220;castagna&#8221;"},"content":{"rendered":"<p>Sebbene le castagne siano frutti\u00c2\u00a0 invernali,<\/p>\n<p><!--more--><\/p>\n<p>questo yoghurt &#8220;MILA&#8221; al gusto &#8220;castagna&#8221; mi ha incuriosita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6905\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8227-1.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8227-1.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8227-1-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8227-1-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8227-1-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8227-1-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Nonostante sulla confezione ci sia scritto &#8220;novita'&#8221;, questo non toglie che il prodotto era gia&#8217; stato lanciato sul mercato anni fa, intorno al 2015.<\/p>\n<p>Si tratta di uno yoghurt INTERO al gusto di frutta, partendo comunque da un prodotto base ottima qualita&#8217;.<\/p>\n<p>Il sapore e&#8217; buono, delicato, non particolarmente intenso, con un lieve sentore di castagna (forse un po&#8217; troppo poco questo &#8220;sentore&#8221;??).<br \/>\nLa consistenza e&#8217; cremosa ma non consistente.<\/p>\n<p>Ottimo per la colazione o per uno spuntino di mezza mattina, come per il mio caso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6904\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8228.jpg\" alt=\"\" width=\"2432\" height=\"4320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8228.jpg 2432w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8228-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8228-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8228-768x1364.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_8228-576x1024.jpg 576w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Lo avete gia&#8217; trovato e provato nel banco frigo?<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sebbene le castagne siano frutti\u00c2\u00a0 invernali,<\/p>\n","protected":false},"author":2,"featured_media":6905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[107,183],"class_list":["post-6680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al_cucchiaio","category-dessert","category-food","tag-frutta","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=6680"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6680\/revisions"}],"predecessor-version":[{"id":29573,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6680\/revisions\/29573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6905"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=6680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=6680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=6680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}