{"id":652,"date":"2017-03-30T18:39:27","date_gmt":"2017-03-30T17:39:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/bentornata-primavera\/"},"modified":"2023-03-26T17:06:11","modified_gmt":"2023-03-26T15:06:11","slug":"bentornata-primavera-2017","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/03\/30\/bentornata-primavera-2017\/","title":{"rendered":"Bentornata primavera!"},"content":{"rendered":"<p style=\"text-align: justify;\">Come vi avevo mostrato qualche settimana fa, la primavera sta arrivando anche da noi.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nEd ogni giorno sempre di piu&#8217; si sente la sua presenza.<\/p>\n<p style=\"text-align: center;\"><strong>FINALMENTE!<\/strong><\/p>\n<p style=\"text-align: justify;\">Basta un attimo ed i fiori sbocciano, il vento spazza le nuvole e ci si ritrova in una giornata solare e luminosa, con un cielo azzurro meraviglioso.<\/p>\n<p style=\"text-align: justify;\">Al momento non e&#8217; ancora cosi&#8217; caldo alla mattina, ma dal primo pomeriggio il clima e&#8217; piu&#8217; mite e si sta bene gozzovigliando in giardino.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12327\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1490629626109.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1490629626109.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1490629626109-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1490629626109-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/1490629626109-100x100.jpg 100w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Oppure facendo delle passeggiate, prendendo un gelato e riscaldando le fredde e vecchie ossa al sole.<br \/>\nInutile dire che i Patatolesi mangiano gia&#8217; all&#8217;aperto&#8230; \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">L&#8217;altro giorno (<a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/03\/10\/primavera_2017\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a>) avevo mostrato alcuni fiori.<br \/>\nQuesta volta ho voluto farvi vedere il mio giardino<\/p>\n<p style=\"text-align: justify;\">Il rosmarino, la salvia e le piante di lavanda sono ancora secche.<br \/>\nNon so se hanno passato l&#8217;inverno e se si riprenderanno.. ma gli do&#8217; un po&#8217; di tempo e speranza.<\/p>\n<p style=\"text-align: justify;\">Poi si vedra&#8217; cosa fare e se sostituirle a nuove (con i soliti pensieri che non so mai quale prendere..).<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come vi avevo mostrato qualche settimana fa, la primavera sta arrivando anche da noi.<\/p>\n","protected":false},"author":2,"featured_media":12327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[154],"class_list":["post-652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-giardino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=652"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/652\/revisions"}],"predecessor-version":[{"id":41436,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/652\/revisions\/41436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12327"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}