{"id":627,"date":"2017-04-30T18:39:25","date_gmt":"2017-04-30T17:39:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/insalata-russa-light\/"},"modified":"2021-03-02T17:52:10","modified_gmt":"2021-03-02T16:52:10","slug":"insalata-russa-light","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/04\/30\/insalata-russa-light\/","title":{"rendered":"Insalata Russa light"},"content":{"rendered":"<p style=\"text-align: justify;\">Durante le feste ci si lascia<del> un po&#8217;<\/del> andare nel mangiare un po&#8217; piu&#8217; del solito.<br \/>\nPoi, come i coccodrilli, si piange e si cerca di correre al riparo.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per compensare a tutte queste lacrime, ho tentato di non caricare ulteriormente le dosi caloriche, proponendo questa &#8220;Insalata Russa versione light&#8221;.<br \/>\nLo so, poi mi sono leccata per bene il contenitore del tiramisu, fatto solo di mascarpone.. ma si tratta sempre di compensare \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Per la preparazione della verdura di base, mi affido a voi: verdure fresche lessate, verdure congelate, verdure in lattina, etc&#8230;<\/p>\n<p style=\"text-align: justify;\">Qui a Patatolandia ho trovato una preparazione simile (carote, piselli ed asparagi) surgelata, alla quale ho aggiunto solo delle patate lessate.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4626\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/04\/insalata_russa.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/04\/insalata_russa.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2017\/04\/insalata_russa-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;intenzione originale era di preparare la maionese, cosa che non ho MAI fatto.<br \/>\nPoi ci ho rinunciato, convertendomi a questa versione light.<\/p>\n<p style=\"text-align: justify;\">E&#8217; bastato prendere dello yoghurt greco, aggiungere un poco di senape (la quantita&#8217; dipende molto a seconda dei gusti personali) ed aiutare la colorazione con della curcuma in polvere.<\/p>\n<p style=\"text-align: justify;\">Facile?<\/p>\n<p style=\"text-align: justify;\">Aspetto i vostri commenti post-preparazione \ud83d\ude42<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante le feste ci si lascia un po&#8217; andare nel mangiare un po&#8217; piu&#8217; del solito. Poi, come i coccodrilli, si piange e si cerca di correre al riparo.<\/p>\n","protected":false},"author":2,"featured_media":4626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,22],"tags":[49,183],"class_list":["post-627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antipasti","category-food","tag-ww","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=627"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/627\/revisions"}],"predecessor-version":[{"id":15217,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/627\/revisions\/15217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/4626"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}