{"id":6134,"date":"2018-02-19T16:09:17","date_gmt":"2018-02-19T15:09:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=6134"},"modified":"2019-11-28T10:08:47","modified_gmt":"2019-11-28T09:08:47","slug":"risolatte-v2-0","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/02\/19\/risolatte-v2-0\/","title":{"rendered":"Risolatte &#8211; v2.0"},"content":{"rendered":"<p>Tobias va matto per il <strong>Risolatte<\/strong>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Ho quindi provato a (ri-)farlo un&#8217;altra volta (la versione 1.0 la potete trovare cliccando <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/12\/16\/risolatte\/\">QUI<\/a>) , seguendo la ricetta trovata sul sito della Migros (ex CucinaDiStagione).<\/p>\n<p style=\"text-align: justify;\">Naturalmente, prima di scegliere la ricetta del risolatte, ho fatto un po&#8217; di confronti tra tutte possibili opzioni.<br \/>\nDiciamo che tutto si &#8216;gioca&#8217; in funzione dalla quantita&#8217; di riso e di latte che vengono cotti insieme.<\/p>\n<p style=\"text-align: justify;\">Leggendo vari commenti, sembrerebbe che la consistenza finale sia decisamente liquida.<br \/>\nNel mio caso&#8230; non lo direi proprio!<\/p>\n<figure id=\"attachment_6494\" aria-describedby=\"caption-attachment-6494\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6494 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7710.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7710.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7710-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7710-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7710-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7710-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6494\" class=\"wp-caption-text\">Risolatte<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Anche il riso utilizzato per la preparazione, sembra essere importante.<br \/>\nQui a Patatolandia esiste proprio del riso impacchettato apposta per questo genere di cottura.<\/p>\n<p style=\"text-align: justify;\">Nelle foto successive ho messo a confronto i chicchi:<br \/>\nnella prima immagine potete vedere il riso &#8216;apposito&#8217; per il risolatte. I chicchi sono piu&#8217; piccoli ed arrotondati<\/p>\n<figure id=\"attachment_6493\" aria-describedby=\"caption-attachment-6493\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6493 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7709.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7709.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7709-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7709-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7709-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7709-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6493\" class=\"wp-caption-text\">Riso per risolatte<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Questa foto, invece, dimostra un riso Carnaroli: il chicco e&#8217; piu&#8217; grande ed appuntito<\/p>\n<figure id=\"attachment_6492\" aria-describedby=\"caption-attachment-6492\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6492 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7708.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7708.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7708-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7708-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7708-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7708-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6492\" class=\"wp-caption-text\">Riso Carnaroli<\/figcaption><\/figure>\n<p>Qui le 2 ciotole vicine:<\/p>\n<figure id=\"attachment_6491\" aria-describedby=\"caption-attachment-6491\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6491 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7706.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7706.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7706-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7706-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7706-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7706-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6491\" class=\"wp-caption-text\">Riso per Risolatte &#8211; Carnaroli a confronto<\/figcaption><\/figure>\n<p>E qui il risultato ottenuto<\/p>\n<figure id=\"attachment_6495\" aria-describedby=\"caption-attachment-6495\" style=\"width: 4320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6495\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7711.jpg\" alt=\"\" width=\"4320\" height=\"2432\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7711.jpg 4320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7711-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7711-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7711-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/02\/IMG_7711-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-6495\" class=\"wp-caption-text\">Risolatte<\/figcaption><\/figure>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tobias va matto per il Risolatte.<\/p>\n","protected":false},"author":2,"featured_media":6495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[],"class_list":["post-6134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al_cucchiaio","category-dessert","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=6134"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6134\/revisions"}],"predecessor-version":[{"id":19207,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/6134\/revisions\/19207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6495"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=6134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=6134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=6134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}