{"id":611,"date":"2019-01-25T10:39:25","date_gmt":"2019-01-25T09:39:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/vino-odoardi\/"},"modified":"2019-01-03T17:12:35","modified_gmt":"2019-01-03T16:12:35","slug":"vino-odoardi","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/01\/25\/vino-odoardi\/","title":{"rendered":"Vino Odoardi"},"content":{"rendered":"<p style=\"text-align: justify;\">La famiglia &#8220;<b>Odoardi<\/b>&#8221; di antica origine tedesca si stabilisce in Calabria nel 1480 nel territorio dell&#8217;attuale Nocera Terinese in provincia di Catanzaro.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">E&#8217; una famiglia di antichissima tradizione agricola, l&#8217;ultima generazione degli Odoardi &#8211; rappresentata da Gregorio Lillo Odoardi e la moglie Barbara Spalletta\u00c2\u00a0 &#8211; continua la tradizione familiare con impegno e successo ottenendo qualificati riconoscimenti e conquistando mercati di assoluto significato in Italia e all&#8217;estero.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15357\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/odoardi.jpg\" alt=\"\" width=\"523\" height=\"317\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/odoardi.jpg 523w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/odoardi-150x91.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/odoardi-300x182.jpg 300w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/p>\n<p style=\"text-align: justify;\">Domina la produzione il <strong>Terra Damia<\/strong> sia bianco che rosato, vino unico dalle piacevoli note fruttate di prugna matura, frutti di bosco e note speziate di caff\u00c3\u00a8 e vaniglia.<\/p>\n<figure id=\"attachment_15358\" aria-describedby=\"caption-attachment-15358\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15358 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20181226_131536-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20181226_131536-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20181226_131536-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20181226_131536-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-15358\" class=\"wp-caption-text\">Terra Damia &#8211; Odoardi<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La tenuta Odoardi si trova a Nocera Terinese e vanta quasi cinquanta ettari di vigneto, molti dei quali in coltivazione intensiva con diecimila ceppi ad ettaro.<br \/>\nLo spirito aziendale \u00c3\u00a8 legato alla tradizione ma con uno sguardo sempre proiettato al futuro.<\/p>\n<p style=\"text-align: justify;\">Il <strong>Savuto<\/strong> (Classico) DOC Rosso prende il nome dal fiume che costeggia i suoi vitigni.<br \/>\nIl fiume Savuto nasce nella Sila piccola, attraversa le montagne e scende attraverso la valle per sfociare nel Tirreno. Terra forte e fertile, la Valle del Savuto subisce gli influssi benefici del mare e della montagna, e i suoi vitigni rispecchiano le sue particolari condizioni climatiche miti.<\/p>\n<figure id=\"attachment_15356\" aria-describedby=\"caption-attachment-15356\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15356 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3517.jpg\" alt=\"\" width=\"300\" height=\"400\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3517.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3517-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3517-225x300.jpg 225w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-15356\" class=\"wp-caption-text\">Savuto &#8211; Odoardi<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">I vini Odoardi hanno infatti una impostazione moderna e denotano un sapiente uso del legno, spesso americano.<\/p>\n<p>Peccato, la mia scorta e&#8217; quasi agli sgoccioli&#8230;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La famiglia &#8220;Odoardi&#8221; di antica origine tedesca si stabilisce in Calabria nel 1480 nel territorio dell&#8217;attuale Nocera Terinese in provincia di Catanzaro.<\/p>\n","protected":false},"author":2,"featured_media":15357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,22],"tags":[],"class_list":["post-611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevande","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/611\/revisions"}],"predecessor-version":[{"id":15359,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/611\/revisions\/15359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/15357"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}