{"id":603,"date":"2017-05-23T18:39:25","date_gmt":"2017-05-23T17:39:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/lego-fidget-spinner\/"},"modified":"2021-07-23T12:19:12","modified_gmt":"2021-07-23T10:19:12","slug":"lego-fidget-spinner","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/05\/23\/lego-fidget-spinner\/","title":{"rendered":"Lego  fidget spinner"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco la nuova moda americana del momento che, lentamente,\u00c2\u00a0 sta invadendo anche ilvecchio continente<!--more--><\/p>\n<p style=\"text-align: center;\">\u00c2\u00a0\u00c2\u00a0\u00c2\u00a0 il\u00c2\u00a0<strong> fidget spinner.<\/strong><\/p>\n<p style=\"text-align: justify;\">Inutile dire che Tobias ha iniziato a chiederlo&#8230; indirettamente.<\/p>\n<p style=\"text-align: justify;\">Ma perche&#8217; acquistarlo quando si puo&#8217; passare un po&#8217; di tempo per auto-costruirselo?<br \/>\nNon metto in dubbio che quello acquistato avada &#8220;piu&#8217; veloce&#8221;, ma vuoi comparare uno gia&#8217; fatto con uno &#8220;fatto da te&#8221;?<\/p>\n<figure id=\"attachment_7437\" aria-describedby=\"caption-attachment-7437\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7437\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20170522_173006.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20170522_173006.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20170522_173006-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20170522_173006-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20170522_173006-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_20170522_173006-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7437\" class=\"wp-caption-text\">Parte dello scatolone &#8220;lego&#8221; &#8211; i pezzi &#8220;technic&#8221; non sono qui<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Sui internet oramai si trovano modelli self-made di tutti i tipi.<br \/>\nLogicamente abbiamo (ho) scelto quello fatto con i pezzi di lego pressocche&#8217; normali, e ravanando nello scatolone abbiamo trovato tutti i pezzi necessari.<br \/>\nSorprendente, vero?<br \/>\nAnche un sacco di omini decapitati erano nella scatola&#8230; \ud83d\ude09<\/p>\n<figure id=\"attachment_7436\" aria-describedby=\"caption-attachment-7436\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7436\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0000.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0000.jpeg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0000-150x113.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0000-300x225.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0000-768x576.jpeg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0000-1024x768.jpeg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7436\" class=\"wp-caption-text\">Fidget spinner con lego<\/figcaption><\/figure>\n<figure id=\"attachment_7435\" aria-describedby=\"caption-attachment-7435\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7435\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0002.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0002.jpeg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0002-150x113.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0002-300x225.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0002-768x576.jpeg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG-20170522-WA0002-1024x768.jpeg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7435\" class=\"wp-caption-text\">Lego fidget spinner<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Per le istruzioni abbiamo seguito il modello che si puo&#8217; trovare <em><strong><a href=\"https:\/\/frugalfun4boys.com\/build-lego-fidget-spinner\/\">qui<\/a><\/strong><\/em> , con la sola modifica di aver inserito un pezzetto in piu&#8217; sotto la struttura, cosi&#8217; da poter mantenere il pezzo sul dito.<\/p>\n<p style=\"text-align: justify;\"><b>Ma che cosa e&#8217; questo &#8220;fidget spinner&#8221;?<\/b><br \/>\nSi dice siano dei giochi antistress, che aiutano le persone con bassa concentrazione [con il Disturbo da Deficit di Attenzione\/Iperattivit\u00c3\u00a0, ADHD]\u00c2\u00a0 a focalizzare.<\/p>\n<p style=\"text-align: justify;\">O cosi&#8217; e&#8217; stata almeno l&#8217;idea originaria di Catherine Hettinger, una donna americana che li invento&#8217; nel 1993 per aiutare\u00c2\u00a0 sua figlia.<br \/>\nBrevett\u00c3\u00b2 la sua invenzione nel 1997, e prov\u00c3\u00b2 a venderla a varie aziende di giocattoli e a promuoverla alle fiere, senza successo<br \/>\nNel 2005 il brevetto scadde, non lo rinnovo&#8217; ed ora non ci sono piu&#8217; limitazioni alcune per la sua realizzazione\/vendita\/utilizzo.<\/p>\n<p style=\"text-align: justify;\">In pratica sono dei piccoli giochi di plastica, o altro materiale, con un perno che fa ruotare una struttura composta da 2 o 3 estremita&#8217; arrotondate.<br \/>\nNon si fa altro che far ruotare questa struttura.<br \/>\nTutto qui.<br \/>\nBasta fare attenzione agli occhi ed ai denti.<br \/>\nIl costo in media varia tra\u00c2\u00a0 5 ed i 15euro, a seconda del materiale, del modello, etc.<br \/>\nNon e&#8217; tanto il costo, ma un po&#8217; di iniziativa-inventiva fa bene!<\/p>\n<p style=\"text-align: justify;\">Se si cerca in Internet si trovano tanti esempi di autocostruzione, anche fatti da ragazzini dato che non &#8220;possono aspettare&#8221; 3 settimane prima di ricerverlo tramite Amazon.<br \/>\nQuello che piu&#8217; ci ha colpito e&#8217; stato il bucare un iphone 5c per inserire dei gommini a sfera e farlo ruotare.<br \/>\nDecisamente molto costoso, in quanto l&#8217;iphone non ha piu&#8217; funzionato (circa 700dollari).<\/p>\n<p style=\"text-align: justify;\">Anche in <em><strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/Fidget_spinner\" target=\"_blank\" rel=\"noopener\">Wiki<\/a><\/strong><\/em> se ne parla..<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco la nuova moda americana del momento che, lentamente,\u00c2\u00a0 sta invadendo anche ilvecchio continente<\/p>\n","protected":false},"author":2,"featured_media":7436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[115],"class_list":["post-603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-passatempo","tag-lego"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=603"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/603\/revisions"}],"predecessor-version":[{"id":32882,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/603\/revisions\/32882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7436"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}