{"id":582,"date":"2017-06-11T14:39:24","date_gmt":"2017-06-11T13:39:24","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/genova-info-generiche\/"},"modified":"2024-01-07T14:50:15","modified_gmt":"2024-01-07T13:50:15","slug":"genova-info-generiche","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/06\/11\/genova-info-generiche\/","title":{"rendered":"Genova: Alcune info"},"content":{"rendered":"<p style=\"text-align: justify;\">Dopo Milano, abbiamo continuato la nostra vacanza in direzione di Genova.<\/p>\n<p style=\"text-align: justify;\">Genova e&#8217; stata la meta per un giorno: giusto per trascorrere una notte a meta&#8217; strada tra Milano e Ventimiglia,\u00c2\u00a0 visitare velocemente la citta&#8217; e, soprattutto, per una sosta al famoso acquario.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nQui di seguito e&#8217; possibile trovare alcune informazioni\u00c2\u00a0 su dove noi abbiamo dormito, cenato e come ci siamo mossi per la visita della citta&#8217;.<br \/>\nMagari puo&#8217; essere uno spunto per altri visitatori.<\/p>\n<p style=\"text-align: justify;\">Partiamo subito con il dire che il trovare un parcheggio a Zena (come viene chiamata dai genovesi) e&#8217; veramente arduo, costosissimo ed e&#8217; impossibile (meglio.. improbabile) riuscire ad utilizzare la macchina per visitare la citta ed effettuare diversi spostamenti.<br \/>\nL&#8217;unico modo fortemente consigliato e&#8217; quello di usare i mezzi locali.<\/p>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/4.bp.blogspot.com\/-NjEd7U5XD6I\/WUpv04PUtdI\/AAAAAAAAJLo\/2HOnuPG-aw0cfSCFd07SLIXLO0xqc0D_gCLcBGAs\/s1600\/IMG_4436.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-NjEd7U5XD6I\/WUpv04PUtdI\/AAAAAAAAJLo\/2HOnuPG-aw0cfSCFd07SLIXLO0xqc0D_gCLcBGAs\/s400\/IMG_4436.JPG\" alt=\"\" width=\"400\" height=\"300\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" \/><\/a><figcaption class=\"wp-caption-text\">Genova: mappa per ipovedenti alla Stazione Brignole<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E&#8217; possibile prenotare hotel, posti letto, BB ma per la maggioranza dei casi vi daranno la possibilita&#8217; di parcheggiare direttamente sulla strada e di pagare la sosta (il costo varia a seconda delle ore in cui l&#8217;auto viene lasciata parcheggiata, o per la giornata).<\/p>\n<p style=\"text-align: justify;\">Dal canto mio ho trovato un meraviglioso B&amp;B con tanto di parcheggio coperto incluso!<br \/>\nA conti fatti non c&#8217;e&#8217; tutta questa differenza di prezzo (un posto poco costoso ma in cui devi pagare il parcheggio, ed un posto un po&#8217; piu&#8217; costoso ma dove il parcheggio e&#8217; incluso), in tutto cio&#8217; il lato positivo e&#8217; la _certezza_ di sapere che l&#8217;auto era al &#8220;sicuro&#8221;.<\/p>\n<p style=\"text-align: justify;\">Nello specifico il B&amp;B da noi selezionato si chiama &#8220;Al Centro di Genova&#8221;<\/p>\n<figure style=\"width: 225px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/4.bp.blogspot.com\/-UhX_qaY40PE\/WUpzoscTDII\/AAAAAAAAJPc\/yHr8DJo-_oM5fnLWhfO4noVRioBRRRM_ACLcBGAs\/s1600\/IMG_4627.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-UhX_qaY40PE\/WUpzoscTDII\/AAAAAAAAJPc\/yHr8DJo-_oM5fnLWhfO4noVRioBRRRM_ACLcBGAs\/s400\/IMG_4627.JPG\" alt=\"\" width=\"225\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"901\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Si tratta di un appartamento di 3 stanze al 4 piano (con ascensore e chiave).<br \/>\nIncluso nel prezzo abbiamo Wi-fi, aria condizionata nella stanza, scelta di libri a disposizione (in varie lingue), asciugamani e lenzuola.<br \/>\nLa colazione a base di focaccia genovese, brioches, panini ed altro ancora e&#8217; ottima e abbondante (grazie Alice!! ) e se non si termina quanto predisposto si puo&#8217; anche portare via, come snack durante la giornata di visita della citta&#8217;.<br \/>\nSempre presenti cordialita&#8217;, disponibilita&#8217;, gentilezza sempre presenti.<\/p>\n<p style=\"text-align: justify;\">Da &#8220;Al Centro di Genova&#8221; la <strong>stazione di Brignole<\/strong> non e&#8217; distante, ma la si raggiunge a piedi in breve tempo.<br \/>\nDa qui, poi,\u00c2\u00a0 si puo&#8217; arrivare in Genova-centro comodamente: con i mezzi o con i piedi \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">La conferma della prenotazione e&#8217; stata immediata, con una mail contente tantissime info utili anche su come muoversi e girare la citta&#8217; (giusto per entrare immediatamente nell&#8217;ottica di dove-come-cosa fare).<\/p>\n<p style=\"text-align: justify;\">Andrea (il proprietario) e&#8217; stato disponibilissimo in tutto: dal nostro arrivo (in mezzo alla strada per segnalarci dove fermarci), fino al fornirci una cartina e segnando su essa i posti meritevoli di visita (ottima la gelateria consigliata &#8220;<a>&#8220;!).<\/a><\/p>\n<p style=\"text-align: justify;\">Una libreria e&#8217; a disposizione anche per scambio di libri (italiano, inglese, tedesco e francese).<\/p>\n<p style=\"text-align: justify;\">Piccola nota per i futuri avventori di questo B&amp;B: fidatevi dei consigli ricevuti da Andrea riguarfo ai localo dove andare a mangiare.<br \/>\nIn questo caso vi conviene tentare di prenotare prima il luogo prescelto, altrimenti farete come e&#8217; successo a noi: ristorante pieno\u00c2\u00a0 \ud83d\ude41<\/p>\n<p style=\"text-align: justify;\">Cosa si puo&#8217; richiedere di piu&#8217;?<\/p>\n<figure style=\"width: 225px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/4.bp.blogspot.com\/-Q1XAAqiVHh8\/WUpzoS40TkI\/AAAAAAAAJPY\/9mv5c0yC2u8eeZ2JmGqAwVmOYRdol9yJgCLcBGAs\/s1600\/IMG_4622.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-Q1XAAqiVHh8\/WUpzoS40TkI\/AAAAAAAAJPY\/9mv5c0yC2u8eeZ2JmGqAwVmOYRdol9yJgCLcBGAs\/s400\/IMG_4622.JPG\" alt=\"\" width=\"225\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"901\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211; Ingresso stanza Lime<\/figcaption><\/figure>\n<figure style=\"width: 225px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/2.bp.blogspot.com\/--SziVdxYF-I\/WUpzoYJDDRI\/AAAAAAAAJPU\/k7Ai3DpoVdUUT8sNCvc8QgLkBL6LAXvwACLcBGAs\/s1600\/IMG_4623.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/--SziVdxYF-I\/WUpzoYJDDRI\/AAAAAAAAJPU\/k7Ai3DpoVdUUT8sNCvc8QgLkBL6LAXvwACLcBGAs\/s400\/IMG_4623.JPG\" alt=\"\" width=\"225\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"901\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211; Stanza Lime<\/figcaption><\/figure>\n<figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/2.bp.blogspot.com\/-FPMqxCxpgLs\/WUpvOh68ZOI\/AAAAAAAAJLE\/Oz8yIBNk9uEBgoCwKqg9mm6NISeOyMgHgCLcBGAs\/s1600\/IMG_4226.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-FPMqxCxpgLs\/WUpvOh68ZOI\/AAAAAAAAJLE\/Oz8yIBNk9uEBgoCwKqg9mm6NISeOyMgHgCLcBGAs\/s400\/IMG_4226.JPG\" alt=\"\" width=\"300\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"1200\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211; Servizi stanza Lime<\/figcaption><\/figure>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/1.bp.blogspot.com\/-56sFvG2KQQE\/WUpvO0aKOMI\/AAAAAAAAJLI\/pGHTl36fCsMa5IXHGlNoQIJ0Z0BHNnNJACLcBGAs\/s1600\/IMG_4228.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-56sFvG2KQQE\/WUpvO0aKOMI\/AAAAAAAAJLI\/pGHTl36fCsMa5IXHGlNoQIJ0Z0BHNnNJACLcBGAs\/s400\/IMG_4228.JPG\" alt=\"\" width=\"400\" height=\"300\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211;<\/figcaption><\/figure>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/2.bp.blogspot.com\/-01OVS-CQAPQ\/WUpvO6T1vsI\/AAAAAAAAJLM\/3sIHCvn3cPYmp82YmpZl9JH5ZkI3Q9aeQCLcBGAs\/s1600\/IMG_4229.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-01OVS-CQAPQ\/WUpvO6T1vsI\/AAAAAAAAJLM\/3sIHCvn3cPYmp82YmpZl9JH5ZkI3Q9aeQCLcBGAs\/s400\/IMG_4229.JPG\" alt=\"\" width=\"400\" height=\"300\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211;<\/figcaption><\/figure>\n<figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/4.bp.blogspot.com\/-kBg8OahwxE8\/WUpvPI0pX2I\/AAAAAAAAJLQ\/aKRE1sjUUVUX2rBwzQpG5VEPLrysfgZSACLcBGAs\/s1600\/IMG_4230.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-kBg8OahwxE8\/WUpvPI0pX2I\/AAAAAAAAJLQ\/aKRE1sjUUVUX2rBwzQpG5VEPLrysfgZSACLcBGAs\/s400\/IMG_4230.JPG\" alt=\"\" width=\"300\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"1200\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211;<\/figcaption><\/figure>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/2.bp.blogspot.com\/-lNxNZf6L1YU\/WUpvPfH-kWI\/AAAAAAAAJLU\/8mknbLeZcZk_xDPzEr9Jx5aebmifCCVcACLcBGAs\/s1600\/IMG_4434.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-lNxNZf6L1YU\/WUpvPfH-kWI\/AAAAAAAAJLU\/8mknbLeZcZk_xDPzEr9Jx5aebmifCCVcACLcBGAs\/s400\/IMG_4434.JPG\" alt=\"\" width=\"400\" height=\"300\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" \/><\/a><figcaption class=\"wp-caption-text\">Al centro di Genova &#8211; B&amp;B &#8211; La nostra colazione!<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il locale suggeritoci da\u00c2\u00a0 Andrea (gestore del B&amp;B)\u00c2\u00a0 per la cena era aperto ma non lo abbiamo potuto provare: una volta arrivati sul posto, seppure fosse ancora presto, era gia&#8217; prenotato ed abbiamo dovuto cercare altrove.<\/p>\n<p style=\"text-align: justify;\">Siamo andati in giro alla ricerca di qualche alternativa ma il dolore ai piedi per il troppo camminare si iniziava a sentire, cosi&#8217; non ci siamo allontanati troppo dal luogo del pernottamento.<\/p>\n<p style=\"text-align: justify;\">Anche se &#8220;decisamente non ligure&#8221; bensi&#8217; di specialita&#8217; napoletane, abbiamo deciso di fermarci da Toto&#8217; &amp; Peppino<\/p>\n<p style=\"text-align: justify;\">Pizza margherita ottima (per il ragazzo), impepata di cozze per me e pasta ai frutti di mare per Geppetto.<br \/>\nCome e&#8217; possibile vedere dalle foto sottostanti le porzioni sono abbondanti\u00c2\u00a0 e molto buone<br \/>\nPer dessert ho chiesto un &#8220;baba&#8221; che e&#8217; stato portato al tavolo direttamente in due porzioni, per la felicita&#8217; di Stephan (ed un po&#8217; meno mia\u00c2\u00a0 \ud83d\ude09 )<\/p>\n<p style=\"text-align: justify;\">Il locale e&#8217; un po&#8217; &#8220;rustico&#8221; ed i tavoli sono vicini tra loro, ma non da fastidio<br \/>\nServizio\u00c2\u00a0 celere.<\/p>\n<figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/3.bp.blogspot.com\/-G7WdvosX2SE\/WUpvgKkMfGI\/AAAAAAAAJLg\/ulvDz9NT-nckcNqdeVhkRP0Q73KjiDG0gCLcBGAs\/s1600\/IMG_4421.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/3.bp.blogspot.com\/-G7WdvosX2SE\/WUpvgKkMfGI\/AAAAAAAAJLg\/ulvDz9NT-nckcNqdeVhkRP0Q73KjiDG0gCLcBGAs\/s400\/IMG_4421.JPG\" alt=\"\" width=\"300\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"1200\" \/><\/a><figcaption class=\"wp-caption-text\">Genova: da Toto&#8217; &amp; Peppino<\/figcaption><\/figure>\n<figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/2.bp.blogspot.com\/-7camhIrcQR8\/WUpvf21Y1wI\/AAAAAAAAJLc\/5cb28uNGc2wcpo-gtSQwbJEXsIsDI3g7ACLcBGAs\/s1600\/IMG_4423.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-7camhIrcQR8\/WUpvf21Y1wI\/AAAAAAAAJLc\/5cb28uNGc2wcpo-gtSQwbJEXsIsDI3g7ACLcBGAs\/s400\/IMG_4423.JPG\" alt=\"\" width=\"300\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"1200\" \/><\/a><figcaption class=\"wp-caption-text\">Genova: da Toto&#8217; &amp; Peppino<\/figcaption><\/figure>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/2.bp.blogspot.com\/-dw1iu6edqkY\/WUpvfwIzu-I\/AAAAAAAAJLY\/OA1g0BnixeINCQniR5wWCm2L9trnzzG8ACLcBGAs\/s1600\/IMG_4424.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-dw1iu6edqkY\/WUpvfwIzu-I\/AAAAAAAAJLY\/OA1g0BnixeINCQniR5wWCm2L9trnzzG8ACLcBGAs\/s400\/IMG_4424.JPG\" alt=\"\" width=\"400\" height=\"300\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" \/><\/a><figcaption class=\"wp-caption-text\">Genova: da Toto&#8217; &amp; Peppino<\/figcaption><\/figure>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/1.bp.blogspot.com\/-qASaRyYGWHE\/WUpvgtoMHfI\/AAAAAAAAJLk\/tXbu06T-XbIpbptI3C2mvRZVxp1HP6JEQCLcBGAs\/s1600\/IMG_4425.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-qASaRyYGWHE\/WUpvgtoMHfI\/AAAAAAAAJLk\/tXbu06T-XbIpbptI3C2mvRZVxp1HP6JEQCLcBGAs\/s400\/IMG_4425.JPG\" alt=\"\" width=\"400\" height=\"300\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" \/><\/a><figcaption class=\"wp-caption-text\">Genova: da Toto&#8217; &amp; Peppino<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Quindi.. Come muoversi a Genova?<\/strong><\/p>\n<p>Questa e&#8217; la nota dolente.<br \/>\nE&#8217; difficile circolare per Genova in auto, praticamente impossibile trovare un parcheggio e, se cosi&#8217; fosse, si pagherebbe caro.<br \/>\nIl mio consiglio per visitare la citta&#8217; e&#8217; quello di calzare scarpe comode ed andare a piedi.<br \/>\nOppure, come ha fatto Tobias, usare un roller\u00c2\u00a0 \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Per alcune visite si puo&#8217; prendere l&#8217;ascensore (90cent il biglietto) e porta direttamente alla panoramica.<\/p>\n<figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><a style=\"margin-left: auto; margin-right: auto;\" href=\"https:\/\/3.bp.blogspot.com\/-eQv80aOn4hk\/WUpv1LUhpBI\/AAAAAAAAJLw\/je_OXz0qjFUhYf6h4G7hlaWAD5WL3PLkQCLcBGAs\/s1600\/IMG_4411.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/3.bp.blogspot.com\/-eQv80aOn4hk\/WUpv1LUhpBI\/AAAAAAAAJLw\/je_OXz0qjFUhYf6h4G7hlaWAD5WL3PLkQCLcBGAs\/s400\/IMG_4411.JPG\" alt=\"\" width=\"300\" height=\"400\" border=\"0\" data-original-height=\"1600\" data-original-width=\"1200\" \/><\/a><figcaption class=\"wp-caption-text\">Genova: porte dell&#8217;ascensore e Tobias che rimonta il roller<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Se si vuole, si puo&#8217; acquistare anche il <a href=\"https:\/\/www.visitgenoa.it\/\" target=\"_blank\" rel=\"noopener\">biglietto dei trasporti<\/a> nelle biglietterie, edicole o distributori automatici.<br \/>\nSconsiglio di acquistarlo direttamente sul mezzo, pare che il suo prezzo aumenti di almeno un euro!<\/p>\n<p style=\"text-align: justify;\">Per circolare ci sono biglietti di diverso tipo.<br \/>\nNoi abbiamo optato per il biglietto famiglia da 9euro: con questo si ha la possibilita&#8217; di circolare in 4 persone, per tutta la giornata, su tutti i mezzi.<\/p>\n<p style=\"text-align: justify;\">Da qualche anno, poi, hanno messo in funzione anche la Metropolitana.<\/p>\n<p style=\"text-align: justify;\">Fa poche fermate ma dal nostro BB arriva direttamente alla Darsena\/Acquario.<\/p>\n<p><strong><a href=\"https:\/\/www.bbalcentrodigenova.it\/\">Al <em>centro<\/em> di Genova &#8211; B&amp;B<\/a><\/strong><br \/>\nVia Canevari 56\/8 (CAP 16137) Genova<br \/>\nalcentrodigenova@gmail.com &#8211;<br \/>\n+39 393 9063367<\/p>\n<p><em><strong>Toto&#8217; &amp; Peppino<\/strong><\/em><br \/>\nVia Archimede 143r<br \/>\n16142 Genova<br \/>\nItalia<\/p>\n<p><em><strong>Stazione Genova-Brignole<\/strong><\/em><br \/>\nPiazza Giuseppe Verdi, 2<br \/>\n16121 Genova GE<br \/>\nItaly<\/p>\n<p><a href=\"https:\/\/www.visitgenoa.it\/\"><strong>Girare <em>per<\/em> Genova<\/strong><\/a><\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo Milano, abbiamo continuato la nostra vacanza in direzione di Genova. Genova e&#8217; stata la meta per un giorno: giusto per trascorrere una notte a meta&#8217; strada tra Milano e Ventimiglia,\u00c2\u00a0 visitare velocemente la citta&#8217; e, soprattutto, per una sosta al famoso acquario.<\/p>\n","protected":false},"author":2,"featured_media":3261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,25,21],"tags":[26,31,28,42],"class_list":["post-582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-italia","category-travel","tag-da_fare","tag-dove_dormire","tag-dove_mangiare","tag-liguria"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=582"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/582\/revisions"}],"predecessor-version":[{"id":43976,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/582\/revisions\/43976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/3261"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}