{"id":573,"date":"2017-07-09T18:39:24","date_gmt":"2017-07-09T17:39:24","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/fragole-a-merenda-naaa-risotto\/"},"modified":"2023-03-26T15:46:28","modified_gmt":"2023-03-26T13:46:28","slug":"fragole-risotto","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/07\/09\/fragole-risotto\/","title":{"rendered":"Fragole a merenda?  Naaa.. risotto !!"},"content":{"rendered":"<p style=\"text-align: justify;\">Quest&#8217;anno sono stata fortunata con il mio raccolto di fragole.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Questo nella foto e&#8217; il quarto raccolto ottenuto (i primi due sono stati presi da Mamma Paola, mentre\u00c2\u00a0 ero in vacanza, giusto per non lasciare le fragole in balia delle lumache).<\/p>\n<figure id=\"attachment_4491\" aria-describedby=\"caption-attachment-4491\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4491\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/raccolto_fragole.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/raccolto_fragole.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/raccolto_fragole-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-4491\" class=\"wp-caption-text\">Fragole: raccolto 2017<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ancora non capisco come sia potuto succedere riuscire ad ottenere cosi&#8217; tante fragole, ma non sto a preoccuparmi troppo.<\/p>\n<p style=\"text-align: justify;\">Anzi, le fragole sono ricche di Vitamina C e, inutile dirlo, mi piacciono enormemente.<\/p>\n<p style=\"text-align: justify;\">Forse per l&#8217;umidita&#8217;, forse per il fatto che durante la crescita delle piantine spargevo i fondi del caffe&#8217; (come consigliato da un amico brasiliano per debellare le lumache), forse perche&#8217; il terreno e&#8217; cosi&#8217; asciutto che neppure le lumache\/limacce ne sono felici e non si avvicinano neppure.<\/p>\n<p style=\"text-align: justify;\">Le fragole raccolte sono piccole,&#8230;ma sono ottime!<\/p>\n<p style=\"text-align: justify;\">Il profumo sprigionato e&#8217; inebriante ed il mio cervello ha deciso di preparare un risotto alle fragole, appunto.<\/p>\n<p style=\"text-align: justify;\">Per alcuni giorni ho spiegato a Tobias che lo avrei fatto, cosi&#8217; da prepararlo mentalmente al possibile risultato e non lasciandolo\u00c2\u00a0 impreparato.<\/p>\n<p style=\"text-align: justify;\">Detto fatto!<\/p>\n<p style=\"text-align: justify;\">Ho trovato diverse indicazioni differenti in rete, cosi&#8217; ho preferito farlo di testa mia (prendendo spunti ovunque) e con quantita&#8217; ad occhio.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Risotto alle fragole<br \/>\n<\/strong><\/p>\n<pre style=\"text-align: justify;\">scalogno\r\nburro\r\nriso\r\nbrodo vegetale\r\ngrana<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><br \/>\nPrendete uno scalogno, tagliatelo a fettine piccole e fatelo imbiondire con del burro.<\/p>\n<p style=\"text-align: justify;\">Aggiungete del riso e fatelo tostare.<br \/>\nNel mio caso ho usato del\u00c2\u00a0 il &#8220;riso Tarantola&#8221; (il riso che avevo acquistato durante il nostro giro a giugno 2017 in quel di <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/06\/vigevano\/\" target=\"_blank\" rel=\"noopener\">Vigevano<\/a>,<\/strong><\/em> e di cui scrivero&#8217; in seguito)<\/p>\n<p style=\"text-align: justify;\">Bagnatelo con del brodo caldo a seconda della richiesta del riso stesso.<\/p>\n<p style=\"text-align: justify;\">Verso la meta&#8217; cottura aggiungete le fragole (circa 200gr) lavate, asciugate (per quanto possibile) e tagliate a pezzettini, portando il riso a fine cottura.<br \/>\nSe il risotto lo richiede, aggiungete altri mestoli di brodo (uno alla volta!)<\/p>\n<p style=\"text-align: justify;\">Fate mantecare con una noce di burro, decoratelo e servitelo caldo.<\/p>\n<p style=\"text-align: justify;\">Ecco il risultato<\/p>\n<figure id=\"attachment_4489\" aria-describedby=\"caption-attachment-4489\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4489\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/risotto_alle_fragole.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/risotto_alle_fragole.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/risotto_alle_fragole-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-4489\" class=\"wp-caption-text\">Risotto alle fragole<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ero scettica se inserire il parmigiano oppure no.. alla fine l&#8217;ho fatto (dopo aver mangiato la decorazione!!) e non e&#8217; stato male.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest&#8217;anno sono stata fortunata con il mio raccolto di fragole.<\/p>\n","protected":false},"author":2,"featured_media":4489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,67],"tags":[107],"class_list":["post-573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-riso_risotti","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=573"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/573\/revisions"}],"predecessor-version":[{"id":41405,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/573\/revisions\/41405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/4489"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}