{"id":556,"date":"2017-07-26T18:39:23","date_gmt":"2017-07-26T17:39:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/tzatziki-light\/"},"modified":"2021-03-02T17:51:57","modified_gmt":"2021-03-02T16:51:57","slug":"tzatziki-light","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/07\/26\/tzatziki-light\/","title":{"rendered":"Tzatziki light"},"content":{"rendered":"<p style=\"text-align: justify;\">Stanchi della solita anonima bistecca e\/o del pesce lesso senza alcun sapore?<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nSiete stati invitati a partecipare ad un BBQ ma siete a dieta e volete limitare le calorie ingerite?<\/p>\n<p style=\"text-align: justify;\">Volete aggiungere un tocco in piu&#8217; alla vostra portata con una salsina leggera?<br \/>\nNiente di piu&#8217; facile con questa veloce ricettina&#8230;<\/p>\n<p style=\"text-align: justify;\"><strong>TZAZIKI LIGHT<\/strong><\/p>\n<figure id=\"attachment_7321\" aria-describedby=\"caption-attachment-7321\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7321\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tzatziki.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tzatziki.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tzatziki-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tzatziki-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-7321\" class=\"wp-caption-text\">Tzatziki light<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre>1 cetriolo\r\nsale, pepe\r\nyoghurt greco o yoghurt 0%\r\naglio\r\nmenta fresca\r\naneto<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Prendete il cetriolo, sbucciatelo, togliete i semini, grattugiatelo, spargetelo di sale e lasciatelo sgocciolare per 15-20 minuti circa.<\/p>\n<p style=\"text-align: justify;\">Ad uno yoghurt greco o yoghurt magro (0% di grasso), unite la polpa di mezzo spicchio d&#8217;aglio (o tutto, se preferite un gusto intenso), menta fresca ed aneto sminuzzati, sale, pepe ed il cetriolo sgocciolato.<\/p>\n<p>Mischiate bene.<br \/>\nVolendo si puo&#8217; aggiungere anche un goccio di olio.<\/p>\n<p style=\"text-align: justify;\">Totale PP punti?<br \/>\nSenza olio, e ci sta molto bene ugualmente, ben.. 0 dico 0 punti!<br \/>\nProvare per credere!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stanchi della solita anonima bistecca e\/o del pesce lesso senza alcun sapore?<\/p>\n","protected":false},"author":2,"featured_media":7321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22],"tags":[126,49,183],"class_list":["post-556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food","tag-salsa","tag-ww","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/556\/revisions"}],"predecessor-version":[{"id":29121,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/556\/revisions\/29121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7321"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}