{"id":51798,"date":"2026-04-27T15:47:08","date_gmt":"2026-04-27T13:47:08","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=51798"},"modified":"2026-04-28T11:07:27","modified_gmt":"2026-04-28T09:07:27","slug":"salsiccia-e-patate-al-forno","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2026\/04\/27\/salsiccia-e-patate-al-forno\/","title":{"rendered":"Salsiccia e patate al forno"},"content":{"rendered":"<p style=\"text-align: justify;\">Anni fa avevo gia&#8217; cucinato la salsiccia al forno, in <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/01\/09\/salsiccia-patate-zucchine_airfryer\/\">friggitrice ad aria<\/a><\/strong><\/em>.<br \/>\nOggi la ho riproposta e, dato che anche Tobias era presente al desco familiare, ho cotto tutto in forno.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Inoltre, visto che Stephan non mangia molta verdura, ho inserito delle carote (che avrebbero potuto\/dovuto) cuocere un po&#8217; di piu&#8217;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51801\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_121320-e1776952395614-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_121320-e1776952395614-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_121320-e1776952395614-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_121320-e1776952395614-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_121320-e1776952395614-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Ingredienti &#8211; Salsiccia e patate al forno<\/strong><\/p>\n<pre>400gr patate\r\n400gr salsiccia\r\nsalvia\r\nrosmarino\r\n1 spicchio aglio\r\nolio\r\nsale\r\npepe\r\ncarote (facoltativo)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preriscaldato a 200\u00c2\u00b0<\/p>\n<p style=\"text-align: justify;\">Iniziate con le patate.<br \/>\nLavatele bene, eventualmente pelatele (dipende molto dalla varieta&#8217;) e tagliatele a pezzetti di circa la stessa dimensione, per favorire una cottura uniforme.<\/p>\n<p style=\"text-align: justify;\">In una ciotola mescolate insieme l&#8217;olio, l&#8217;acqua, il trito di salvia-rosmarino, il sale ed i pepe macinato fresco.<\/p>\n<p style=\"text-align: justify;\">Versate le patate in una ciotola e mescolate bene, insaporendole, all&#8217;emulsione appena preparata<\/p>\n<p style=\"text-align: justify;\">Trasferite il tutto su una teglia rivestita con carta forno e cuocete in forno statico, preriscaldato a 200\u00c2\u00b0, per 20 minuti.<br \/>\nNel frattempo pulite le carote, tagliatele a pezzetti ed inseritele in teglia per la cottura.<\/p>\n<p style=\"text-align: justify;\">Spellate (eventualmente) le salsicce.<br \/>\nTrascorsi i 20 minuti, unite alle patate nella teglia le salsicce a pezzi.<br \/>\nProseguite la cottura per altri 20 minuti, sempre a 200\u00c2\u00b0, mescolando la preparazione.<\/p>\n<p style=\"text-align: justify;\">Sfornate e servite subito!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51800\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_125151-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_125151-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_125151-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_125151-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/04\/ok_IMG_20260414_125151-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Potete conservare in frigorifero salsiccia e patate per 1-2 giorni al massimo. Molto meglio scaldare la prepazione prima di servirla.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anni fa avevo gia&#8217; cucinato la salsiccia al forno, in friggitrice ad aria. Oggi la ho riproposta e, dato che anche Tobias era presente al desco familiare, ho cotto tutto in forno.<\/p>\n","protected":false},"author":2,"featured_media":51800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,138,60],"tags":[],"class_list":["post-51798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-piatti_unici","category-secondi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/51798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=51798"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/51798\/revisions"}],"predecessor-version":[{"id":51826,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/51798\/revisions\/51826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/51800"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=51798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=51798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=51798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}