{"id":51088,"date":"2026-03-04T12:04:55","date_gmt":"2026-03-04T11:04:55","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=51088"},"modified":"2026-02-11T15:11:40","modified_gmt":"2026-02-11T14:11:40","slug":"mini-fladenbrot_paa","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2026\/03\/04\/mini-fladenbrot_paa\/","title":{"rendered":"Mini Fladenbrot (focaccine) \u00e2\u20ac\u201c Marcel Paa"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Vera<\/strong>, oramai, e&#8217; in frigo e sta bene.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Nonostante tutto, ho ancora del timore nel preparare pani con semplicemente lei.<br \/>\nTutto cio&#8217; e&#8217; causato dal non sapermi organizzare con le tempistiche.<\/p>\n<p style=\"text-align: justify;\">Quindi&#8230; ecco un modo, semplice e buono, per utilizzarne un po&#8217;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51103\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_114708-e1770729868666-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_114708-e1770729868666-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_114708-e1770729868666-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_114708-e1770729868666-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_114708-e1770729868666-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Ingredienti &#8211; <em><a href=\"https:\/\/www.marcelpaa.com\/rezepte\/mini-fladenbrot\/\">Mini Fladenbrot (focaccine<\/a><\/em><\/strong><em>)<\/em> \u00e2\u20ac\u201c Marcel Paa &#8211; 8 pezzi<\/p>\n<pre>500 g di farina bianca (farina di grano tenero tipo 550) (*)\r\n400 g di acqua\r\n1 g di lievito di birra fresco (facoltativo)\r\n10 g di zucchero di canna grezzo\r\n40 g di lievito madre\r\n10 g di sale\r\n\r\nOlio d'oliva\r\nSemi di sesamo\r\nSemi di nigella (ossia cumino)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete la farina, il lievito, lo zucchero, il lievito madre e circa met\u00c3\u00a0 dell&#8217;acqua in una planetaria e iniziate a impastare a bassa velocit\u00c3\u00a0.<br \/>\nAggiungete quindi gradualmente il sale e l&#8217;acqua rimanente, aumentate la velocit\u00c3\u00a0 e impastate a velocit\u00c3\u00a0 media per circa 15 minuti.<\/p>\n<p style=\"text-align: justify;\">Mettete l&#8217;impasto in una ciotola unta, coprite e lasciate lievitare a temperatura ambiente per 30 minuti.<br \/>\nSuccessivamente, stendete e piegare l&#8217;impasto (S&amp;F) (*)<br \/>\n(funziona meglio se si inumidiscono le mani).<\/p>\n<p style=\"text-align: justify;\">Coprite di nuovo l&#8217;impasto e lasciatelo riposare per altre 12-16 ore a temperatura ambiente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51102\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_092237-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_092237-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_092237-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_092237-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_092237-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Trascorso il tempo di lievitazione, disponete l&#8217;impasto su un piano di lavoro infarinato e piegatelo una volta da sinistra a destra e una volta da destra a sinistra con il bordo che si sovrappone all&#8217;impasto. Questo intrappola i gas nell&#8217;impasto e lo rende pi\u00c3\u00b9 stabile.<\/p>\n<p style=\"text-align: justify;\">Quindi dividere l&#8217;impasto a met\u00c3\u00a0 nel senso della lunghezza con una spatola e dividete ciascuna met\u00c3\u00a0 in quarti.<\/p>\n<p style=\"text-align: justify;\">Stendete leggermente i pezzi di impasto nel senso della lunghezza e disponetli su un foglio di carta da forno lasciando abbastanza spazio tra i vari pezzi di impasto, per poi farli riposare brevemente.<\/p>\n<p style=\"text-align: justify;\">Coprite e lasciate riposare per 40-50 minuti a temperatura ambiente.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo, preriscaldate il forno a 250\u00c2\u00b0C (statico) con due teglie nella parte inferiore del forno.<\/p>\n<p style=\"text-align: justify;\">Dopo la lievitazione, spennellate uniformemente i pezzi di pasta con olio e premeteli nel senso della lunghezza con le dita (o con una spatola).<br \/>\nCospargete quindi i pezzi di impasto con semi di sesamo e semi di nigella.<\/p>\n<p style=\"text-align: justify;\">Posizionate l&#8217;impasto, ancora sulla carta da forno, su una teglia preriscaldata, coprire con la seconda teglia calda e posizionate nella met\u00c3\u00a0 inferiore del forno preriscaldato.<br \/>\nIn alternativa, \u00c3\u00a8 possibile cuocere le piadine su una piastra di cottura preriscaldata mentre il forno \u00c3\u00a8 in funzione.<\/p>\n<p style=\"text-align: justify;\">Dopo circa 10 minuti di cottura, rimuovete la teglia superiore (se si utilizza una vaporiera, aprire brevemente lo sportello del forno per far fuoriuscire il vapore) e proseguite la cottura per altri 10-15 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51101\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_122341-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_122341-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_122341-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_122341-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/03\/ok_IMG_20260210_122341-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Fate attenzione alla tipologia di <strong>farina<\/strong> utilizzata.<\/li>\n<li style=\"text-align: justify;\">Nel mio caso la 550 aveva veramente poche proteine (10,5%) cosi&#8217; che non si e&#8217; neppure incordata.<br \/>\nHo aggiunto (a casaccio) un po&#8217; di<strong> manitoba oro<\/strong> (14%) ed ha aiutato il tutto.<\/li>\n<li style=\"text-align: justify;\">Ho dato<strong> 2 giri<\/strong> di pieghe S&amp;F a distanza di mezz&#8217;oretta<\/li>\n<li style=\"text-align: justify;\">Lasciate al <strong>fresco<\/strong> (e non ha temperatura ambiente) per la notte&#8230; potrebbe tracimare<\/li>\n<li style=\"text-align: justify;\"><strong>A mio avviso<\/strong> e&#8217; molto meglio preparare 2 teglie da 4 pezzi cadauno. Il mio impasto e&#8217; rimasto molto idratato, cosi&#8217; da allargarsi in teglia.<\/li>\n<li>Se il lievito madre e&#8217; in forma, e&#8217; possibile omettere il lievito<\/li>\n<li>Affinch\u00c3\u00a9 le mini piadine siano soffici e croccanti, un impasto ben lievitato e un&#8217;elevata temperatura di cottura sono fondamentali. Cotte brevemente e ad alta temperatura, sviluppano una superficie croccante e rimangono morbide all&#8217;interno.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vera, oramai, e&#8217; in frigo e sta bene.<\/p>\n","protected":false},"author":2,"featured_media":51106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,22,90,91],"tags":[116,112,106],"class_list":["post-51088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-focaccia","category-food","category-lievitati","category-pane","tag-ldb","tag-licoli","tag-ricetta_perfetta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/51088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=51088"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/51088\/revisions"}],"predecessor-version":[{"id":51107,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/51088\/revisions\/51107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/51106"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=51088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=51088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=51088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}