{"id":50930,"date":"2026-02-23T20:27:06","date_gmt":"2026-02-23T19:27:06","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=50930"},"modified":"2026-02-24T09:47:52","modified_gmt":"2026-02-24T08:47:52","slug":"tortilla-pollo-avocado","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2026\/02\/23\/tortilla-pollo-avocado\/","title":{"rendered":"Tortilla \/ piadine con pollo e avocado"},"content":{"rendered":"<p style=\"text-align: justify;\">Non e&#8217; stata proprio una cena tex-mex quella che ho preparato questa sera.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Almeno e&#8217; stato un modo diverso per preparare il pollo \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50932\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_192159-e1770111324452-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_192159-e1770111324452-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_192159-e1770111324452-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_192159-e1770111324452-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_192159-e1770111324452-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Pollo e avocado<\/strong><\/p>\n<pre>2 petti di pollo\r\nolio\r\ncondimento per fajita (*)\r\nsucco di lime\r\n2 pomodori\r\ntortilla\r\nsale\r\npepe\r\n\r\n<strong>Per servire<\/strong>\r\n avocado\r\n fettine di lime\r\n rucola\r\n peperoncini jalapenos\r\n coriandolo fresco<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Scaldate 2 cucchiai di olio in una padella a fuoco moderato.<br \/>\nAggiungete il petto di pollo tagliato a dadini\/striscioline, un pizzico di sale e pepe e fate dorare.<br \/>\nAggiungete un cucchiaino di condimento per fajitas ed il succo di lime fresco.<br \/>\nContinuate a saltare il pollo altri 3-4 minuti, fino a cottura.<br \/>\nLasciare raffreddare.<\/p>\n<p style=\"text-align: justify;\">Scaldate una padella per grigliare e cuocete le tortilla, una dopo l&#8217;altra, dopo averle spruzzate con un po&#8217; d&#8217;acqua.<\/p>\n<p style=\"text-align: justify;\">Riepitele con il pollo mescolato ai pomodori sbucciati e tagliati a dadini, i jalapenos senza semi e affettati, l&#8217;avocado maturo (pulito e affettato), foglie di coriandolo fresco lavate e spezzettate.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50933\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_191348-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_191348-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_191348-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_191348-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260202_191348-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Servite le tortillas con la fajita accompagnate dalla salsa e fettine di lime<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho sostituito il condimento per fajita con salsa bbq<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non e&#8217; stata proprio una cena tex-mex quella che ho preparato questa sera.<\/p>\n","protected":false},"author":2,"featured_media":50934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[],"class_list":["post-50930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/50930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=50930"}],"version-history":[{"count":1,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/50930\/revisions"}],"predecessor-version":[{"id":50935,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/50930\/revisions\/50935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/50934"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=50930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=50930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=50930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}