{"id":50807,"date":"2026-02-20T15:07:48","date_gmt":"2026-02-20T14:07:48","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=50807"},"modified":"2026-03-18T10:38:41","modified_gmt":"2026-03-18T09:38:41","slug":"pane-lepinja-fulvio-marino","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2026\/02\/20\/pane-lepinja-fulvio-marino\/","title":{"rendered":"Pane Lepinja &#8211; Fulvio Marino &#8211; ldb &#8211; IN giornata"},"content":{"rendered":"<p style=\"text-align: justify;\">Il pane <strong>lepinja<\/strong>, chiamato anche lepinje o somun \u00c3\u00a8 il pane quotidiano dei Balcani (in particolare in Bosnia ed Erzegovina).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Questo pane, come fattore lievitante, solitamente contiene lievito ma puo&#8217; essere preparato anche con bicarbonato di sodio (o lievito in polvere) cosi&#8217; da rendere il pane molto pi\u00c3\u00b9 leggero.<\/p>\n<p style=\"text-align: justify;\">Il Lepinja e&#8217; un tipo di pane molto comune, soprattutto perche&#8217; e&#8217; conosciuto anche per essere quello che accompagna solitamente i cevapcici ( &#8220;lepinje za cevapi&#8221;).<\/p>\n<p style=\"text-align: justify;\">La ricetta seguita e&#8217; quella di Fulvio Marino, dal suo libro &#8220;<em>Tutto il mondo del pane<\/em>&#8220;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50858\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_180500-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_180500-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_180500-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_180500-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_180500-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Pane Lepinja<\/strong> &#8211; 8 panini (circa 100gr cad)<\/p>\n<pre>500gr di farina di grano tenero 00 (14% proteine)\r\n5gr di lievito di birra secco\r\n280g di acqua\r\n10gr di sale\r\nfarina per spolverare<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite in una ciotola la farina, il lievito e l&#8217;acqua.<br \/>\nIniziate a lavorare il composto, dopo 5-6 minuti unite il sale e termiante di impastare, ottenendo una massa ben liscia che farete riposare per un&#8217;oretta in una ciotola coperta con pellicola.<\/p>\n<p style=\"text-align: justify;\">Trascorso questo tempo, riprendete l&#8217;impasto e dividetelo in 8 parti uguali, ottenendo pagnottine piu&#8217; o meno del peso di 100gr.<br \/>\nDisponetele in una teglia rivestita da carta forno, appiattitele leggermente con il palmo della mano e lasciatele lievitare per 40 minuti a temperatura ambiente.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50860\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_154247-e1769539269173-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_154247-e1769539269173-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_154247-e1769539269173-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_154247-e1769539269173-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_154247-e1769539269173-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nQuindi incidete la superficie di ognuna di esser con un coltello bagnato creando una sorta di scacchiera.<\/p>\n<p style=\"text-align: justify;\">Spolveratele con un po&#8217; di farina setacciata e cuocetele in forno statico a 220gradi per 20 minuti.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La <strong>prima<\/strong> volta:<br \/>\nfarina di farro 630 (con 13%di proteine)<br \/>\nlievito di birra fresco (12gr) + 50gr esubero di licoli<br \/>\nseguito le tempistiche specificate<br \/>\ncottura come da ricetta<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50859\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_165408-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_165408-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_165408-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_165408-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/01\/ok_IMG_20260126_165408-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/li>\n<li style=\"text-align: justify;\">La <strong>seconda<\/strong> volta<br \/>\nuna farina 550<br \/>\nlievito di birra fresco (10gr)<br \/>\natteso il doppio della lievitazione<br \/>\ni tagli sono stati effettuati con la spatola<br \/>\npreriscaldato il forno a 270<br \/>\ncottura 8minuti a 250gradi, direttamente con carta forno, su teglia riscaldata e rovesciata all&#8217;interno (ripiano piu&#8217; basso)<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50913\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_152200-e1769785325850-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_152200-e1769785325850-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_152200-e1769785325850-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_152200-e1769785325850-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_152200-e1769785325850-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50911\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191934-e1769785335597-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191934-e1769785335597-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191934-e1769785335597-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191934-e1769785335597-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191934-e1769785335597-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50912\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191939-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191939-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191939-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191939-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2026\/02\/ok_IMG_20260129_191939-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/li>\n<li style=\"text-align: justify;\">A quanto pare questo pane dovrebbe avere un&#8217;<strong>alta percentuale<\/strong> di <strong>idratazione<\/strong><\/li>\n<li>i<strong> tagli<\/strong> effettuati (a scacchiera) servono per evitare che il pane gonfi, cosi&#8217; da restare basso<\/li>\n<li style=\"text-align: justify;\">Una volta cotto, dovrebbe diventare come un <strong>palloncino<\/strong>, con una tasca interna. Proprio come la pita, i due strati si separano durante la cottura e il suo centro cavo forma una tasca. Puoi aprirla da un lato e riempirla per fare un panino o tagliarla a met\u00c3\u00a0 o anche a quattro per fare panini pi\u00c3\u00b9 piccoli.<strong><br \/>\n<\/strong><\/li>\n<li style=\"text-align: justify;\">Per raggiungere tale risultato di cottura, dovrebbe essere messo in un forno molto alto, per pochi minuti<\/li>\n<li style=\"text-align: justify;\"><strong>Si consiglia,<\/strong> quando sfornato, di umidirlo leggermente e chiudere il tutto in un telo, cosi&#8217; da farlo restare umido<\/li>\n<li style=\"text-align: justify;\">La lepinja non ha un\u00e2\u20ac\u2122origine specifica, e&#8217; semplicemente &#8220;pane comune&#8221;.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il pane lepinja, chiamato anche lepinje o somun \u00c3\u00a8 il pane quotidiano dei Balcani (in particolare in Bosnia ed Erzegovina).<\/p>\n","protected":false},"author":2,"featured_media":50858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[176,236,275,116,112],"class_list":["post-50807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-176","tag-europa_centrale","tag-f_marino","tag-ldb","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/50807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=50807"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/50807\/revisions"}],"predecessor-version":[{"id":50914,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/50807\/revisions\/50914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/50858"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=50807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=50807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=50807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}