{"id":499,"date":"2017-10-07T18:39:21","date_gmt":"2017-10-07T17:39:21","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/tarantola\/"},"modified":"2023-03-26T14:30:45","modified_gmt":"2023-03-26T12:30:45","slug":"tarantola","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/10\/07\/tarantola\/","title":{"rendered":"Tarantola &#8211; Gnocchi di riso"},"content":{"rendered":"<p style=\"text-align: justify;\">In un primo momento ero indecisa se acquistare questi &#8220;gnocchi di riso&#8221; (prodotti dall&#8217; &#8220;Antica Riseria Tarantola&#8221; di Albairate).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Come ricorderete ne avevo anticipato scritto <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/09\/14\/antica-riseria-tarantola\/\">qui,<\/a><\/strong><\/em>\u00c2\u00a0 mentre <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/07\/09\/fragole-risotto\/\"><em><strong>qua<\/strong><\/em> <\/a>li avevo utilizzati per la preparazione del risottl alle fragole.<\/p>\n<p style=\"text-align: justify;\">Poi mi sono dispersa tra le mie faccende e non ho scritto piu&#8217; niente di questi gnocchi.<\/p>\n<p style=\"text-align: justify;\">Alla fine, inspiegabilmente, mi sono ritrovata in mano la confezione di &#8220;gnocchi di riso&#8221; a casa \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Il\u00c2\u00a0 dubbio che ho subito avuto e&#8217; stato su come prepararli al meglio, magari con un sugo particolare o quanto altro, per esaltare l&#8217;eventuale sapore &#8220;diverso&#8221;(??)\/<\/p>\n<p style=\"text-align: justify;\">Niente di piu&#8217; facile: nel solito modo (con pesto o passata).<\/p>\n<p style=\"text-align: justify;\">Vedete che ho scritto un numero sulla confezione?<\/p>\n<p style=\"text-align: justify;\">Mi riferisco al punteggio ProPoints della WW.<br \/>\nPer 100gr di gnocchi di riso, bisogna calcolare solo 4PP&#8230; peccato che, alla fine, ne abbia assaggiato solamente uno, mentre il resto e&#8217; finito nelle fauci di Tobias. \ud83d\ude41<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un primo momento ero indecisa se acquistare questi &#8220;gnocchi di riso&#8221; (prodotti dall&#8217; &#8220;Antica Riseria Tarantola&#8221; di Albairate).<\/p>\n","protected":false},"author":2,"featured_media":5850,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[49],"class_list":["post-499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/499\/revisions"}],"predecessor-version":[{"id":41376,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/499\/revisions\/41376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/5850"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}