{"id":49793,"date":"2025-12-29T12:17:02","date_gmt":"2025-12-29T11:17:02","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49793"},"modified":"2025-12-29T16:06:52","modified_gmt":"2025-12-29T15:06:52","slug":"bibanesi-ldb-e-esubero","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/12\/29\/bibanesi-ldb-e-esubero\/","title":{"rendered":"Bibanesi &#8211; ldb e esubero"},"content":{"rendered":"<p style=\"text-align: justify;\">Lo ammetto.<br \/>\nDovrei fare un po&#8217; di cose, tra cui finire di aggiornare ancora il mio Blog con le vacanze appena trascorse (e non solo!) ma sto perdendo tempo.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quindi, quando ho visto questi &#8220;<strong>Bibanesi<\/strong>&#8221; ne ho approfittato per prepararli e verificare il risultato.<br \/>\nLa mia idea sarebbe quella di portarli alla cena di fine corso &#8220;abspecken&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il nome &#8220;bibanese&#8221; deriva da Bibano di Godega San Urbano(TV), ossia il nome del paese di origine della fabbrica che li produce.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49797\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251122_110716-e1763810181771-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251122_110716-e1763810181771-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251122_110716-e1763810181771-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251122_110716-e1763810181771-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251122_110716-e1763810181771-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <strong><em><a href=\"https:\/\/www.aniceecannella.com\/i-bibanesi\/\">Bibanesi<\/a><\/em><\/strong><\/p>\n<pre>400 gr di farina 0\r\n150\/180 gr circa di acqua (l\u00e2\u20ac\u2122impasto dovr\u00c3\u00a0 essere morbido come il lobo dell\u00e2\u20ac\u2122orecchio)\r\n1 cucchiaino di malto\r\n50 gr olio evo\r\n30 gr. di strutto\r\n12 gr lievito di birra (*)\r\n8 gr sale\r\n\r\n<strong>Per decorare<\/strong>:\r\nSemi di sesamo\r\nSemi di finocchio\r\nSemi di papavero<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Impastate tutti gli ingredienti per circa 10 minuti, a mano sulla spianatoia (o nella planetaria).<br \/>\nLasciate riposare l\u00e2\u20ac\u2122impasto 30\u00e2\u20ac\u2122.<\/p>\n<p style=\"text-align: justify;\">Formate dei grissini grossi circa un dito e lunghi, ripassateli nei semi prescelti, poi tagliate dei pezzi da 5 cm. lasciandoli abbastanza irregolari.<\/p>\n<p style=\"text-align: justify;\">Sistemateli su una teglia coperta da carta forno e lasciateli lievitare ancora 1 ora circa, ma non di pi\u00c3\u00b9.<\/p>\n<p style=\"text-align: justify;\">Pre-riscaldate il forno a 180\u00c2\u00b0\/190\u00c2\u00b0 ventilato (*)<br \/>\nInfornateli\u00c2\u00a0 per 25 minuti, o fino a che non risultano dorati.<br \/>\nAbbassate il forno a circa 150\u00c2\u00b0 e lasciateli tostare ancora una decina di minuti, controllandoli: devono rimanere dorati, ma diventare croccanti anche dentro.<\/p>\n<p style=\"text-align: justify;\">Fateli raffreddare in forno spento e semiaperto, quest\u00e2\u20ac\u2122ultima cosa \u00c3\u00a8 importante, siate pazienti e aspettate che siano completamente freddi per assaggiarli.<\/p>\n<p style=\"text-align: justify;\">Si conservano benissimo anche una settimana in una scatola di latta.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho inserito 10 grammi di lievito di birra fresco e 50gr di <strong>esubero<\/strong> (erano mesi che non rinfrescavo Vera, giusto per evitare di buttarne un po&#8217;)<\/li>\n<li style=\"text-align: justify;\">Ho dunque inserito in totale 120gr di <strong>acqua<\/strong> (100 per iniziare, gli altri gocci dato che l&#8217;impasto lo richiedeva)<\/li>\n<li style=\"text-align: justify;\">Ho utilizzato il forno <strong>ventilato<\/strong> cosi&#8217; da cuocere 2 teglie contemporaneamente. Nel caso abbiate una teglia con bibanesi un po&#8217; piu&#8217; grossi, metteteli nel ripiano sotto.<\/li>\n<li style=\"text-align: justify;\">Ottimi per accompagnare affettati o perche&#8217; no, un antipastino.<\/li>\n<li style=\"text-align: justify;\">Nulla vieta di sostituire la farina utilizzata nella ricetta con quella di kamut.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo ammetto. Dovrei fare un po&#8217; di cose, tra cui finire di aggiornare ancora il mio Blog con le vacanze appena trascorse (e non solo!) ma sto perdendo tempo.<\/p>\n","protected":false},"author":2,"featured_media":49798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[116,112],"class_list":["post-49793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-ldb","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49793"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49793\/revisions"}],"predecessor-version":[{"id":49799,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49793\/revisions\/49799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49798"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}