{"id":49757,"date":"2025-12-14T17:37:59","date_gmt":"2025-12-14T16:37:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49757"},"modified":"2025-12-14T18:48:20","modified_gmt":"2025-12-14T17:48:20","slug":"post_cheto_1","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/12\/14\/post_cheto_1\/","title":{"rendered":"Reintroduzione cibi &#8211; 1"},"content":{"rendered":"<p style=\"text-align: justify;\">Ho meditato molto se proseguire con la cheto o iniziare la reintroduzione dei cibi.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Dopo aver continuato per 2 settimane, ho deciso di interrompere: ero stufa della solita colazione (mi ha poi inviato altre proposte) ma, soprattutto, di mangiare tutta quella carne.<br \/>\nEffettivamente ne avro&#8217; mangiata cosi&#8217; tanto che avrei potuto coprire almeno 6 mesi della mia vita standard.<\/p>\n<p style=\"text-align: justify;\">La reintroduzione non deve avvenire velocemente, ma con una certa gradualita&#8217;.<\/p>\n<p style=\"text-align: justify;\">Ho cosi&#8217; comunicato ad Imma il mio ultimo peso e&#8230; rieccomi con un nuovo piano alimentare.<br \/>\nGuardando il plan, le colazioni sembrano molto interessanti: molte sono salate.<br \/>\nIl cioccolato e&#8217; piu&#8217; scarso, come frutta secca ho molti pistacchi e, finalmente, rivedo della verdura meno triste e della frutta.<br \/>\nOltre ai legumi ed a una parvenza di cereali.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49911\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/12\/ok_IMG_20251125_202317-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/12\/ok_IMG_20251125_202317-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/12\/ok_IMG_20251125_202317-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/12\/ok_IMG_20251125_202317-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Avendo tagliato ieri dell&#8217;avocado, ho iniziato immediatamente a sbagliare, con la colazione del giovedi..<\/p>\n<p><strong>Colazione<\/strong> (colazione del giovedi)<br \/>\n1 wasa integrali<br \/>\n23 avocado<br \/>\n15 formaggio spalmabile<br \/>\n5 semi di zucca<\/p>\n<p><strong>Pranzo<\/strong><br \/>\n100 ceci<br \/>\n50 tonno sott&#8217;olio<br \/>\n120 insalata+carota+cetriolo+sedano rapa<br \/>\n15 olio<\/p>\n<p><strong>Merenda<\/strong><br \/>\n15g pistacchi<\/p>\n<p><strong>Cena<\/strong><br \/>\n200 spada<br \/>\n250 verdura<br \/>\n5 olio<br \/>\n40 pane<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho meditato molto se proseguire con la cheto o iniziare la reintroduzione dei cibi.<\/p>\n","protected":false},"author":2,"featured_media":49911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[277,278],"class_list":["post-49757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","tag-cheto","tag-keto"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49757"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49757\/revisions"}],"predecessor-version":[{"id":49913,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49757\/revisions\/49913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49911"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}