{"id":49618,"date":"2026-01-03T18:03:55","date_gmt":"2026-01-03T17:03:55","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49618"},"modified":"2025-11-11T20:09:18","modified_gmt":"2025-11-11T19:09:18","slug":"terra","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2026\/01\/03\/terra\/","title":{"rendered":"&#8230; TERRA !!!.."},"content":{"rendered":"<p style=\"text-align: justify;\">Sicuramente saremo una tra le ultime famiglie ad essere passata all&#8217;utilizzo della &#8220;Soda Stream&#8221;, o apparecchiatura affine.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Stephan ha tenuto duro fino ad oggi, coerente fino alla fine alle nostre richieste e non fornendoci una minima risposta o motivazione.<\/p>\n<p style=\"text-align: justify;\">Stanchi di dover aspettare il non si sa bene che cosa o quale risposta da Geppo, in un attimo di sua distrazione abbiamo effettuato alcuni conti e.. direttamente l&#8217;acquisto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49619\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251104_110754-e1762422531993-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251104_110754-e1762422531993-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251104_110754-e1762422531993-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251104_110754-e1762422531993-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251104_110754-e1762422531993-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Per noi e&#8217; stato molto semplice:<\/p>\n<ul>\n<li style=\"text-align: justify;\">basta pesi da portare nel fare la spesa<\/li>\n<li style=\"text-align: justify;\">basta avere sacchetti della spazzatura pieni di bottiglie vuote (con la conseguenza di creare ulteriore disordine a quanto abbiamo di gia&#8217;)<\/li>\n<li style=\"text-align: justify;\">acqua gasata a nostro piacimento (vedi Tobias)<\/li>\n<li style=\"text-align: justify;\">tentativo (per me) di bere di piu&#8217;<\/li>\n<li style=\"text-align: justify;\">varie ed eventuali<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La scelta del modello si e&#8217; basata sulle offerte disponibili: niente di troppo esagerato, niente di troppo leggero.<br \/>\nQuindi <strong>TERRA<\/strong> e&#8217; stata la via di mezzo.<\/p>\n<p style=\"text-align: justify;\">L&#8217;offerta Amazon perfetta, nessuno sciroppo incluso alla confezione, alla quale abbiamo aggiunto altre 2 bottiglie di plastica.<\/p>\n<p style=\"text-align: justify;\">Al momento stiamo segnando quante bottiglie e quanti &#8220;tap&#8221; abbiamo fatto, giusto per statistica.<\/p>\n<p style=\"text-align: justify;\">E&#8217; stato anche corretto vedere la confezione delle bottiglie aggiunte con la seguente indicazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49640\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093435-e1762621373909-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093435-e1762621373909-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093435-e1762621373909-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093435-e1762621373909-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093435-e1762621373909-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49641\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093456-e1762621382884-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093456-e1762621382884-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093456-e1762621382884-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093456-e1762621382884-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251108_093456-e1762621382884-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Voi cosa ne pensate?<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sicuramente saremo una tra le ultime famiglie ad essere passata all&#8217;utilizzo della &#8220;Soda Stream&#8221;, o apparecchiatura affine.<\/p>\n","protected":false},"author":2,"featured_media":49619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[157],"class_list":["post-49618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","tag-acquisto"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49618"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49618\/revisions"}],"predecessor-version":[{"id":49642,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49618\/revisions\/49642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49619"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}