{"id":495,"date":"2017-10-11T18:39:21","date_gmt":"2017-10-11T17:39:21","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/spesa-bio-e-bionella\/"},"modified":"2022-01-25T16:53:51","modified_gmt":"2022-01-25T15:53:51","slug":"spesa-bio-e-bionella","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/10\/11\/spesa-bio-e-bionella\/","title":{"rendered":"Spesa Bio e BioNella"},"content":{"rendered":"<p style=\"text-align: justify;\">Ora ditemi, secondo voi e&#8217; possibile spedere un patrimonio per solo queste 4 cosine?<!--more--><br \/>\nLo so, le ho acquistate in un negozio BIO dove, naturalmente, cercavo altro&#8230; ma proprio non conviene.<\/p>\n<p style=\"text-align: justify;\">La <strong>bionella<\/strong>, poi, costa quasi come un vasetto intero di crema spalmabile!<br \/>\nSi, avrei potuto acquistare direttamente la porzione grozza, ma lo avrei dovuto anche TERMINARE.<br \/>\nNon che mi dispiaccia, in fondo, ma me ne serviva giusto un poco per preparare la &#8216;crema al caffe&#8217; in bottiglia (vedere <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/06\/25\/crema-al-caffe-in-bottiglia\/\" target=\"_blank\" rel=\"noopener\">qua<\/a>).<\/strong><\/em><\/p>\n<figure id=\"attachment_6985\" aria-describedby=\"caption-attachment-6985\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6985\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/spesa_bio.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/spesa_bio.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/spesa_bio-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/spesa_bio-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-6985\" class=\"wp-caption-text\">Spesa al negozio BIO<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ho sempre pensato che in un negozio BIO si fosse piu&#8217; rispettosi per l&#8217;ambiente circostante, nonche&#8217; il cibo piu&#8217; salutare.<br \/>\nMa mi devo ravvedere dopo aver visto gli ingredienti che costituisono la &#8216; <a href=\"https:\/\/www.bionella.info\/\" target=\"_blank\" rel=\"noopener\">Bionella<\/a> &#8216;, come e&#8217; verificabile dalla foto, almeno per quanto ne possa pensare io<\/p>\n<figure id=\"attachment_6984\" aria-describedby=\"caption-attachment-6984\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6984\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4935.jpg\" alt=\"\" width=\"400\" height=\"225\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4935.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4935-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4935-300x169.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-6984\" class=\"wp-caption-text\">Ingredienti della &#8216;BioNella&#8217;<\/figcaption><\/figure>\n<figure id=\"attachment_6983\" aria-describedby=\"caption-attachment-6983\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6983\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4934.jpg\" alt=\"\" width=\"400\" height=\"225\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4934.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4934-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4934-300x169.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-6983\" class=\"wp-caption-text\">&#8216;BioNella&#8217;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Nonostante gli ingredienti di base siano 100% da agricoltura biologica e controllata, c&#8217;e&#8217; sempre la presenza dell&#8217;\u00c2\u00a0 olio di palma\u00c2\u00a0 .<\/p>\n<p style=\"text-align: justify;\">Tanto si e&#8217; detto e tanto si e&#8217; fatto, che e&#8217; stato bandito dalla stra-grande maggioranza dei prodotti dolciari.<\/p>\n<p style=\"text-align: justify;\">L&#8217;unica casa italiana che lo usa ancora, e che non si nasconde dietro a nulla, e&#8217; la Ferrero (nello specifico con la Nutella).<\/p>\n<p style=\"text-align: justify;\">Quindi, perche&#8217; fare tanto schiamazzo quando, a ben guardare, anche altri produttori utilizzano ancora questo &#8216;fatidico&#8217; olio?<br \/>\nSe proprio si vuole fare i puristi, <a href=\"https:\/\/www.greenme.it\/mangiare\/prodotti-biologici\/14239-alternative-biologiche-nutella-migliori\" target=\"_blank\" rel=\"noopener\">qui<\/a> potete trovare una valida lista di alternative (e non) di creme spalmabili alla nocciola con\/senza olio di palma.<\/p>\n<p style=\"text-align: justify;\">Non e&#8217; mia intenzione puntare il dito su un prodotto o un altro, ma a voi la scelta per i vostri prossimi acquisti.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ora ditemi, secondo voi e&#8217; possibile spedere un patrimonio per solo queste 4 cosine?<\/p>\n","protected":false},"author":2,"featured_media":6985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22],"tags":[84,88,89],"class_list":["post-495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","tag-cioccolato","tag-frutta_secca","tag-info_cucina"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions"}],"predecessor-version":[{"id":35633,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions\/35633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6985"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}