{"id":49464,"date":"2025-11-18T20:34:06","date_gmt":"2025-11-18T19:34:06","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49464"},"modified":"2025-11-19T17:50:12","modified_gmt":"2025-11-19T16:50:12","slug":"16_21-keto","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/11\/18\/16_21-keto\/","title":{"rendered":"16\/21 &#8211; Keto"},"content":{"rendered":"<p style=\"text-align: justify;\">Oramai sto andando avanti ad inerzia.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nManca poco al termine delle 3 settimane, poi ce ne saranno almeno altre 2 per la reintroduzione graduale degli ingredienti e della loro pesatura.<\/p>\n<p style=\"text-align: justify;\">Nonostante gli scarsi risultati ottenuti, diciamo che quanto letto in giro assicuravano un maggior calo di peso, vorrei evitare di perdere quel poco che ho smaltito.<br \/>\nE poi, il mio scopo principale non era tanto dimagrire (si, mi avrebbe dato un enorme incoraggiamento, lo ammetto) ma quello di dare un &#8220;colpo&#8221; al mio corpo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49622\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_194305-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_194305-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_194305-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_194305-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Colazione<\/strong><br \/>\n200 bevanda di mandorle (*)<br \/>\n10gr ciocco 85%<br \/>\n60gr lamponi (*)<br \/>\n(*) <em>ho provato con un frullato<\/em><\/p>\n<p><strong>Pranzo<\/strong><br \/>\n200gr petto di tacchino alla piastra<br \/>\n5 semini<br \/>\n150 cavolo bianco<br \/>\n20g olio<\/p>\n<p><strong>Merenda<\/strong><br \/>\n20 grana<br \/>\n80 finocchio<\/p>\n<p><strong>Cena<\/strong><br \/>\n2 uova sode ( cavolfiore al formaggio )<br \/>\n30gr taleggio<br \/>\n300 cavolfiore<br \/>\n15 olio<\/p>\n<p>20g mandorle \/ 20g noci<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Cavolfiore al formaggio<\/strong> &#8211; 4 persone<\/p>\n<pre>1 cavolfiore\r\n2 uova sode\r\nabbondante grana grattugiato\r\nprezzemolo tritato\r\n2 cucchiai di succo di limone\r\n1 cucchiaio di burro\r\nsale\r\npepe<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Dividete i cavolfiori a capolini, salateli e fateli lessare a vapore, oppure in microonde.<br \/>\nAncora caldi spennellateli con il burro fuso, rotolateli nel grana.<\/p>\n<p style=\"text-align: justify;\">Disponeteli in una teglia da forno, che possa andare in tavola.<br \/>\nPassateli nel microonde 30secondi per far sciogliere il formaggio, o nel forno tradizionale, caldo a 180gradi, per 10 minuti,<\/p>\n<p style=\"text-align: justify;\">Sgusciate le uova, tritatele, metteteli in una ciotola, aggiungete il succo di limone e il prezzemolo tritato.<br \/>\nSalate, pepate e rimescolate.<\/p>\n<p style=\"text-align: justify;\">A cottura ultimata, spolverizzate con il composto di uova e servite caldo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49626\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_191149-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_191149-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_191149-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_191149-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/11\/ok_IMG_20251105_191149-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Non ho rotolato le cimette di cavolfiore nel formaggio ma, essendo uno strato unico, lo ho distribuito sulla superficie.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oramai sto andando avanti ad inerzia.<\/p>\n","protected":false},"author":2,"featured_media":49622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,60,61],"tags":[277,278],"class_list":["post-49464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-secondi_piatti","category-uova-formaggio","tag-cheto","tag-keto"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49464"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49464\/revisions"}],"predecessor-version":[{"id":49627,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49464\/revisions\/49627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49622"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}