{"id":49281,"date":"2025-10-24T15:48:19","date_gmt":"2025-10-24T13:48:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49281"},"modified":"2025-10-12T15:30:56","modified_gmt":"2025-10-12T13:30:56","slug":"rigatoni-alla-zucca","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/10\/24\/rigatoni-alla-zucca\/","title":{"rendered":"Rigatoni alla zucca &#8211; versione leggera"},"content":{"rendered":"<p style=\"text-align: justify;\">Autunno, tempo di zucca e di altre prelibatezze.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La stagione estiva mi piace un sacco, soprattutto per la sua frutta colorata e profumata.<br \/>\nMa l&#8217;autunno e&#8217;, e resta, il mio periodo dell&#8217;anno preferito.<\/p>\n<figure id=\"attachment_49296\" aria-describedby=\"caption-attachment-49296\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49296\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251010_122205-e1760192363739-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251010_122205-e1760192363739-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251010_122205-e1760192363739-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251010_122205-e1760192363739-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251010_122205-e1760192363739-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-49296\" class=\"wp-caption-text\">Rigatoni alla zucca<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; Rigatoni alla zucca<\/strong> &#8211; 1 persona<\/p>\n<pre>60gr pasta (meglio integrale)\r\n200gr zucca a tocchetti\r\nolio\r\n1 scalogno piccolo\r\n100ml brodo vegetale\r\nrosmarino \/ prezzemolo\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una padella scaldate l&#8217;olio e fate soffriggere lo scalogno tritato, finche&#8217; non diventa trasparente.<br \/>\nAggiungete i tocchetti di zuccha (meglio della stessa grandezza, per avere una cottura uniforme) e cuoceteli a fuoco medio per circa 10 minuti, unendo il brodo poco alla volta, fino a quando la zucca non sara&#8217; morbida.<\/p>\n<p style=\"text-align: justify;\">Frullate meta&#8217; della zucca con il fondo di cottura per ottenere una crema vellutata.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo cuocete la pasta in acqua salata, fino a che non sara&#8217; al dente.<br \/>\nUnitela alla crema di zucca nella padella.<br \/>\nSaltate la pasta con la crema e i tocchetti di zucca (in caso di necessita&#8217; aggiungete qualche cucchiaio di acqua di cottura), aggiustate di sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Profumate con del rosmarino e servite subito.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autunno, tempo di zucca e di altre prelibatezze.<\/p>\n","protected":false},"author":2,"featured_media":49297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,138,51],"tags":[257,265],"class_list":["post-49281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-piatti_unici","category-primi_piatti","tag-light","tag-nascondo_le_verdure"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49281"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49281\/revisions"}],"predecessor-version":[{"id":49305,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49281\/revisions\/49305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49297"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}