{"id":49252,"date":"2025-10-20T15:28:04","date_gmt":"2025-10-20T13:28:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49252"},"modified":"2025-10-21T15:39:49","modified_gmt":"2025-10-21T13:39:49","slug":"avena-nuda-con-spinaci_pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/10\/20\/avena-nuda-con-spinaci_pap\/","title":{"rendered":"Avena nuda con spinaci e peperoncino &#8211; Pentola a pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Questo e&#8217; un tipico esempio di come modificare totalmente una ricetta ed ottenerne una nuova.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">L&#8217;idea originale parlava di &#8220;<em>risotto con bietole e peperoncino<\/em>&#8221; e, essendo in due e dovendo terminare un po&#8217; di scorte, ho sostituito il riso con l&#8217;ultimo avanzo di avena nuda.<\/p>\n<figure id=\"attachment_49265\" aria-describedby=\"caption-attachment-49265\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49265\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_122137-e1760016294887-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_122137-e1760016294887-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_122137-e1760016294887-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_122137-e1760016294887-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_122137-e1760016294887-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-49265\" class=\"wp-caption-text\">Avena nuda con spinaci e peperoncino<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Le biete?<br \/>\nNon le ho trovate al mercato, quindi&#8230; spinaci surgelati \ud83d\ude42<\/p>\n<p><strong>Ingredienti &#8211; Risotto con bietole e peperoncino<\/strong> &#8211; 2 persone<\/p>\n<pre>120gr di riso semi integrale\r\n300gr di bietole\r\n50gr di grana grattugiato (*)\r\n1 cucchiaio di olio\r\n1 scalogno\r\nsale\r\npeperoncino (a piacere)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mondate le bietole e tritatele.<br \/>\nMettetele poi in un litro e 1\/2 di acqua in ebollizione e spegnete il fuoco dopo 2-3 minuti.<\/p>\n<p style=\"text-align: justify;\">Affettate a velo lo scalogno e mettetelo in una casseruola con l&#8217;olio caldo ad appassire.<\/p>\n<p style=\"text-align: justify;\">Versate il riso e lasciatelo insaporire aggiungendo un mestolino di acqua bollente (quella dove ci sono le biete).<br \/>\nPortate a cottura unendo poca acqua bollente con le biete per volta.<\/p>\n<p style=\"text-align: justify;\">Quando e&#8217; cotto, unite il grana, mescolando, e terminate con peperoncino in polvere a piacere.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Il riso integrale e&#8217; stato sostituito con <strong>avena nuda<\/strong><\/li>\n<li style=\"text-align: justify;\">La bieta e&#8217; stata sostituita con <strong>spinaci surgelati,<\/strong> leggermente poco cotti in microonde (conservando l&#8217;acqua di cottura)<\/li>\n<li style=\"text-align: justify;\">Gli spinaci sono stati aggiunti al riso poco per volta, insieme a dell&#8217;acqua con un pochino di dado<\/li>\n<li style=\"text-align: justify;\">Ho deciso di cuocere in <strong>Pentola a Pressione<\/strong>. Il tutto ha cotto circa 15 minuti dal fischio e, come quantita&#8217; di acqua\/brodo, ho messo il doppio del peso.<br \/>\nIl risultato e&#8217; stato un po&#8217; brodoso, cosi&#8217; da proseguire ed ultimare la cottura a fuoco vivo e senza coperchio<\/li>\n<li style=\"text-align: justify;\">Il grana? Una <strong>burrata<\/strong> sopra, per far contento il marito.<\/li>\n<li>Questa e&#8217; l&#8217;avena nuda utilizzata<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49267\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_115611-e1760016332838-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_115611-e1760016332838-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_115611-e1760016332838-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_115611-e1760016332838-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251009_115611-e1760016332838-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/li>\n<\/ul>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo e&#8217; un tipico esempio di come modificare totalmente una ricetta ed ottenerne una nuova.<\/p>\n","protected":false},"author":2,"featured_media":49268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,180,138,51,67],"tags":[54,53],"class_list":["post-49252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pentola-a-pressione","category-piatti_unici","category-primi_piatti","category-riso_risotti","tag-cereali","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49252"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49252\/revisions"}],"predecessor-version":[{"id":49270,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49252\/revisions\/49270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49268"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}