{"id":49248,"date":"2025-10-14T13:37:49","date_gmt":"2025-10-14T11:37:49","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49248"},"modified":"2025-10-09T12:07:13","modified_gmt":"2025-10-09T10:07:13","slug":"gamberetti-al-coriandolo-e-lime","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/10\/14\/gamberetti-al-coriandolo-e-lime\/","title":{"rendered":"Gamberetti al coriandolo e lime"},"content":{"rendered":"<p style=\"text-align: justify;\">Ero alla ricerca di come preparare, in modo diverso, i gamberi per la cena di questa sera.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Niente di complicato, volendoli aggiungere ad un&#8217;insalata mista, accompagnandoli con del pane.<\/p>\n<p style=\"text-align: justify;\">Ho cosi&#8217; iniziato a ricercare tra alcune ricette che avevo tenuto da parte, fino a quando non ho trovato &#8220;lei&#8221;, la ricetta ideale: <strong>gamberetti al coriandolo e lime<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Naturalmente non disponendo di lime o di coriandolo fresco, ho pensato di sostituire questi ingredienti con le loro solite alternative: limone e prezzemolo<\/p>\n<figure id=\"attachment_49258\" aria-describedby=\"caption-attachment-49258\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49258\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251007_191311-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251007_191311-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251007_191311-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251007_191311-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251007_191311-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-49258\" class=\"wp-caption-text\">Gamberetti al coriandolo e lime<\/figcaption><\/figure>\n<p><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/rasamalaysia.com\/cilantro-lime-shrimp\/\">Gamberetti al coriandolo e lime<\/a><\/strong><\/em><\/p>\n<pre>450 g di gamberoni jumbo, sgusciati e privati \u00e2\u20ac\u2039\u00e2\u20ac\u2039dell'intestino, con la coda\r\n\u00c2\u00bc di cucchiaino di sale, o a piacere\r\n1 pizzico di pepe di Cayenna\r\n2 cucchiai di olio d'oliva\r\n4 spicchi d'aglio tritati\r\n3 cucchiai di coriandolo tritato, gambi e foglie (*)\r\n1 cucchiaio di burro non salato\r\n2 cucchiai di succo di lime\r\nSpicchi di lime fresco (*)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Condite i gamberi con sale e pepe di Cayenna a piacere.<\/p>\n<p style=\"text-align: justify;\">Riscaldate una padella di ghisa e aggiungete l&#8217;olio d&#8217;oliva e l&#8217;aglio.<br \/>\nRosolate leggermente fino a quando non saranno fragranti, quindi aggiungete i gamberi.<\/p>\n<p style=\"text-align: justify;\">Mescolate e cuocete fino a met\u00c3\u00a0 cottura.<br \/>\nQuindi, aggiungete il coriandolo e il burro, mescolando per amalgamare bene il tutto.<br \/>\nInfine, aggiungete il succo di lime e continuate fino a completa cottura dei gamberi.<\/p>\n<p style=\"text-align: justify;\">Spegnete il fuoco quando il succo di lime sar\u00c3\u00a0 evaporato e i gamberi saranno ben cotti, con una superficie leggermente bruciacchiata.<br \/>\nServite subito con spicchi di lime fresco.<\/p>\n<p style=\"text-align: justify;\">Io li ho appoggiati su di una insalatona mista, ottimo!<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho sostituito il lime con del limone<\/li>\n<li style=\"text-align: justify;\">E lo stesso il coriandolo con del prezzemolo<\/li>\n<\/ul>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ero alla ricerca di come preparare, in modo diverso, i gamberi per la cena di questa sera.<\/p>\n","protected":false},"author":2,"featured_media":49258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,60],"tags":[],"class_list":["post-49248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-secondi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49248"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49248\/revisions"}],"predecessor-version":[{"id":49260,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49248\/revisions\/49260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49258"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}