{"id":49203,"date":"2025-10-04T10:20:02","date_gmt":"2025-10-04T08:20:02","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49203"},"modified":"2025-10-03T19:31:41","modified_gmt":"2025-10-03T17:31:41","slug":"sommer-emmer","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/10\/04\/sommer-emmer\/","title":{"rendered":"Sommer-Emmer &#8211;"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>farro dicoccum<\/strong> (Triticum dicoccum) \u00c3\u00a8 una variet\u00c3\u00a0 di frumento o Triticum, un cereale minore molto antico, ancora oggi utilizzato in cucina per preparare insalate estive, zuppe, pasta e prodotti da forno.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il farro dicoccum noto anche come emmer, farro medio o comunemente anche solo farro, \u00c3\u00a8 un cereale della famiglia delle Poace ed e&#8217; una delle tre specie del genere Triticum .<\/p>\n<p style=\"text-align: justify;\">Le prime menzioni di questo cereale si ritrovano nella Mesopotamia del terzo millennio, ed in seguito anche nella Bibbia.<\/p>\n<p style=\"text-align: justify;\">Non mi resta che aprire il sacchetto e &#8230; provare a utilizzarlo\u00c2\u00a0 \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">La ricetta seguita e&#8217; stata presa da Brot, rivista del 30-1-2019<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-49213\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251001_162819-e1759512102707-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251001_162819-e1759512102707-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251001_162819-e1759512102707-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251001_162819-e1759512102707-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/10\/ok_IMG_20251001_162819-e1759512102707-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Ingredienti &#8211; Sommer-Emmer<\/strong> &#8211; 1 pagnotta<\/p>\n<pre><strong>Preimpasto<\/strong>\r\n 300gr di semola - Hartweizengriess (*)\r\n 200gr di acqua ghiacciata (*)\r\n 0,1gr di lievito fresco\r\n\r\n<strong>Autolisi<\/strong>\r\n 300gr di farina di farro integrale (Emmer) \/\/ farro dicocco\r\n 220gr di acqua tiepida\r\n\r\n<strong>Impasto principale<\/strong>\r\n Preimpasto\r\n Autolisi\r\n 12gr di sale<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Preimpasto<\/strong><br \/>\nImpastate a mano gli ingredienti del preimpasto e lasciate maturare a temperatura ambiente per 14-18 ore.<\/p>\n<p style=\"text-align: justify;\"><strong>Autolisi<\/strong><br \/>\nMescolate la farina con l&#8217;acqua e lasciate gonfiare per 60 minuti<\/p>\n<p style=\"text-align: justify;\">Impasto principale<\/p>\n<p style=\"text-align: justify;\">Impastate i due pre-impasti con il sale per 4 minuti a velocita&#8217; lenta.<\/p>\n<p style=\"text-align: justify;\">Coprite l&#8217;impasto e lasciatelo riposare a temperatura ambiente per 2 ore, effettuando delle pieghe ogni 30 minuti.<\/p>\n<p style=\"text-align: justify;\">Date all&#8217;impasto una forma (rotonda) e mettetelo in un cestino di lievitazione infarinato, con chiusura in alto, e coprite per 1 ora.<\/p>\n<p style=\"text-align: justify;\">Capovolgete l&#8217;impasto dal cestino di lievitazione (chiusura in basso).<\/p>\n<p style=\"text-align: justify;\">Effettuate dei tagli trasversali.<\/p>\n<p style=\"text-align: justify;\">Mettetelo in forno ben caldo a 250gradi con vapore.<br \/>\nDopo 10 minuti abbassate la temperatura a 230gradi e proseguite la cottura per ulteriori 15 minuti.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Nel preimpasto l&#8217;acqua inserita era a temperatura ambiente<\/li>\n<li style=\"text-align: justify;\">Non ho utilizzato solamente &#8220;Hartweizengriess&#8221; ma un mix di farine di semola che avevo in dispensa. Cosi&#8217; composto:<br \/>\n187gr di Hartweizengriess<br \/>\n50gr di semola rimacinata<br \/>\n46gr di farina Pan (per arepa)<br \/>\n16gr di Weichweizengriess<\/li>\n<li style=\"text-align: justify;\">Comparando il risultato ottenuto con l&#8217;immagine, direi che sono ben diversi.<br \/>\nNel mio l&#8217;interno e&#8217; compatto, tipico di una forma di pane di campagna, mentre nell&#8217;illustrazione sarebbe dovuto essere bucoso.<\/li>\n<li style=\"text-align: justify;\">Non so se sia dovuto alle modifiche, ma non e&#8217; esploso assolutamente in cottura, risultando compatto ma buono<\/li>\n<\/ul>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il farro dicoccum (Triticum dicoccum) \u00c3\u00a8 una variet\u00c3\u00a0 di frumento o Triticum, un cereale minore molto antico, ancora oggi utilizzato in cucina per preparare insalate estive, zuppe, pasta e prodotti da forno.<\/p>\n","protected":false},"author":2,"featured_media":49214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[54,116],"class_list":["post-49203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-cereali","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49203"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49203\/revisions"}],"predecessor-version":[{"id":49215,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49203\/revisions\/49215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/49214"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}