{"id":49138,"date":"2025-10-02T13:00:23","date_gmt":"2025-10-02T11:00:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=49138"},"modified":"2025-09-28T16:08:15","modified_gmt":"2025-09-28T14:08:15","slug":"riso-venere-verdure","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/10\/02\/riso-venere-verdure\/","title":{"rendered":"Riso venere con (fave) e verdure"},"content":{"rendered":"<p style=\"text-align: justify;\">Mi sono messa a sistemare la dispensa della cucina, quella contenente cibo per intendersi, e sono saltati fuori prodotti che non ricordavo di avere e, visto il periodo, meglio consumare.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">In questo caso&#8230;<strong> riso venere (nero)<\/strong> integrale.<\/p>\n<p style=\"text-align: justify;\">Per il suo utilizzo ho seguito la seguente ricetta<\/p>\n<p><strong>Ingredienti &#8211; Riso venere con (fave) e verdure<\/strong> &#8211; 2 persone<\/p>\n<pre>150gr di riso venere\r\n100gr di fave surgelate (*)\r\n50gr di piselli surgelati\r\n1 pomodoro\r\n2 carote\r\n1 scalogno\r\n1 cucchiao di olio\r\nsale\r\nprezzemolo\r\npepe<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete a lessare il riso Venere integrale (verificare il tempo di cottura scritto sulla confezione, il mio ci impiega circa 30 minuti dall&#8217;ebollizione).<br \/>\nQuando mancano circa 20 minuti alla fine della cottura, regolate si sale.<\/p>\n<p style=\"text-align: justify;\">Fate lessare fave e fagioli surgelati (in acqua o nel micro), poi scolateli e versateli in un tegame con l&#8217;olio caldo e lo scalogno tritato gia&#8217; appassito.<\/p>\n<p style=\"text-align: justify;\">Unite le carote ed il pomodoro tritati e lasciate cuocere 7-10 minuti.<\/p>\n<p style=\"text-align: justify;\">Aggiungete il riso Venere scolato, una presa di pepe nero e prezzemolo tritato.<\/p>\n<p style=\"text-align: justify;\">Mescolate bene e servite.<\/p>\n<p style=\"text-align: justify;\">Io ho inserito nella padella anche dei ceci scolati, cosi&#8217; da creare un piatto unico.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Non ho fave in casa, e neppure ne vado cosi&#8217; matta..<br \/>\nPer sostituirle, ho abbondato con i piselli e l&#8217;altra verdura<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi sono messa a sistemare la dispensa della cucina, quella contenente cibo per intendersi, e sono saltati fuori prodotti che non ricordavo di avere e, visto il periodo, meglio consumare.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,138],"tags":[54,55,256],"class_list":["post-49138","post","type-post","status-publish","format-standard","hentry","category-food","category-piatti_unici","tag-cereali","tag-legumi","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=49138"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49138\/revisions"}],"predecessor-version":[{"id":49142,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/49138\/revisions\/49142"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=49138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=49138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=49138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}