{"id":48797,"date":"2025-07-30T12:27:30","date_gmt":"2025-07-30T10:27:30","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=48797"},"modified":"2025-07-21T11:44:21","modified_gmt":"2025-07-21T09:44:21","slug":"crinkles-al-caffe-e-cioccolato","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/07\/30\/crinkles-al-caffe-e-cioccolato\/","title":{"rendered":"&#8220;Crinkles&#8221; al caffe&#8217; e cioccolato"},"content":{"rendered":"<p style=\"text-align: justify;\">Ancora una volta Tobias e&#8217; stato invitato ad una festa di compleanno.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Questa volta giocheranno a poker, quindi eviterei di preparare della focaccia\/pizza (ungerebbe inutilmente le mani) o del beveraggio (presenza di &#8220;minorenni&#8221;).<\/p>\n<p style=\"text-align: justify;\">Dei cookies sarebbero stati troppo scontati.<br \/>\nHo cosi&#8217; scovato, sul <strong>TavolarteGusto<\/strong>, dei fantastici biscotti (con la speranza di avere la possibilita&#8217; di assaggiarne qualcuno anche io!).<\/p>\n<figure id=\"attachment_48840\" aria-describedby=\"caption-attachment-48840\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48840\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250720_072722-621x1024.jpg\" alt=\"\" width=\"525\" height=\"866\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250720_072722-621x1024.jpg 621w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250720_072722-91x150.jpg 91w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250720_072722-182x300.jpg 182w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250720_072722-768x1266.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48840\" class=\"wp-caption-text\">&#8220;Crinkles&#8221; al caffe&#8217; e cioccolato<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/www.tavolartegusto.it\/ricetta\/biscotti-al-caffe\/\">Biscotti al caffe&#8217; <\/a><\/strong><\/em>&#8211; Quantit\u00c3\u00a0 per circa 40 pezzi<\/p>\n<pre>280 gr di farina 00\r\n2 cucchiai di caff\u00c3\u00a8 solubile da sciogliere in 1 cucchiaio di acqua calda\r\n100 gr di zucchero semolato + 3 cucchiai per rotolare i biscotti\r\n100 gr di burro morbido (90ml olio di semi di girasole - o a scelta)\r\n1 uovo\r\n1 cucchiaino di lievito per dolci\r\nvaniglia (in polvere, in bacca o estratto)\r\n150 gr di zucchero a velo per rotolare i biscotti<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Prima di tutto montate con le fruste burro (oppure l\u00e2\u20ac\u2122olio) e zucchero con la vaniglia fino ad ottenere una crema spumosa e chiara.<\/p>\n<p style=\"text-align: justify;\">Poi aggiungete l\u00e2\u20ac\u2122uovo, continuate a montare e a filo aggiungete il caff\u00c3\u00a8 precedentemente mescolato con l\u00e2\u20ac\u2122acqua.<\/p>\n<p style=\"text-align: justify;\">Infine aggiungete la farina setacciata con il lievito e impastate a mano pochi secondi. Se necessario aggiungete un altro cucchiaio di farina per spolverarvi le mani e staccare l\u00e2\u20ac\u2122impasto dal piano di lavoro.<\/p>\n<p style=\"text-align: justify;\">Sigillate con una pellicola e riponete in freezer 15 minuti (oppure 40 \u00e2\u20ac\u201c 50 minuti in frigo)<\/p>\n<p style=\"text-align: justify;\">A questo punto staccate dall\u00e2\u20ac\u2122impasto dei pezzetti di 18 gr., arrotolate ogni pezzetto tra i palmi, tanto da fare una forma tonda ai biscotti al caff\u00c3\u00a8.<br \/>\nRotolate prima nello zucchero semolato, poi nello zucchero a velo.<\/p>\n<p style=\"text-align: justify;\"><strong>Attenzione<\/strong> a svolgere bene quest\u00e2\u20ac\u2122ultimo passaggio, in modo che si formi una patina molto bianca, in questo modo le crepe saranno visibili!<\/p>\n<p style=\"text-align: justify;\">Man mano che realizzate i vostri biscottini al caffe riponeteli in una teglia foderata di carta da forno ad una distanza di 5 \u00e2\u20ac\u201c 6 cm .<br \/>\nRiponete la teglia in freezer per 20 minuti oppure in frigo per circa 1 h (potete anche lasciarli 1 giorno e cuocere al momento).<\/p>\n<p style=\"text-align: justify;\">Se vedete che in frigo i biscotti hanno assorbito tutto lo zucchero, rotolateli di nuovo nello zucchero a velo, vedrete che le crepe saranno perfette!<\/p>\n<p style=\"text-align: justify;\">Poi cuocete in forno caldo a 190\u00c2\u00b0 \u00e2\u20ac\u201c 180\u00c2\u00b0 nella parte media del forno per i primi 5 \u00e2\u20ac\u201c 10 minuti, finch\u00c3\u00a8 non si gonfiano e crepano in superficie; poi abbassate a 170\u00c2\u00b0 senza aprire il forno e completate la cottura per 5 \u00e2\u20ac\u201c 8 minuti circa!<\/p>\n<p style=\"text-align: justify;\">Sfornate e lasciate intiepidire fuori dalla teglia per circa 30 minuti!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48828\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_151952-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_151952-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_151952-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_151952-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_151952-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Serviteli quando sono ben freddi<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_48838\" aria-describedby=\"caption-attachment-48838\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48838\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250719_190306-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250719_190306-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250719_190306-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250719_190306-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250719_190306-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48838\" class=\"wp-caption-text\">&#8220;Crinkles&#8221; al caffe&#8217; e cioccolato<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Chocolate crinkles cookies<\/strong> ( di Alice Medrich ) &#8211; circa 30 pezzi<\/p>\n<pre>180 gr di cioccolato fondente\r\n60 gr di burro\r\n2 uova\r\n150 gr di zucchero semolato + qualche cucchiaio per la copertura\r\n1 cucchiaino di vaniglia\r\n220 gr di farina 00\r\n1 cucchiaino di lievito\r\n200 gr circa di zucchero a velo per la copertura dei biscotti<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Prima di tutto sciogliete a bagnomaria il cioccolato ed il burro, lasciate intiepidire e ponete poi tutto da parte facendo raffreddare completamente<\/p>\n<p style=\"text-align: justify;\">Montate le uova con lo zucchero semolato (150gr) e la vaniglia per 1 minuto.<\/p>\n<p style=\"text-align: justify;\">Infine aggiungete il composto di cioccolato fuso freddo, mescolando con un cucchiaio, aggiungete farina e lievito ben setacciato.<\/p>\n<figure id=\"attachment_48816\" aria-describedby=\"caption-attachment-48816\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48816\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102642-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102642-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102642-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102642-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102642-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48816\" class=\"wp-caption-text\">&#8220;Crinkles&#8221; al cioccolato<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Impastate pochi secondi con le mani per creare l\u00e2\u20ac\u2122impasto!<br \/>\nL\u00e2\u20ac\u2122impasto avr\u00c3\u00a0 bisogno di restare in frigo per almeno 3 h , deve risultare duro.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48817\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102846-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102846-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102846-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102846-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/07\/ok_IMG_20250718_102846-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quando l\u00e2\u20ac\u2122impasto \u00c3\u00a8 freddo e denso, staccate delle palline di 18 gr ciascuna con un cucchiaio, arrotolatele tra mani.<br \/>\nPotete lasciarle al naturale oppure rotolarle nello zucchero semolato.<\/p>\n<p style=\"text-align: justify;\">Man mano che le realizzate adagiatele su una teglia rivestita di carta da forno.<\/p>\n<p style=\"text-align: justify;\">Per avere l\u00e2\u20ac\u2122effetto screpolato il cosidetto &#8220;Crinkles&#8221; rotolate le palline prima nello zucchero semolato e infine nello zucchero a velo.<\/p>\n<p style=\"text-align: justify;\">Se avete utilizzato impasto con il burro i biscotti prima di essere infornati dovranno stare 30 \u00e2\u20ac\u201c 40 minuti in frigo ad indurirsi.<\/p>\n<p style=\"text-align: justify;\">In ogni caso cuocete una teglia per volta, in forno statico ben caldo a 180\u00c2\u00b0 per 12 minuti, finch\u00c3\u00a9 non risultano gonfi.<\/p>\n<p style=\"text-align: justify;\">Sfornate e lasciate intiepidire perfettamente!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora una volta Tobias e&#8217; stato invitato ad una festa di compleanno.<\/p>\n","protected":false},"author":2,"featured_media":48838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,69,22],"tags":[84,273],"class_list":["post-48797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-dessert","category-food","tag-cioccolato","tag-tobias"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=48797"}],"version-history":[{"count":12,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48797\/revisions"}],"predecessor-version":[{"id":48841,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48797\/revisions\/48841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/48838"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=48797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=48797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=48797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}