{"id":48444,"date":"2025-06-28T16:21:07","date_gmt":"2025-06-28T14:21:07","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=48444"},"modified":"2025-06-26T16:26:54","modified_gmt":"2025-06-26T14:26:54","slug":"focaccia-genovese_sorelle-simili","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/06\/28\/focaccia-genovese_sorelle-simili\/","title":{"rendered":"Focaccia genovese &#8211; Sorelle Simili (LDB)"},"content":{"rendered":"<p style=\"text-align: justify;\">In previsione del compleanno di Stephan, mi dedico ad alcune prove.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">In effetti avevo pensato di preparare la <strong>focaccia genovese<\/strong> (delle Sorelle Simili, dal loro libro &#8220;<em>Pane e roba dolce<\/em>&#8220;) per la festa della scuola (di Tobias), ma poi ho scoperto che non partecipera&#8217;.<\/p>\n<p style=\"text-align: justify;\">Quindi&#8230; l&#8217;ho fatta comunque.<\/p>\n<p style=\"text-align: justify;\">Essendo per due teglie, ne ho lasciato una &#8220;<strong>bianca<\/strong>&#8221; e, sull&#8217;altra, ho messo dei <strong>pomodorini<\/strong> (non avevo i ciliegini, quindi li ho tagliati in 4).<br \/>\nI pomodorini li ho spremuti leggermente, cosi&#8217; da utilizzare il loro succo insieme al mix olio-acqua, donando (spero) un sapore diverso.<\/p>\n<figure id=\"attachment_48477\" aria-describedby=\"caption-attachment-48477\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48477\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131641-e1750947725944-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131641-e1750947725944-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131641-e1750947725944-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131641-e1750947725944-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131641-e1750947725944-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48477\" class=\"wp-caption-text\">Focaccia genovese &#8211; Sorelle Simili (LDB)<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; Focaccia genovese &#8211; Sorelle Simili (LDB)<\/strong> &#8211; 2 teglie 30&#215;40<\/p>\n<pre>1 kg farina 00 (io per pizza)\r\n550 ml acqua\r\n20 g lievito di birra fresco\r\n20 g sale fino\r\n2 cucchiai olio di oliva\r\n\r\n<strong>Per la spennellatura (emulsione)<\/strong>\r\n6 cucchiai olio\r\n6 cucchiai acqua (o liquido rilasciato dai pomodorini)\r\nq.b. sale grosso\r\nVarie (*)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sciogliete in una ciotola il lievito di birra con circa met\u00c3\u00a0 dell\u00e2\u20ac\u2122acqua, quindi aggiungete una parte della farina e cominciate ad impastare.<br \/>\nUnite quindi i due cucchiai di olio e il sale e poi continuate ad aggiungere la farina rimasta, alternandola con l\u00e2\u20ac\u2122acqua.<br \/>\nQuando avrete ottenuto un impasto lavorabile, trasferitelo sul piano di lavoro e lavoratelo battendolo per 7-8 minuti.<\/p>\n<p style=\"text-align: justify;\">Lavorate fino ad ottenere un impasto liscio, formate una palla e mettetela in una ciotola unta di olio.<br \/>\nCoprite con un panno umido o con pellicola trasparente e fate lievitare fino al raddoppio (24gradi &#8211; circa un&#8217;oretta)<\/p>\n<p style=\"text-align: justify;\">Quando l\u00e2\u20ac\u2122impasto sar\u00c3\u00a0 lievitato, riprendetelo e rovesciatelo sul piano di lavoro.<br \/>\nDividete l\u00e2\u20ac\u2122impasto a met\u00c3\u00a0 e formate due filoni (circa 780-790 gr cadauno).<br \/>\nAppoggiate ciascun filone su una teglia 30 x 40 cm, rivestita di carta da forno (<em>ho preferito aggiungere un velo di olio, giusto per poi aiutarmi nella stesura dell&#8217;impasto &#8211; nella ricetta originale non c&#8217;e&#8217; olio in teglia<\/em>).<br \/>\nFate riposare l\u00e2\u20ac\u2122impasto per 15 minuti, quindi riprendetelo e stendetelo con un mattarello e con le mani, fino a ricoprire quasi completamente la teglia<\/p>\n<p style=\"text-align: justify;\">Lasciate riposare ancora 30 minuti<\/p>\n<p style=\"text-align: justify;\">Affondate le dita nella pasta, formando delle impronte profonde sulla superficie<\/p>\n<p style=\"text-align: justify;\">Spennellate le due focacce con l\u00e2\u20ac\u2122emulsione di acqua e olio e cospargete la superficie con granelli di sale grosso.<br \/>\nCoprite con pellicola (meglio non a contatto!) e continuate a far lievitare fino al raddoppio<\/p>\n<p style=\"text-align: justify;\">Una volta che le focacce saranno ben lievitate, infornatele in forno preriscaldato a 200\u00c2\u00b0C e fate cuocere per 25-30 minuti, finch\u00c3\u00a9 non avranno un bel colore dorato.<br \/>\nEssendo due teglie, invertite i ripiani a meta&#8217; cottura (o adattatevi alle esigenze della cottura)<\/p>\n<figure id=\"attachment_48478\" aria-describedby=\"caption-attachment-48478\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48478\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131647-e1750947713963-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131647-e1750947713963-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131647-e1750947713963-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131647-e1750947713963-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250625_131647-e1750947713963-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48478\" class=\"wp-caption-text\">Focaccia genovese &#8211; Sorelle Simili (LDB)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">E&#8217; possibile certamente variare la quantita&#8217; di farina inserita, aggiungendo un 30% di <strong>semola<\/strong>. Potremo quindi usare un mix di 700 gr Farina 00 + 300 gr Farina di semola rimacinata<\/li>\n<li style=\"text-align: justify;\">Non ho impastato a mano, ma utilizzato la <strong>planetaria<\/strong><\/li>\n<li style=\"text-align: justify;\">Potete aggiungere all\u00e2\u20ac\u2122impasto del vostro lievitato un paio di cucchiai di<strong> erbe aromatiche<\/strong>, dalla salvia al rosmarino.<\/li>\n<li style=\"text-align: justify;\">Potete anche decorare la <strong>superficie<\/strong> della focaccia prima di infornare con olive nere o verdi, cipolla tritata e\/o dei peperoni a filetti (precotti in padella precedentemente). Oppure pomodorini<br \/>\nO tanto altro ancora<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In previsione del compleanno di Stephan, mi dedico ad alcune prove.<\/p>\n","protected":false},"author":2,"featured_media":48473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,22,90],"tags":[116],"class_list":["post-48444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-focaccia","category-food","category-lievitati","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=48444"}],"version-history":[{"count":17,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48444\/revisions"}],"predecessor-version":[{"id":48486,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48444\/revisions\/48486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/48473"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=48444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=48444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=48444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}