{"id":48442,"date":"2025-06-18T18:40:04","date_gmt":"2025-06-18T16:40:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=48442"},"modified":"2025-07-04T17:28:20","modified_gmt":"2025-07-04T15:28:20","slug":"c-nonno_pedrieu","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/06\/18\/c-nonno_pedrieu\/","title":{"rendered":"Compleanno del Nonno. E Pedrieu"},"content":{"rendered":"<p style=\"text-align: justify;\">Essendo in periodo vacanziero (dalla scuola), ne abbiamo approfittato per fare un salto in Italia e festeggiare il compleanno del Nonno.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Niente di particolare gli e&#8217; stato regalato, non ha voluto nulla (come sempre).<\/p>\n<p style=\"text-align: justify;\">La sera ci siamo trovati al Pedrieu (di Garbagnate), lo stesso posto di <em><strong>6 anni fa<\/strong><\/em>.<\/p>\n<p>Fortunatamente siamo arrivati un po&#8217; in anticipo sull&#8217;orario di apertura, cosi&#8217; ho avuto la possibilita&#8217; di leggere, piu&#8217; volte, il Menu&#8217; proposto.<br \/>\nDi questo ne sono restata totalmente perplessa.. ma poi e&#8217; andato tutto bene.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48579\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_221256-e1751641958731-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_221256-e1751641958731-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_221256-e1751641958731-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_221256-e1751641958731-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_221256-e1751641958731-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Di seguito una carrellata dei piatti ordinati con (alcune) descrizioni, quelle che mi ricordo.<\/p>\n<figure id=\"attachment_48572\" aria-describedby=\"caption-attachment-48572\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48572 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0027-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0027-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0027-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0027-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0027-768x576.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48572\" class=\"wp-caption-text\">Polpettina di carne con verdurine e senape delicata<\/figcaption><\/figure>\n<figure id=\"attachment_48584\" aria-describedby=\"caption-attachment-48584\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48584 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203630-e1751641973686-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203630-e1751641973686-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203630-e1751641973686-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203630-e1751641973686-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203630-e1751641973686-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48584\" class=\"wp-caption-text\">Tagliere misto<\/figcaption><\/figure>\n<figure id=\"attachment_48582\" aria-describedby=\"caption-attachment-48582\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48582 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203635-e1751641991318-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203635-e1751641991318-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203635-e1751641991318-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203635-e1751641991318-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_203635-e1751641991318-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48582\" class=\"wp-caption-text\">Formaggio fuso con patate al cartoccio<\/figcaption><\/figure>\n<figure id=\"attachment_48576\" aria-describedby=\"caption-attachment-48576\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48576 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0028-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0028-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0028-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0028-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48576\" class=\"wp-caption-text\">crema di ceci con baccala&#8217; mantecato<\/figcaption><\/figure>\n<figure id=\"attachment_48573\" aria-describedby=\"caption-attachment-48573\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48573 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0029-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0029-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0029-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0029-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48573\" class=\"wp-caption-text\">Sella di maiale con ??<\/figcaption><\/figure>\n<figure id=\"attachment_48574\" aria-describedby=\"caption-attachment-48574\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48574 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0022-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0022-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0022-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0022-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48574\" class=\"wp-caption-text\">Tartare di carne con sedano fritto<\/figcaption><\/figure>\n<figure id=\"attachment_48577\" aria-describedby=\"caption-attachment-48577\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48577 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0025-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0025-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0025-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250618-WA0025-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48577\" class=\"wp-caption-text\">Ravioli all&#8217;ossobuco<\/figcaption><\/figure>\n<figure id=\"attachment_48578\" aria-describedby=\"caption-attachment-48578\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48578 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211405-e1751642002979-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211405-e1751642002979-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211405-e1751642002979-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211405-e1751642002979-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211405-e1751642002979-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48578\" class=\"wp-caption-text\">Tonno<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48580\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211047-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211047-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211047-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211047-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_211047-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Il tutto con del vinello bianco&#8230; che andava giu&#8217; perfettamente.<\/p>\n<p style=\"text-align: justify;\">Silvia, la padrona di casa, ci ha accolto molto bene e non ha avuto problemi quando abbiamo iniziato a spostare i tavoli (eliminandone uno) per stare un po&#8217; piu&#8217; raccolti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48585\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_200100-e1751641966224-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_200100-e1751641966224-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_200100-e1751641966224-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_200100-e1751641966224-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250618_200100-e1751641966224-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">La torta e&#8217; stata mangiata a casa, optando per la <strong>Pasticceria Palma<\/strong>: un&#8217;ennesima conferma!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48571\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250624_185613-1024x796.jpg\" alt=\"\" width=\"525\" height=\"408\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250624_185613-1024x796.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250624_185613-150x117.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250624_185613-300x233.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250624_185613-768x597.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">(Diciamo, onestamente, che siamo passati diverse volte per fare delle prove di valutazione dei loro prodotti :)\u00c2\u00a0 )<\/p>\n<p><strong>Per Informazioni<\/strong><\/p>\n<p><strong>Pedrieu<\/strong><br \/>\nVia Conciliazione 17<br \/>\n20024 Garbagnate Milanese<\/p>\n<p><strong>Pasticceria Palma<\/strong><br \/>\nVia Don Virgilio Sioli, 1c<br \/>\nRho<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Essendo in periodo vacanziero (dalla scuola), ne abbiamo approfittato per fare un salto in Italia e festeggiare il compleanno del Nonno.<\/p>\n","protected":false},"author":2,"featured_media":48571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,25,46,21],"tags":[36,28,274],"class_list":["post-48442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-italia","category-life","category-travel","tag-compleanno","tag-dove_mangiare","tag-vacanze_2025"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=48442"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48442\/revisions"}],"predecessor-version":[{"id":48588,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48442\/revisions\/48588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/48571"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=48442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=48442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=48442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}