{"id":48232,"date":"2025-06-01T10:26:24","date_gmt":"2025-06-01T08:26:24","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=48232"},"modified":"2025-06-01T17:04:16","modified_gmt":"2025-06-01T15:04:16","slug":"muffin-alla-cannella_ldb-fresco","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/06\/01\/muffin-alla-cannella_ldb-fresco\/","title":{"rendered":"Muffin alla Cannella &#8211; LDB fresco"},"content":{"rendered":"<p style=\"text-align: justify;\">Nelle note presenti nel Blog, dal quale ho preso la seguente ricetta, si scrive che <em>&#8220;Se conservati in un contenitore ermetico, <strong>i muffin alla cannella<\/strong> si conservano per almeno 3 giorni&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Staremo a vedere!!! (*)<\/p>\n<figure id=\"attachment_48257\" aria-describedby=\"caption-attachment-48257\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48257\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250531_090024-e1748790100574-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250531_090024-e1748790100574-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250531_090024-e1748790100574-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250531_090024-e1748790100574-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250531_090024-e1748790100574-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48257\" class=\"wp-caption-text\">Muffin alla Cannella &#8211; LDB fresco<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; <em><a href=\"https:\/\/www.einfachbacken.de\/rezepte\/zimtschnecken-muffins-weltbestes-rezept\">Muffin alla Cannella<\/a><\/em><\/strong><\/p>\n<pre><strong>Per l'impasto lievitato<\/strong>\r\n 120 ml di latte\r\n 60 g di burro\r\n \u00c2\u00bc di cubetto di lievito (10gr)\r\n 250 g di farina di grano tenero (tipo 00 \/\/ 450)\r\n 50 g di zucchero\r\n \u00c2\u00bd cucchiaino di cannella in polvere\r\n\r\n<strong>Crema<\/strong>\r\n 100 g di burro\r\n 2 cucchiaini di cannella in polvere\r\n 50 g di zucchero\r\n\r\nUn po' di burro per la teglia (se non avete i pirottini)\r\nUn po' di farina per lavorare sulla spianatoia<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Scaldate il latte e il burro in un pentolino fino a quando non saranno tiepidi (non fate bollire!).<br \/>\nSciogliete il lievito nel composto caldo di latte e burro.<br \/>\nMescolate la farina con lo zucchero e la cannella. Aggiungete il composto di lievito e impastate con il gancio della planetaria per circa 10 minuti fino a ottenere un impasto liscio.<br \/>\nCoprite l&#8217;impasto e lasciatelo lievitare in un luogo caldo per circa 60 minuti.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo..<br \/>\nFate sciogliere il burro in un pentolino (* <em><strong>Attenzione, meglio a pomata<\/strong><\/em>!!! ). Aggiungete lo zucchero e la cannella e mescolate.<\/p>\n<p style=\"text-align: justify;\">Imburrate bene uno stampo per muffin o foderatelo con pirottini di carta.<\/p>\n<p style=\"text-align: justify;\">Stendete l&#8217;impasto su una superficie infarinata in un rettangolo (circa 50&#215;30 cm *). Spennellatelo con il burro alla cannella e arrotolatelo dal lato lungo.<\/p>\n<figure id=\"attachment_48250\" aria-describedby=\"caption-attachment-48250\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48250\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_171907-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_171907-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_171907-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_171907-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_171907-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48250\" class=\"wp-caption-text\">Muffin alla Cannella &#8211; LDB fresco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Preriscaldate il forno statico a 180\u00c2\u00b0C (ventilato: 160 \u00c2\u00b0C).<\/p>\n<p style=\"text-align: justify;\">Tagliate i rotoli di pasta in 12 pezzi (circa 4 cm) con un coltello affilato.<br \/>\nDisponeteli nello stampo per muffin preparato e lasciateli lievitare per circa 15 minuti.<\/p>\n<figure id=\"attachment_48249\" aria-describedby=\"caption-attachment-48249\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48249\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_175211-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_175211-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_175211-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_175211-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG_20250530_175211-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48249\" class=\"wp-caption-text\">Muffin alla Cannella &#8211; LDB fresco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cuocete in forno preriscaldato per circa 20 minuti.<\/p>\n<p style=\"text-align: justify;\">Lasciateli raffreddare brevemente e poi toglieteli dallo stampo.<\/p>\n<figure id=\"attachment_48253\" aria-describedby=\"caption-attachment-48253\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-48253\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250530-WA0011-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250530-WA0011-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250530-WA0011-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250530-WA0011-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/06\/ok_IMG-20250530-WA0011-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-48253\" class=\"wp-caption-text\">Muffin alla Cannella &#8211; LDB fresco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Avendo della <strong>margarina<\/strong> (acquistata perche&#8217; si voleva fare i biscotti) ho utilizzato quella.<\/li>\n<li style=\"text-align: justify;\">Non sono cosi&#8217; sicura possa essere colpa della margarina&#8230; meglio il burro\/margarina a pomata (per il ripieno) che non farlo sciogliere!<\/li>\n<li style=\"text-align: justify;\">Il nostro zucchero era di <strong>canna<\/strong>.<\/li>\n<li style=\"text-align: justify;\">OK, sono ancora un&#8217;apprendista&#8230; ma un <strong>rettangolo di 50&#215;30<\/strong> comporta una pasta veramente sottile (non certo come quella rappresentata nella foto dal Blog). Il mio rettangolo era di 50&#215;30 (ed era fine!)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">(*) I dolcetti sono finiti velocemente.<br \/>\nNe ho assaggiato solamente uno (prova-gusto) e, personalmente, non e&#8217; che mi abbia fatto impazzire.<br \/>\nSi, sono decisamente piu&#8217; veloci da preparare, ma non mi hanno convinta.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelle note presenti nel Blog, dal quale ho preso la seguente ricetta, si scrive che &#8220;Se conservati in un contenitore ermetico, i muffin alla cannella si conservano per almeno 3 giorni&#8221;.<\/p>\n","protected":false},"author":2,"featured_media":48252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,145,22,90,80],"tags":[116],"class_list":["post-48232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-dolci","category-food","category-lievitati","category-muffins","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=48232"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48232\/revisions"}],"predecessor-version":[{"id":48258,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/48232\/revisions\/48258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/48252"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=48232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=48232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=48232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}