{"id":47409,"date":"2025-02-28T10:41:08","date_gmt":"2025-02-28T09:41:08","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=47409"},"modified":"2025-02-22T15:33:24","modified_gmt":"2025-02-22T14:33:24","slug":"porridge-al-cacao-base","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/02\/28\/porridge-al-cacao-base\/","title":{"rendered":"Porridge al cacao (base)"},"content":{"rendered":"<p style=\"text-align: justify;\">Fino ad oggi non avevamo mai preparato il <strong>porridge<\/strong>, secondo lo &#8220;standard&#8221; normale.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ossia cuocendolo direttamente in un pentolino, bensi&#8217; utilizzandolo semplicemente come overnight.<\/p>\n<p style=\"text-align: justify;\">Come mai?<br \/>\nSemplice, perche&#8217; per solamente 30-60gr di avena non ne valeva la pena.<br \/>\nAumentando la dose, ed aggiungendo quella parte di Tobias, ne e&#8217; valsa veramente la pena.<\/p>\n<figure id=\"attachment_47411\" aria-describedby=\"caption-attachment-47411\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47411\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG-20250217-WA0020-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG-20250217-WA0020-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG-20250217-WA0020-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG-20250217-WA0020-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG-20250217-WA0020-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG-20250217-WA0020.jpg 1152w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47411\" class=\"wp-caption-text\">Porridge al cacao (base)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Porridge al cacao &#8211; base<\/strong> &#8211; +4 portate<\/p>\n<pre>250gr di fiocchi di avena (Zart)\r\n700ml di latte\r\n2 cucchiai di cacao in polvere\r\nsale\r\n1 cucchiaino di cardamomo macinato\r\n2 cucchiai di sciroppo di acero \/ agave<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite i fiocchi di avena in una pentola e lasciateli scaldare.<br \/>\nAggiungete il latte e mescolate bene, a fuoco medio, per circa 5 minuti.<br \/>\nNel frattempo inserite il cacao in polvere, un pizzico di sale, il cardamomo (poco, attenzione, e&#8217; veramente intenso), addolcite (a piacere) con lo sciroppo di acero\/agave.<\/p>\n<p style=\"text-align: justify;\">Spegnete il fuoco e porzionate.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">A questo punto, non vi resta che aggiungere del <strong>topping<\/strong> a piacere: filetti di arancia \/ kiwi \/ frutti di bosco \/ banana, cioccolato (piu&#8217; o meno fondente), mousse di mandorle \/ arachidi,\u00c2\u00a0 frutta secca<\/li>\n<li>Sicuramente una brevissima scaldata (al microonde) lo rende perfetto.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fino ad oggi non avevamo mai preparato il porridge, secondo lo &#8220;standard&#8221; normale.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[84,258],"class_list":["post-47409","post","type-post","status-publish","format-standard","hentry","category-al_cucchiaio","category-dessert","category-food","tag-cioccolato","tag-colazione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=47409"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47409\/revisions"}],"predecessor-version":[{"id":47460,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47409\/revisions\/47460"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=47409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=47409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=47409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}