{"id":47397,"date":"2025-02-19T14:13:42","date_gmt":"2025-02-19T13:13:42","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=47397"},"modified":"2025-02-17T18:32:23","modified_gmt":"2025-02-17T17:32:23","slug":"ciabattine-lutz_ldb","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/02\/19\/ciabattine-lutz_ldb\/","title":{"rendered":"Ciabattine &#8211; Lutz &#8211; LdB"},"content":{"rendered":"<p style=\"text-align: justify;\">Proviamo a preparare altro pane ciabatta, con una ricetta presa da un libro diverso, proprio quello che mi aveva regalato Francesca alcuni anni fa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Come allora, ho ripetuto lo stesso pane ma.. proprio non ne ha voluto sapere di lievitare.<br \/>\nSara&#8217; forse perche&#8217; non ho utilizzato la pietra ma la teglia forata?<br \/>\nE dire che, questa volta, ho inserito anche il vapore.<\/p>\n<p style=\"text-align: justify;\">Sono abbastanza scettica sull&#8217;ordine di inserimento degli ingredienti.<br \/>\nVoi cosa ne pensate?<\/p>\n<figure id=\"attachment_47398\" aria-describedby=\"caption-attachment-47398\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47398\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133537-e1739809774887-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133537-e1739809774887-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133537-e1739809774887-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133537-e1739809774887-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133537-e1739809774887-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47398\" class=\"wp-caption-text\">Ciabattine<\/figcaption><\/figure>\n<p><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/09\/30\/ciabatta-ldb\/\">Ciabattine<\/a><\/strong><\/em> &#8211; 3 pezzi (circa 300gr ognuna)<\/p>\n<pre><strong>Preimpasto<\/strong> (poolish)\r\n 124 gr acqua (fredda)\r\n 4gr di lievito di birra fresco\r\n 99gr di semola\r\n 99gr di farina di frumento 550\r\n\r\n<strong>Impasto principale<\/strong>\r\n 199gr di acqua A (35gradi)\r\n 11gr di sale\r\n 15gr di olio di oliva\r\n 298g di farina 550\r\n Preimpasto\r\n 50gr di acqua B (25gradi)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Preimpasto<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola inserite l&#8217;acqua pesata, poi il lievito.<br \/>\nAggiungete la semola, la farina e iniziate a mischiare.<br \/>\nCoprite con coperchio e lasciate maturare per 12 ore ad una temperatura di circa 5 gradi (in frigorifero)<\/p>\n<p style=\"text-align: justify;\"><strong>Impasto principale<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella ciotola della planetaria inserite l&#8217;acqua A, poi il sale.<br \/>\nAggiungete l&#8217;olio, la farina, il prempasto.<\/p>\n<p style=\"text-align: justify;\">Iniziate a mescolare per 3-5 minuti alla velocita&#8217; 1.<br \/>\nAumentate la velocita&#8217; a 2, procedento per 15-18 minuti, fino a che non si sara&#8217; creata una massa appiccicosa.<br \/>\nDiminuite nuovamente la velocita&#8217; ad 1, inserendo la seconda quantita&#8217; di acqua (B), fino a che l&#8217;impasto non avra&#8217; assorbito per bene.<br \/>\nA questo punto aumentate alla velocita&#8217; 3, per 3-5 minuti.<br \/>\nL&#8217;impasto risulta elastico ed appiccicoso (temperatura dell&#8217;impasto circa 26gradi).<br \/>\nInserite in una ciotola e coprite con coperchio o pellicola.<\/p>\n<p style=\"text-align: justify;\">Lasciate a temperatura ambiente (20-22gradi) per 2,5 ore ma&#8230; ogni 30 minuti effettuate un giro di pieghe in ciotola (S&amp;F), per un totale di 3 giri.<\/p>\n<p style=\"text-align: justify;\">Disponete delicatamente l&#8217;impasto su il piano di lavoro ben infarinato.<br \/>\nPesate 3 pezzi, di circa 300gr cadauno.<\/p>\n<p style=\"text-align: justify;\">Posizionate i bordi piu&#8217; lunghi dei pezzi di pasta uno sopra l&#8217;altro per stendere la pasta.<br \/>\nDisporre i pezzo di pasta con la chiusura verso il basso, su un panno di lino foderato.<br \/>\nPremete i pezzi di pasta con la punta delle dita finoa quando non saranno appena sopra il fondo.<\/p>\n<p style=\"text-align: justify;\">Copriteli con un telo o un foglio di alluminio e lasciateli maturare per 30 minuti a temperatura ambienta (20-22gradi).<\/p>\n<p style=\"text-align: justify;\">Preriscaldate il forno e la pietra refrattaria a 250gradi per circa 1 ora.<\/p>\n<p style=\"text-align: justify;\">Premete di nuovo l&#8217;impasto con la punta delle dita, ma non cosi&#8217; profondamente come la prima volta.<\/p>\n<p style=\"text-align: justify;\">Lasciate riposare per altri 30 minuti.<br \/>\nSrotolate con cura l&#8217;impasto dal telo di lino e mettetelo salla mano, adagiandolo poi sulla carta forno.<\/p>\n<p style=\"text-align: justify;\">Passate le dita di pasta e la carta sulla pietra refrattaria calda (aiutandovi con una pala), cuocete a vapore.<br \/>\nDopo 8-10 minuti fate uscire il vapore aprendo lo sportello del forno.<\/p>\n<p style=\"text-align: justify;\">Cuocete in forno in tutto 18-20 minuti.<\/p>\n<p style=\"text-align: justify;\">Lasciate raffreddare su una griglia.<\/p>\n<figure id=\"attachment_47399\" aria-describedby=\"caption-attachment-47399\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47399\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133550-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133550-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133550-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133550-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/02\/ok_IMG_20250217_133550-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47399\" class=\"wp-caption-text\">Ciabattine<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proviamo a preparare altro pane ciabatta, con una ricetta presa da un libro diverso, proprio quello che mi aveva regalato Francesca alcuni anni fa.<\/p>\n","protected":false},"author":2,"featured_media":47398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[116],"class_list":["post-47397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=47397"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47397\/revisions"}],"predecessor-version":[{"id":47408,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47397\/revisions\/47408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/47398"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=47397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=47397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=47397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}