{"id":47273,"date":"2025-02-01T19:30:05","date_gmt":"2025-02-01T18:30:05","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=47273"},"modified":"2025-01-28T18:40:02","modified_gmt":"2025-01-28T17:40:02","slug":"new-york-bagels-vers-1-0-ldb-secco","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2025\/02\/01\/new-york-bagels-vers-1-0-ldb-secco\/","title":{"rendered":"New York Bagels &#8211; vers 1.0 &#8211; LDB secco"},"content":{"rendered":"<p style=\"text-align: justify;\">Tobias ha pensato di preparare, per domenica, un brunch.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Peccato abbia solamente delle grandi idee poi, al momento dei fatti, ha sempre da fare.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho proseguito io.<\/p>\n<p style=\"text-align: justify;\">Non volendo acquistare dei <strong>bagels<\/strong> (decisamente piu&#8217; comodi), ho deciso di farli.<br \/>\nPraticamente dovrei tener fede, o almeno tentare di farlo, ai buoni propositi di inizio anno.<\/p>\n<p style=\"text-align: justify;\">La ricetta in questione e&#8217; stata presa dal libro &#8220;<em>Homemade bagels<\/em>&#8221; &#8211; Edizione Fackeltraeger<\/p>\n<p><strong>Ingredienti &#8211; New York Bagels &#8211; vers 1.0 &#8211; 8 bagels o 20 fingerfood<\/strong><\/p>\n<pre>500gr farina 0 (550 - extrastark)\r\n 1 pacchetto di lievito di birra secco\r\n 280-300 ml di acqua\r\n 1 cucchiai di zucchero\r\n 1 cucchiaio di malto d'orzo\r\n 1 cucchiaio di sale\r\n 2 cucchiai di olio vegetale\r\n\r\n1 cucchiai di zucchero\r\n 1 uovo (misura M)\r\n farina\r\n  semini vari per decorare (sesamo, papavero, etc..)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella planetaria inserite la farina, il lievito,lo zucchero, il malto d&#8217;orzo e 280-300ml di acqua.<br \/>\nIniziate a mescolare.<br \/>\nInserite in seguito il sale e l&#8217;olio, portando a incordatura.<\/p>\n<p style=\"text-align: justify;\">In una ciotola leggermente oleata, inserite l&#8217;impasto e coprite.<br \/>\nIniziate con la lievitazione a t.a. per un&#8217;ora, poi trasferite il tutto in frigorifero per una notte.<\/p>\n<p style=\"text-align: justify;\">Il giorno seguente rimuovete dal frigo, impastate ancora e porzionate in 8 palline.<\/p>\n<figure id=\"attachment_47292\" aria-describedby=\"caption-attachment-47292\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47292\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0002-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0002-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0002-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0002-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47292\" class=\"wp-caption-text\">New York Bagels &#8211; vers 1.0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Procedete con la formazione del bagels (o facendo un buco nella pallina rotonda, oppure creando il bordo ed attaccandolo).<\/p>\n<figure id=\"attachment_47291\" aria-describedby=\"caption-attachment-47291\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47291\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_090827-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_090827-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_090827-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_090827-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_090827-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47291\" class=\"wp-caption-text\">New York Bagels &#8211; vers 1.0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Accendete il forno, statico, a 230gradi (*)<br \/>\nIn una grande pentola, inserite circa 4 litri di acqua, il cucchiaio di zucchero e portate a bollore.<\/p>\n<figure id=\"attachment_47288\" aria-describedby=\"caption-attachment-47288\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47288\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0008-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0008-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0008-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0008-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47288\" class=\"wp-caption-text\">New York Bagels &#8211; vers 1.0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Aiutandovi con una schiumarola, inserite 2 bagels alla volta e lasciate precuocere per circa 40 secondi (*).<\/p>\n<figure id=\"attachment_47289\" aria-describedby=\"caption-attachment-47289\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47289\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0010-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0010-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0010-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0010-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47289\" class=\"wp-caption-text\">New York Bagels &#8211; vers 1.0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Girate il bagel e cuocete, nello stesso modo, per altri 40 secondi.<\/p>\n<p style=\"text-align: justify;\">Rimuovete e procedete alla pre-cottura di tutti i bagels.<\/p>\n<p style=\"text-align: justify;\">Coprite una teglia da forno con della carta-forno e posizionate i bagels precotti.<br \/>\nMischiate l&#8217;uovo (*) in una ciotolina e, con un pennello da cucina, pennellate i bagels e copriteli a preferenza (sesamo, semi di papavero, etc..).<\/p>\n<figure id=\"attachment_47293\" aria-describedby=\"caption-attachment-47293\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47293\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0004-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0004-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0004-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG-20250126-WA0004-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47293\" class=\"wp-caption-text\">New York Bagels &#8211; vers 1.0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cuocete in forno per circa 35-40 minuti (*) fino a che non saranno dorati e croccanti.<\/p>\n<figure id=\"attachment_47290\" aria-describedby=\"caption-attachment-47290\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47290\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_100021-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_100021-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_100021-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_100021-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2025\/01\/ok_IMG_20250126_100021-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47290\" class=\"wp-caption-text\">New York Bagels &#8211; vers 1.0<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La <strong>precottura<\/strong> in acqua zuccherata e&#8217; durata circa 30 secondi per lato.<\/li>\n<li>non ho utilizzato l&#8217;<strong>uovo<\/strong> ma ho aggiunto direttamente i semi di sesamo<\/li>\n<li style=\"text-align: justify;\">la <strong>cottura<\/strong> vera e propria, in forno, e&#8217; stata:\n<ul>\n<li>entrambe le teglie in forno (ripiano 2 e 4)<\/li>\n<li>260 gradi &#8211; 7 minuti<\/li>\n<li>estrazione delle teglia, rotazione di 180gradi e scambio posizione<\/li>\n<li>230 gradi &#8211; 7 minuti<\/li>\n<li>ho poi verificato e, sotto, non erano cotti, cosi&#8217; li ho ribaltati, proseguendo per altri 5 minuti (troppo!)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tobias ha pensato di preparare, per domenica, un brunch.<\/p>\n","protected":false},"author":2,"featured_media":47290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[116,125],"class_list":["post-47273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-ldb","tag-lettura"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=47273"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47273\/revisions"}],"predecessor-version":[{"id":47295,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/47273\/revisions\/47295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/47290"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=47273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=47273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=47273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}