{"id":46713,"date":"2024-11-16T13:55:27","date_gmt":"2024-11-16T12:55:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=46713"},"modified":"2025-10-11T15:59:01","modified_gmt":"2025-10-11T13:59:01","slug":"pizza-in-teglia_ricetta-bonci","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/11\/16\/pizza-in-teglia_ricetta-bonci\/","title":{"rendered":"Pizza in teglia &#8211; ricetta Bonci"},"content":{"rendered":"<p style=\"text-align: justify;\">Dopo decenni, ho provato nuovamente a preparare la pizza Bonci, questa volta in teglia.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">In effetti, molti anni fa, avevo tentato con quella alla pala, la cui <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/11\/14\/pizza\/\">ricetta<\/a><\/strong><\/em> mi era stata passata da Alice.<\/p>\n<p style=\"text-align: justify;\">Ho provato a preparare anche questa, con l&#8217;intenzione &#8211; ed il tentativo &#8211; di poter mangiare tutti e tre insieme.<br \/>\nLimitandondo il dramma di dover pulire tutto quanto, con farina ovunque.<\/p>\n<p style=\"text-align: justify;\">Il risultato mi ha soddisfatta.<br \/>\nLa pizza e&#8217; stata alta, soffice, non proprio croccante sotto (probabilmente dipende dalla fase di stesura), con una lunga maturazione in frigo di 24 ore, e poca gestione.<\/p>\n<p style=\"text-align: justify;\">Bisogna pero&#8217; ricordarsi di non mettere troppo pomodoro: l&#8217;acqua bagna molto l&#8217;impasto ed il risultato non e&#8217; particolarmente cotto.<br \/>\nNel mio terzo, infatti, non avevo messo la passata e non ho avuto problemi.<\/p>\n<figure id=\"attachment_46732\" aria-describedby=\"caption-attachment-46732\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46732\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_124146-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_124146-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_124146-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_124146-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_124146-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46732\" class=\"wp-caption-text\">Pizza in teglia &#8211; ricetta Bonci<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/blog.giallozafferano.it\/dulcisinforno\/pizza-bonci\/\">Pizza in teglia &#8211; ricetta Gabriele Bonci <\/a><\/strong><\/em>&#8211; 1 teglia grande di pizza (40 x 30 cm)<\/p>\n<pre>500 g Farina 0 (io farina per pizza)\r\n400 ml Acqua\r\n20 ml olio extravergine d\u00e2\u20ac\u2122oliva\r\n10 g Sale\r\n3 g Lievito di birra fresco\r\nSemola di grano duro rimacinata (per la spianatoia)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola capiente inserite tutta la farina.<br \/>\nAl centro versate met\u00c3\u00a0 dell\u00e2\u20ac\u2122acqua e sbriciolate il lievito di birra. Amalgamate il tutto utilizzando una forchetta (o un cucchiaio).<\/p>\n<p style=\"text-align: justify;\">Per ultimo, unite anche il sale e mescolate.<br \/>\n<em>Il composto risulter\u00c3\u00a0 molto morbido e appiccicoso, \u00c3\u00a8 normale.<\/em><br \/>\nCoprite la ciotola con un panno e lasciate riposare l\u00e2\u20ac\u2122impasto per 15 minuti.<\/p>\n<p style=\"text-align: justify;\">Infarinate leggermente la spianatoia (meglio con la semola se l\u00e2\u20ac\u2122avete, se no con la farina usata per l\u00e2\u20ac\u2122impasto) e iniziate a fare le pieghe: <em>questo passaggio \u00c3\u00a8 fondamentale perch\u00c3\u00a8 permette all\u00e2\u20ac\u2122impasto di incorporare aria e di formare le famose bolle sulla superficie.<\/em><\/p>\n<figure id=\"attachment_46735\" aria-describedby=\"caption-attachment-46735\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46735\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_093722-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_093722-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_093722-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_093722-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_093722-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46735\" class=\"wp-caption-text\">Pizza in teglia &#8211; ricetta Bonci<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Rovesciate l\u00e2\u20ac\u2122impasto sulla spianatoia, allargatelo leggermente con i polpastrelli delle dita, in modo da formare un piccolo rettangolo. Con un tarocco (o una spatola), piegate il rettangolo in 3 parti (piega a portafoglio) portando prima un lato verso il centro e poi l\u00e2\u20ac\u2122altro.<\/p>\n<p style=\"text-align: justify;\">Infine, piegatelo a met\u00c3\u00a0 e riponete nella ciotola e coprite.<\/p>\n<p style=\"text-align: justify;\">Ripetete le<strong> pieghe altre 2 volte<\/strong>, sempre a distanza di 15\/20 minuti.<\/p>\n<p style=\"text-align: justify;\">Dopo questa operazione, ungete la ciotola con un velo di olio e adagiate all\u00e2\u20ac\u2122interno l\u00e2\u20ac\u2122impasto.<br \/>\nCoprite con della pellicola trasparente e riponete in<strong> frigorifero per 24 ore<\/strong>, nella parte pi\u00c3\u00b9 bassa del frigorifero.<\/p>\n<p style=\"text-align: justify;\">Nel pomeriggio del giorno dopo, riprendete l\u00e2\u20ac\u2122impasto e lasciatelo acclimatare a temperatura ambiente per 1 ora, sempre coperto con la pellicola.<\/p>\n<p style=\"text-align: justify;\">Spolverate la spianatoia con della semola rimacinata, oppure con la farina che avete usato nell\u00e2\u20ac\u2122impasto e rovesciate sopra la pasta per la pizza.<br \/>\nCon le mani leggermente umide, accarezzando l\u00e2\u20ac\u2122impasto con i polpastrelli, formate un rettangolo.<br \/>\n<em>Come suggerisce Gabriele Bonci, la pizza metodo Bonci v\u00c3\u00a0 stesa prima sulla farina e poi in teglia.<\/em><\/p>\n<p style=\"text-align: justify;\">Ungete la teglia con dell\u00e2\u20ac\u2122olio e trasferite il vostro rettangolo di pasta su di essa. Sempre con le mani umide e delicatamente, allargate l\u00e2\u20ac\u2122impasto in modo da coprire di pizza tutta la teglia.<br \/>\n<em>Potete lasciare i bordi bassi, tanto si alzeranno di loro.<\/em><\/p>\n<figure id=\"attachment_46736\" aria-describedby=\"caption-attachment-46736\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46736\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_094354-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_094354-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_094354-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_094354-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_094354-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46736\" class=\"wp-caption-text\">Pizza in teglia &#8211; ricetta Bonci<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ora coprite la teglia con un canovaccio pulito e lasciate lievitare per 2\/3 ore, direttamente in teglia.<\/p>\n<p style=\"text-align: justify;\">Condite la pizza Bonci come preferite.<br \/>\nInfornate nel forno statico a 250\u00c2\u00b0C per 10 minuti nel ripiano basso del forno. Poi abbassate la temperatura a 230\u00c2\u00b0C, spostate la teglia nel ripiano centrale e proseguite la cottura per altri 10 minuti (*).<\/p>\n<figure id=\"attachment_46730\" aria-describedby=\"caption-attachment-46730\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46730\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_121621-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_121621-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_121621-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_121621-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20241103_121621-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46730\" class=\"wp-caption-text\">Pizza in teglia &#8211; ricetta Bonci<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">E&#8217; consigliabile <strong>iniziare<\/strong> nel primo pomeriggio del giorno prima, in modo da completare la lievitazione della pizza per 24 ore (in frigorifero).<\/li>\n<li style=\"text-align: justify;\">La <strong>farina<\/strong> consigliata \u00c3\u00a8 la farina 0, possibilmente W270 \u00e2\u20ac\u201c W330, ma e&#8217; possibile utilizzare anche la classica farina per pizza oppure met\u00c3\u00a0 farina manitoba e met\u00c3\u00a0 farina 00, in base a quello che avete a casa.<\/li>\n<li style=\"text-align: justify;\">Se non avete il lievito di birra fresco, potete preparare l\u00e2\u20ac\u2122impasto anche con il <strong>lievito di birra secco<\/strong> (disidratato): ne baster\u00c3\u00a0 solo 1 grammo.<\/li>\n<li style=\"text-align: justify;\">Se avete il <strong>lievito madre,<\/strong> in un\u00e2\u20ac\u2122intervista, Bonci suggerisce di utilizzarne 50 grammi al posto del lievito di birra (quindi 100 g di lievito madre per 1 Kg di farina).<\/li>\n<li style=\"text-align: justify;\">L\u00e2\u20ac\u2122acqua v\u00c3\u00a0 bene fredda o a temperatura ambiente, non deve essere tiepida.<\/li>\n<li style=\"text-align: justify;\">Per la <strong>cottura<\/strong>, noi abbiamo preferito passare sotto il grill.<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>1 Marzo 2025<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Non potevamo aspettare oltre nel mangiare la pizza, quindi abbiamo ripetuto.<br \/>\nNell&#8217;insieme e&#8217; buono l&#8217;impasto, peccato non si cuocia perfettamente l&#8217;interno.<br \/>\nLa prossima volta proveremo a dividere l&#8217;impasto in due teglia, cosi&#8217; da risultare piu&#8217; bassa e favorendo la cottura.<\/p>\n<figure id=\"attachment_47567\" aria-describedby=\"caption-attachment-47567\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47567\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0010-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0010-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0010-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0010-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0010-768x576.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47567\" class=\"wp-caption-text\">Pizza bonci<\/figcaption><\/figure>\n<figure id=\"attachment_47568\" aria-describedby=\"caption-attachment-47568\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-47568\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0011-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0011-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0011-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0011-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG-20250301-WA0011-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-47568\" class=\"wp-caption-text\">Pizza bonci<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Aggiornamento 11 ottobre 2025<\/strong><\/span><\/p>\n<p>Questa pizza e&#8217; stata riproposta in tavola.<\/p>\n<pre>Le modifiche adottate sono state:\r\n 35gr licoli\r\n 2gr ldb fresco\r\n 500gr farina per pizza.<\/pre>\n<p>Ed ecco il risultato ottenuto.<br \/>\nHo prelevato circa 310gr di impasto e messo in una teglia rotonda, traforata.<br \/>\nIl restante nella teglia grande.<br \/>\nIl risultato e&#8217; stata una pizza soffice, cotta e non particolarmente alta.<\/p>\n<figure id=\"attachment_49290\" aria-describedby=\"caption-attachment-49290\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49290\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_124918-e1760191051160-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_124918-e1760191051160-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_124918-e1760191051160-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_124918-e1760191051160-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_124918-e1760191051160-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-49290\" class=\"wp-caption-text\">Pizza ricetta Bonci<\/figcaption><\/figure>\n<figure id=\"attachment_49289\" aria-describedby=\"caption-attachment-49289\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49289\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130755-e1760191043726-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130755-e1760191043726-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130755-e1760191043726-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130755-e1760191043726-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130755-e1760191043726-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-49289\" class=\"wp-caption-text\">Pizza ricetta Bonci<\/figcaption><\/figure>\n<figure id=\"attachment_49288\" aria-describedby=\"caption-attachment-49288\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49288\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130751-e1760191034829-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130751-e1760191034829-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130751-e1760191034829-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130751-e1760191034829-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/11\/ok_IMG_20251011_130751-e1760191034829-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-49288\" class=\"wp-caption-text\">Pizza ricetta Bonci<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo decenni, ho provato nuovamente a preparare la pizza Bonci, questa volta in teglia.<\/p>\n","protected":false},"author":2,"featured_media":46731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,104],"tags":[116],"class_list":["post-46713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pizza","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=46713"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46713\/revisions"}],"predecessor-version":[{"id":49291,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46713\/revisions\/49291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/46731"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=46713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=46713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=46713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}