{"id":466,"date":"2017-11-08T18:39:19","date_gmt":"2017-11-08T17:39:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/joghurt-del-mese-mueller-rudies-lebkuchenmann\/"},"modified":"2021-03-02T16:46:40","modified_gmt":"2021-03-02T15:46:40","slug":"yoghurt-lebkuchenmann","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/11\/08\/yoghurt-lebkuchenmann\/","title":{"rendered":"Yoghurt del mese &#8211; Mueller Rudies Lebkuchenmann"},"content":{"rendered":"<p style=\"text-align: justify;\">Lo so, lo yoghurt della Mueller proprio non mi piace, generalmente parlando.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Poi ho visto questo da lontano, mi sono avvicinata, ho visto la Renna Rudy, gli ominiiniini di lebkuchen e non ho resistito alla tentazione.<\/p>\n<p style=\"text-align: justify;\">Nell&#8217;angolo apposito ci sono dei deliziosi pupazzetti speziati, e delle palline di cioccolato.<br \/>\nCapovolgendo il contenuto dell&#8217;angolo nello yoghurt, si ha subito la sensazione di essere gia&#8217; a Natale!<\/p>\n<figure id=\"attachment_13891\" aria-describedby=\"caption-attachment-13891\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13891\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mueller.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mueller.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mueller-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mueller-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-13891\" class=\"wp-caption-text\">yoghurt &#8211; Mueller Rudies Lebkuchenmann<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In effetti non manca molto, ma gia&#8217; c&#8217;e&#8217; si sente quel &#8220;qualche cosa&#8221; di strano nell&#8217;aria.<br \/>\nLa voglia di tornare a casa, quando fuori inizia gia&#8217; ad essere buio, la voglia di stare a casuccia con una fetta di torta alla cannella, aroma di chiodi di garofano e spezie sono sparsi nell&#8217;aria di casa dai diffusori di essenze, le scorze di arancio sono sui caloriferi (per chi li ha).<\/p>\n<p style=\"text-align: justify;\">E fuori?<br \/>\nle prime luci comunali, i primi festaioli che addobbano gli esterni delle loro case con luci (qui non colorate), candele alle finestre.<\/p>\n<p style=\"text-align: justify;\">Insomma, la giusta e perfetta atmosfera natalizia.<\/p>\n<p style=\"text-align: justify;\">PS: Nonostante si legga la scadenza in ottobre, lo yoghurt e&#8217; stato mangiato a settembre!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo so, lo yoghurt della Mueller proprio non mi piace, generalmente parlando.<\/p>\n","protected":false},"author":2,"featured_media":13891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[183],"class_list":["post-466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al_cucchiaio","category-dessert","category-food","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=466"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/466\/revisions"}],"predecessor-version":[{"id":29009,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/466\/revisions\/29009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13891"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}