{"id":46364,"date":"2024-10-11T15:15:32","date_gmt":"2024-10-11T13:15:32","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=46364"},"modified":"2024-10-08T14:00:52","modified_gmt":"2024-10-08T12:00:52","slug":"piadina-sfogliata","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/10\/11\/piadina-sfogliata\/","title":{"rendered":"Piadina sfogliata"},"content":{"rendered":"<p style=\"text-align: justify;\">Troppe ricette, troppe alternative.<\/p>\n<p style=\"text-align: justify;\">Indecisione assoluta.<br \/>\nTempo &#8220;perso&#8221; nella vana ricerca di trovare qualcosa<!--more--><\/p>\n<p style=\"text-align: justify;\">Soluzione?<br \/>\nPiadine sfogliate con quel (poco) di Vera a disposizione)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46382\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240926_192537-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240926_192537-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240926_192537-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240926_192537-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240926_192537-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Ingredienti &#8211; Piadina sfogliata<\/strong><\/p>\n<pre>130gr licoli\r\n350gr farina 0 (*)\r\n30gr olio\r\n200gr acqua\r\n6gr sale\r\n\r\n20gr burro\/strutto (*)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Impastate il licoli con la farina e l&#8217;acqua.<br \/>\nAggiungete il sale e l&#8217;olio e lavorate fino ad ottenere un impasto liscio e non appiccicoso.<\/p>\n<p style=\"text-align: justify;\">Su un piano da lavoro pezzate l&#8217;impasto, formando delle palline del peso di circa 60gr cadauno, che lascerete riposare per mezz&#8217;oretta a campana.<\/p>\n<p style=\"text-align: justify;\">Sciogliete il burro\/strutto nel microonde.<br \/>\nSpennellate con il burro fuso, arrotolate formando un cilindro, avvolgendo e formando una chiocciola e lasciando riposare l&#8217;impasto per 10 minuti.<\/p>\n<p style=\"text-align: justify;\">Stendete la chioccola dello spessore di qualche millimetro e cuocete in padella calda, qualche minuto per lato.<\/p>\n<p>Se non le mangiate subito, mettetele all&#8217;interno di un canovaccio da cucina immediatamente, cosi&#8217; che il vapore rimanga all&#8217;interno e mantenga morbido il prodotto<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La <strong>farina<\/strong> da me utilizzata e&#8217; stata 150gr di Vollkorn (integrale bianca) e 200gr di farina 405<\/li>\n<li style=\"text-align: justify;\">Anche meno di <strong>burro\/strutto<\/strong>!<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La foto e&#8217; orribile, non che le altre siano meglio&#8230; proprio mi sono scordata di scattarne qualcuna.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Troppe ricette, troppe alternative. Indecisione assoluta. Tempo &#8220;perso&#8221; nella vana ricerca di trovare qualcosa<\/p>\n","protected":false},"author":2,"featured_media":46382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[112],"class_list":["post-46364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=46364"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46364\/revisions"}],"predecessor-version":[{"id":46385,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46364\/revisions\/46385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/46382"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=46364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=46364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=46364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}